{"id":122528,"date":"2021-06-22T11:32:11","date_gmt":"2021-06-22T09:32:11","guid":{"rendered":"https:\/\/www.foment.com\/?post_type=ajde_events&amp;p=122528"},"modified":"2021-06-22T11:32:11","modified_gmt":"2021-06-22T09:32:11","slug":"herramientas-de-prevencion-de-las-enfermedades-vasculares-en-el-entorno-laboral","status":"publish","type":"ajde_events","link":"https:\/\/www.foment.com\/es\/events\/herramientas-de-prevencion-de-las-enfermedades-vasculares-en-el-entorno-laboral\/","title":{"rendered":"Herramientas de prevenci\u00f3n de las enfermedades vasculares en el entorno laboral"},"content":{"rendered":"<h2 style=\"text-align: center;\"><span style=\"color: #ab192d;\"><strong>Herramientas de prevenci\u00f3n de las enfermedades vasculares en el entorno laboral<\/strong><\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"color: #656565;\"><strong>Webinar de PRL<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ab192d;\"><strong>Objetivo<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">El concepto de empresa saludable trasciende el campo de la prevenci\u00f3n de riesgos laborales y nos acerca a conceptos de eficiencia, de modernidad y de mangement global. Detectar riesgos, prevenir y dar herramientas a los trabajadores y directivos nos acerca al concepto de \u00e9xito.<\/p>\n<p style=\"text-align: justify;\">Las enfermedades vasculares son enfermedades complejas, pero muy corrientes (no solo en el \u00e1mbito laboral), su falta de prevenci\u00f3n acostumbra a desencadenar cuadros cl\u00ednicos severos como el infarto de miocardio, accidente cerebro-vascular (ictus) o tromboembolismo venoso (que desgraciadamente constituyen la primera causa de muerte en el mundo). De estas tres entidades cl\u00ednicas, el tromboembolismo venoso es el m\u00e1s desconocido, pese a que cada minuto muere una persona en Europa como consecuencia de esta patolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">En este webinar se abordar\u00e1n por un lado las herramientas de valoraci\u00f3n y t\u00e9cnicas de prevenci\u00f3n y por otro lado las necesidades de investigaci\u00f3n cient\u00edfica para generar un entorno saludable. Ello, a cargo de los doctores Soria, Escudero y Padr\u00f3s del Hospital i Institut de Recerca de la Santa Creu i Sant Pau de Barcelona.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ab192d;\"><strong>Programa<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"10%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>09.30 h<\/strong><\/p>\n<\/td>\n<td width=\"90%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>Presentaci\u00f3n.<\/strong><\/p>\n<ul>\n<li>Sr. C\u00e9sar S\u00e1nchez. Director Oficina Prevenci\u00f3n Riesgos Laborales. Fomento del Trabajo.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"10%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>09.40 h<\/strong><\/p>\n<\/td>\n<td width=\"90%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>Activa\u2019tt Por la Salud Vascular.<\/strong><\/p>\n<ul>\n<li>Dr. Jos\u00e9 Manuel Soria. President. Activa\u2019tt. Director de la Unidad Gen\u00f3mica de Enfermedades Complejas. Institut de Recerca de Sant Pau.<\/li>\n<li>Sr. C\u00e9sar S\u00e1nchez. Director Oficina Prevenci\u00f3n Riesgos Laborales. Fomento del Trabajo.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"10%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>09.55 h<\/strong><\/p>\n<\/td>\n<td width=\"90%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>Enfermedades vasculares en el entorno laboral.<\/strong><\/p>\n<ul>\n<li>Dr. Rafael Padr\u00f3s. Responsable Riesgos Laborales. Hospital de la Santa Cruz y San Pablo.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"10%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>10.10 h<\/strong><\/p>\n<\/td>\n<td width=\"90%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>Herramientas de prevenci\u00f3n y motivaci\u00f3n de las enfermedades vasculares.<\/strong><\/p>\n<ul>\n<li>Dr. Jos\u00e9 Rom\u00e1n Escudero. Vicepresidente. Activa\u2019tt. Director del Servicio Mancomunado de cirug\u00eda vascular y angiolog\u00eda de los Hospitales de San Pablo y Dos de Mayo.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"10%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>10.25 h<\/strong><\/p>\n<\/td>\n<td width=\"90%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>Experiencias pr\u00e1cticas.<\/strong><\/p>\n<ul>\n<li>Dr. Antoni Nicolau. Jefe del Servicio de Salud Laboral. Corporaci\u00f3n Catalana de Medios Audiovisuales<\/li>\n<li>Sr. Francesc Bl\u00e1zquez. Responsable de Prevenci\u00f3n de Riesgos Laborales. CERTIS.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"10%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>10:45 h<\/strong><\/p>\n<\/td>\n<td width=\"90%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>Preguntas de los asistentes.<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"10%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>11.00 h<\/strong><\/p>\n<\/td>\n<td width=\"90%\">\n<p style=\"margin: 5px 0px;\" align=\"left\"><strong>Clausura.<\/strong><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"author":1,"featured_media":122531,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_links_to":"","_links_to_target":""},"tags":[4823,416,417,513],"event_type":[202],"event_type_2":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/ajde_events\/122528"}],"collection":[{"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/ajde_events"}],"about":[{"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/types\/ajde_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/comments?post=122528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/media\/122531"}],"wp:attachment":[{"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/media?parent=122528"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/tags?post=122528"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/event_type?post=122528"},{"taxonomy":"event_type_2","embeddable":true,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/event_type_2?post=122528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}