{"id":16235,"date":"2016-07-29T14:28:36","date_gmt":"2016-07-29T12:28:36","guid":{"rendered":"http:\/\/foment.itartech.com\/?page_id=16235"},"modified":"2026-07-07T13:10:09","modified_gmt":"2026-07-07T11:10:09","slug":"emprendedores-y-empresa","status":"publish","type":"page","link":"https:\/\/www.foment.com\/es\/emprendedores-y-empresa\/","title":{"rendered":"Emprendedores"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=\u00bb1\/1&#8243;]\t\t\t<script type=\"text\/javascript\" src=\"\/\/www.foment.com\/wp-content\/plugins\/revslider\/public\/assets\/js\/rbtools.min.js?rev=6.4.6\"><\/script>\n\t\t\t<script type=\"text\/javascript\" src=\"\/\/www.foment.com\/wp-content\/plugins\/revslider\/public\/assets\/js\/rs6.min.js?rev=6.4.6\"><\/script>\n\n\t\t\t<!-- START post emprendedores REVOLUTION SLIDER 6.4.6 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_129_1_wrapper\" data-source=\"post\" style=\"background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_129_1\" style=\"\" data-version=\"6.4.6\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide data-key=\"rs-221980\" data-title=\"Del balance a la estrategia: Foment y ACCID refuerzan la conexi\u00f3n entre contabilidad y direcci\u00f3n de empresas\" data-thumb=\"\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/DSC_0179-scaled-200x150.jpg\" data-link=\"\/\/www.foment.com\/es\/del-balance-a-la-estrategia-foment-y-accid-refuerzan-la-conexion-entre-contabilidad-y-direccion-de-empresas\/\" data-target=\"_self\" data-seoz=\"front\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.foment.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"DSC_0179\" width=\"2560\" height=\"1707\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/DSC_0179-scaled.jpg\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-129-slide-221980-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:b;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;fw:100;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:100%;h:100%;\"\n\t\t\t\t\t\t\t\tdata-basealign=\"slide\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"e:power2.inOut;st:500;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgba(30,30,30,0.5);\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-129-slide-221980-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"Newspaper-Title\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:m;yo:0,-120px,-60px,-70px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:28,28,28,22;l:35,35,32,32;fw:700;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:882px,882px,673px,407px;h:90px,90px,95px,95px;\"\n\t\t\t\t\t\t\t\tdata-padding=\"b:10,10,11,11;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0px,0px;y:0,0,0px,0px;e:power2.inOut;st:500;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:Montserrat;text-transform:uppercase;\"\n\t\t\t\t\t\t\t>Del balance a la estrategia: Foment y ACCID refuerzan la conexi\u00f3n entre contabilidad y direcci\u00f3n de empresas \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide data-key=\"rs-216817\" data-title=\"El talento femenino se organiza desde el territorio: Foment pone en marcha el Consell Territorial de Dones d\u2019Empresa de Catalunya\" data-thumb=\"\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/JVF6296-scaled-200x150.jpg\" data-link=\"\/\/www.foment.com\/es\/el-talento-femenino-se-organiza-desde-el-territorio-foment-pone-en-marcha-el-consell-territorial-de-dones-dempresa-de-catalunya\/\" data-target=\"_self\" data-seoz=\"front\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.foment.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"_JVF6296\" width=\"2560\" height=\"1707\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/JVF6296-scaled.jpg\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-129-slide-216817-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:b;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;fw:100;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:100%;h:100%;\"\n\t\t\t\t\t\t\t\tdata-basealign=\"slide\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"e:power2.inOut;st:500;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgba(30,30,30,0.5);\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-129-slide-216817-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"Newspaper-Title\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:m;yo:0,-120px,-60px,-70px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:28,28,28,22;l:35,35,32,32;fw:700;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:882px,882px,673px,407px;h:90px,90px,95px,95px;\"\n\t\t\t\t\t\t\t\tdata-padding=\"b:10,10,11,11;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0px,0px;y:0,0,0px,0px;e:power2.inOut;st:500;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:Montserrat;text-transform:uppercase;\"\n\t\t\t\t\t\t\t>El talento femenino se organiza desde el territorio: Foment pone en marcha el Consell Territorial de Dones d\u2019Empresa de Catalunya \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide data-key=\"rs-215463\" data-title=\"Foment del Treball impulsa el debate sobre soberan\u00eda tecnol\u00f3gica europea en el MWC\" data-thumb=\"\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/JVF4553-scaled-200x150.jpg\" data-link=\"\/\/www.foment.com\/es\/foment-del-treball-impulsa-el-debate-sobre-soberania-tecnologica-europea-en-el-mwc\/\" data-target=\"_self\" data-seoz=\"front\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.foment.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"_JVF4553\" width=\"2560\" height=\"1707\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/JVF4553-scaled.jpg\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-129-slide-215463-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:b;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;fw:100;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:100%;h:100%;\"\n\t\t\t\t\t\t\t\tdata-basealign=\"slide\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"e:power2.inOut;st:500;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgba(30,30,30,0.5);\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-129-slide-215463-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"Newspaper-Title\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:m;yo:0,-120px,-60px,-70px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:28,28,28,22;l:35,35,32,32;fw:700;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:882px,882px,673px,407px;h:90px,90px,95px,95px;\"\n\t\t\t\t\t\t\t\tdata-padding=\"b:10,10,11,11;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0px,0px;y:0,0,0px,0px;e:power2.inOut;st:500;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:Montserrat;text-transform:uppercase;\"\n\t\t\t\t\t\t\t>Foment del Treball impulsa el debate sobre soberan\u00eda tecnol\u00f3gica europea en el MWC \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide data-key=\"rs-201572\" data-title=\"Transformaci\u00f3n digital con impacto real: m\u00e1s de 1.200 pymes acompa\u00f1adas por Foment a trav\u00e9s de Accelera Pyme\" data-thumb=\"\/\/www.foment.com\/wp-content\/uploads\/2025\/05\/JJVF9130-1-scaled-200x150.jpg\" data-link=\"\/\/www.foment.com\/es\/transformacion-digital-con-impacto-real-mas-de-1200-pymes-acompanadas-por-foment-a-traves-acelera-pyme\/\" data-target=\"_self\" data-seoz=\"front\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.foment.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Acelera Pyme\" title=\"JJVF9130 (1)\" width=\"2560\" height=\"1707\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.foment.com\/wp-content\/uploads\/2025\/05\/JJVF9130-1-scaled.jpg\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-129-slide-201572-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:b;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;fw:100;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:100%;h:100%;\"\n\t\t\t\t\t\t\t\tdata-basealign=\"slide\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"e:power2.inOut;st:500;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgba(30,30,30,0.5);\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-129-slide-201572-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"Newspaper-Title\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:m;yo:0,-120px,-60px,-70px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:28,28,28,22;l:35,35,32,32;fw:700;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:882px,882px,673px,407px;h:90px,90px,95px,95px;\"\n\t\t\t\t\t\t\t\tdata-padding=\"b:10,10,11,11;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0px,0px;y:0,0,0px,0px;e:power2.inOut;st:500;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:Montserrat;text-transform:uppercase;\"\n\t\t\t\t\t\t\t>Transformaci\u00f3n digital con impacto real: m\u00e1s de 1.200 pymes acompa\u00f1adas por Foment a trav\u00e9s de Accelera Pyme \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_129_1',rl:[1240,1024,778,480],el:[500,500,360,360],gw:[1600,1024,778,480],gh:[500,500,360,360],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});\n\t\t\t\t\tvar\trevapi129,\n\t\t\t\t\t\ttpj;\n\t\t\t\t\tfunction revinit_revslider1291() {\n\t\t\t\t\tjQuery(function() {\n\t\t\t\t\t\ttpj = jQuery;\n\t\t\t\t\t\trevapi129 = tpj(\"#rev_slider_129_1\");\n\t\t\t\t\t\ttpj.noConflict();\n\t\t\t\t\t\tif(revapi129==undefined || revapi129.revolution == undefined){\n\t\t\t\t\t\t\trevslider_showDoubleJqueryError(\"rev_slider_129_1\");\n\t\t\t\t\t\t}else{\n\t\t\t\t\t\t\trevapi129.revolution({\n\t\t\t\t\t\t\t\tDPR:\"dpr\",\n\t\t\t\t\t\t\t\tsliderLayout:\"fullwidth\",\n\t\t\t\t\t\t\t\tvisibilityLevels:\"1240,1024,778,480\",\n\t\t\t\t\t\t\t\tgridwidth:\"1600,1024,778,480\",\n\t\t\t\t\t\t\t\tgridheight:\"500,500,360,360\",\n\t\t\t\t\t\t\t\tlazyType:\"smart\",\n\t\t\t\t\t\t\t\tperspective:600,\n\t\t\t\t\t\t\t\tperspectiveType:\"local\",\n\t\t\t\t\t\t\t\teditorheight:\"500,500,360,360\",\n\t\t\t\t\t\t\t\tresponsiveLevels:\"1240,1024,778,480\",\n\t\t\t\t\t\t\t\tprogressBar:{disableProgressBar:true},\n\t\t\t\t\t\t\t\tnavigation: {\n\t\t\t\t\t\t\t\t\tmouseScrollNavigation:false,\n\t\t\t\t\t\t\t\t\twheelCallDelay:1000,\n\t\t\t\t\t\t\t\t\tonHoverStop:false,\n\t\t\t\t\t\t\t\t\ttouch: {\n\t\t\t\t\t\t\t\t\t\ttouchenabled:true,\n\t\t\t\t\t\t\t\t\t\tswipe_min_touches:50\n\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\tarrows: {\n\t\t\t\t\t\t\t\t\t\tenable:true,\n\t\t\t\t\t\t\t\t\t\tstyle:\"uranus\",\n\t\t\t\t\t\t\t\t\t\thide_onmobile:true,\n\t\t\t\t\t\t\t\t\t\thide_under:600,\n\t\t\t\t\t\t\t\t\t\tleft: {\n\t\t\t\t\t\t\t\t\t\t\th_offset:30\n\t\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\tright: {\n\t\t\t\t\t\t\t\t\t\t\th_offset:30\n\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\tbullets: {\n\t\t\t\t\t\t\t\t\t\tenable:true,\n\t\t\t\t\t\t\t\t\t\ttmp:\"\",\n\t\t\t\t\t\t\t\t\t\tstyle:\"hesperiden\",\n\t\t\t\t\t\t\t\t\t\tv_offset:25,\n\t\t\t\t\t\t\t\t\t\tspace:11\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\tparallax: {\n\t\t\t\t\t\t\t\t\tlevels:[2,3,4,5,6,7,12,16,10,50,47,48,49,50,51,55],\n\t\t\t\t\t\t\t\t\ttype:\"mouse\",\n\t\t\t\t\t\t\t\t\torigo:\"slidercenter\",\n\t\t\t\t\t\t\t\t\tspeed:2000\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\tfallbacks: {\n\t\t\t\t\t\t\t\t\tallowHTML5AutoPlayOnAndroid:true\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t}\n\t\t\t\t\t\t\n\t\t\t\t\t});\n\t\t\t\t\t} \/\/ End of RevInitScript\n\t\t\t\tvar once_revslider1291 = false;\n\t\t\t\tif (document.readyState === \"loading\") {document.addEventListener('readystatechange',function() { if((document.readyState === \"interactive\" || document.readyState === \"complete\") && !once_revslider1291 ) { once_revslider1291 = true; revinit_revslider1291();}});} else {once_revslider1291 = true; revinit_revslider1291();}\n\t\t\t\t<\/script>\n\t\t\t\t<script>\n\t\t\t\t\tvar htmlDivCss = unescape(\"%23rev_slider_129_1_wrapper%20.uranus.tparrows%20%7B%0A%20%20width%3A50px%3B%0A%20%20height%3A50px%3B%0A%20%20background%3Argba%28255%2C255%2C255%2C0%29%3B%0A%20%7D%0A%20%23rev_slider_129_1_wrapper%20.uranus.tparrows%3Abefore%20%7B%0A%20width%3A50px%3B%0A%20height%3A50px%3B%0A%20line-height%3A50px%3B%0A%20font-size%3A40px%3B%0A%20transition%3Aall%200.3s%3B%0A-webkit-transition%3Aall%200.3s%3B%0A%20%7D%0A%20%0A%20%20%23rev_slider_129_1_wrapper%20.uranus.tparrows%3Ahover%3Abefore%20%7B%0A%20%20%20%20opacity%3A0.75%3B%0A%20%20%7D%0A%23rev_slider_129_1_wrapper%20.hesperiden.tp-bullets%20%7B%0A%7D%0A%23rev_slider_129_1_wrapper%20.hesperiden.tp-bullets%3Abefore%20%7B%0A%09content%3A%27%20%27%3B%0A%09position%3Aabsolute%3B%0A%09width%3A100%25%3B%0A%09height%3A100%25%3B%0A%09background%3Atransparent%3B%0A%09padding%3A10px%3B%0A%09margin-left%3A-10px%3Bmargin-top%3A-10px%3B%0A%09box-sizing%3Acontent-box%3B%0A%20%20%20border-radius%3A8px%3B%0A%20%20%0A%7D%0A%23rev_slider_129_1_wrapper%20.hesperiden%20.tp-bullet%20%7B%0A%09width%3A12px%3B%0A%09height%3A12px%3B%0A%09position%3Aabsolute%3B%0A%09background%3A%20%23ffffff%3B%20%2F%2A%20old%20browsers%20%2A%2F%0A%20%20%20%20background%3A%20-moz-linear-gradient%28top%2C%20%20%23ffffff%200%25%2C%20%23ffffff%20100%25%29%3B%20%2F%2A%20ff3.6%2B%20%2A%2F%0A%20%20%20%20background%3A%20-webkit-linear-gradient%28top%2C%20%20%23ffffff%200%25%2C%23ffffff%20100%25%29%3B%20%2F%2A%20chrome10%2B%2Csafari5.1%2B%20%2A%2F%0A%20%20%20%20background%3A%20-o-linear-gradient%28top%2C%20%20%23ffffff%200%25%2C%23ffffff%20100%25%29%3B%20%2F%2A%20opera%2011.10%2B%20%2A%2F%0A%20%20%20%20background%3A%20-ms-linear-gradient%28top%2C%20%20%23ffffff%200%25%2C%23ffffff%20100%25%29%3B%20%2F%2A%20ie10%2B%20%2A%2F%0A%20%20%20%20background%3A%20linear-gradient%28to%20bottom%2C%20%20%23ffffff%200%25%2C%23ffffff%20100%25%29%3B%20%2F%2A%20w3c%20%2A%2F%0A%20%20%20%20filter%3A%20progid%3Adximagetransform.microsoft.gradient%28%20%0A%20%20%20%20startcolorstr%3D%27%23ffffff%27%2C%20endcolorstr%3D%27%23ffffff%27%2Cgradienttype%3D0%20%29%3B%20%2F%2A%20ie6-9%20%2A%2F%0A%09border%3A0px%20solid%20%23ffffff%3B%0A%09border-radius%3A50%25%3B%0A%09cursor%3A%20pointer%3B%0A%09box-sizing%3Acontent-box%3B%0A%7D%0A%23rev_slider_129_1_wrapper%20.hesperiden%20.tp-bullet%3Ahover%2C%0A%23rev_slider_129_1_wrapper%20.hesperiden%20.tp-bullet.selected%20%7B%0A%09background%3A%23d2112d%3B%0A%7D%0A%23rev_slider_129_1_wrapper%20.hesperiden%20.tp-bullet-image%20%7B%0A%7D%0A%23rev_slider_129_1_wrapper%20.hesperiden%20.tp-bullet-title%20%7B%0A%7D%0A%0A\");\n\t\t\t\t\tvar htmlDiv = document.getElementById('rs-plugin-settings-inline-css');\n\t\t\t\t\tif(htmlDiv) {\n\t\t\t\t\t\thtmlDiv.innerHTML = htmlDiv.innerHTML + htmlDivCss;\n\t\t\t\t\t}else{\n\t\t\t\t\t\tvar htmlDiv = document.createElement('div');\n\t\t\t\t\t\thtmlDiv.innerHTML = '<style>' + htmlDivCss + '<\/style>';\n\t\t\t\t\t\tdocument.getElementsByTagName('head')[0].appendChild(htmlDiv.childNodes[0]);\n\t\t\t\t\t}\n\t\t\t\t<\/script>\n\t\t\t\t<script>\n\t\t\t\t\tvar htmlDivCss = unescape(\"%0A%23rev_slider_129_1%5Bdata-slideactive%3D%22rs-180%22%5D%20.hesperiden%20.tp-bullet%7B%0Abackground%3A%20linear-gradient%28to%20bottom%2C%20%20%23999999%200%25%2C%23ffffff%20100%25%29%20%21important%3B%0Afilter%3A%20progid%3Adximagetransform.microsoft.gradient%28%20%0A%20%20%20%20startcolorstr%3D%22%23999999%22%2C%20endcolorstr%3D%22%23ffffff%22%2Cgradienttype%3D0%20%29%20%21important%3B%0Aborder%3A%203px%20solid%20%23ffffff%20%21important%3B%0A%7D%0A%0A\");\n\t\t\t\t\tvar htmlDiv = document.getElementById('rs-plugin-settings-inline-css');\n\t\t\t\t\tif(htmlDiv) {\n\t\t\t\t\t\thtmlDiv.innerHTML = htmlDiv.innerHTML + htmlDivCss;\n\t\t\t\t\t}else{\n\t\t\t\t\t\tvar htmlDiv = document.createElement('div');\n\t\t\t\t\t\thtmlDiv.innerHTML = '<style>' + htmlDivCss + '<\/style>';\n\t\t\t\t\t\tdocument.getElementsByTagName('head')[0].appendChild(htmlDiv.childNodes[0]);\n\t\t\t\t\t}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n[\/vc_column][\/vc_row][vc_row bg_color=\u00bb#ffffff\u00bb top_padding=\u00bb10&#8243; bottom_padding=\u00bb20&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_row_inner][vc_column_inner css=\u00bb.vc_custom_1621001846585{background-color: #ffffff !important;}\u00bb]<div class=\"iconbox  wpb_content_element iconbox-style-3 icon-color-custom color-dark\"><img src='https:\/\/www.foment.com\/wp-content\/uploads\/2021\/05\/icono-emprenedoria.png' class='iconimg' alt='' \/><h3><\/h3><p>\n<p style=\"font-weight: 400; text-align: center;\">La comisi\u00f3n de Emprendedores reafirma el compromiso de Foment dar respuesta a los retos que tienen que afrontar los nuevos empresarios de Catalu\u00f1a. As\u00ed, la Comisi\u00f3n trabaja para favorecer las condiciones adecuadas para la actividad empresarial y proponer iniciativas y l\u00edneas de actuaci\u00f3n dirigidas a la empresa y a los emprendedores directamente relacionadas con la operativa de la unidad empresarial.<\/p>\n<\/p><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_section\u00bb bg_color=\u00bb#efefef\u00bb top_padding=\u00bb60&#8243; bottom_padding=\u00bb20&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_row_inner][vc_column_inner offset=\u00bbvc_hidden-sm vc_hidden-xs\u00bb]<h1 class=\"headline font-inherit fontsize-xxxl fontweight-700 lh-inherit align-center transform-inherit \" style=\"margin: 0 0 20px 0; color: #000000;\">ACTUALIDAD<\/h1>[vc_column_text]<style type=\"text\/css\">.bdpp-style-mngr-3 .bdpp-post-title {font-size: 16px !important;}.bdpp-style-mngr-3 .bdpp-post-title {line-height: 22px !important;}.bdpp-style-mngr-3 .bdpp-post-title a,\r\n\t\t\t\t   .bdpp-style-mngr-3 .bdpp-post-title a:visited, bdpp-style-mngr-3 .bdpp-post-title a:focus\r\n\t\t\t\t   {color: #000000 !important;}.bdpp-style-mngr-3 .bdpp-post-meta span {font-size: 10px !important;}.bdpp-style-mngr-3 .bdpp-post-meta span, .bdpp-style-mngr-3 .bdpp-post-meta, .bdpp-style-mngr-3 .bdpp-post-meta .bdpp-post-tags a.bdpp-post-cat-link {color: #969696 !important;}<\/style><div id=\"bdpp-post-carousel-wrap-1\" class=\"bdpp-wrap bdpp-post-carousel-wrap owl-carousel bdpp-design-1 botons bdpp-style-mngr-3 bdpp-clearfix\" data-conf=\"{&quot;slide_show&quot;:6,&quot;loop&quot;:true,&quot;slide_margin&quot;:20,&quot;start_position&quot;:0,&quot;arrows&quot;:false,&quot;dots&quot;:true,&quot;autoplay&quot;:false,&quot;autoplay_interval&quot;:5000,&quot;speed&quot;:500,&quot;autoplay_hover_pause&quot;:false,&quot;nav_text&quot;:[&quot;&amp;#x2039;&quot;,&quot;&amp;#x203a;&quot;],&quot;lazyload&quot;:false,&quot;url_hash_listener&quot;:false,&quot;stage_padding&quot;:0,&quot;center&quot;:true,&quot;slide_scroll&quot;:7,&quot;auto_height&quot;:false}\"><div class=\"bdpp-post-slide bdpp-post-216817 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/el-talento-femenino-se-organiza-desde-el-territorio-foment-pone-en-marcha-el-consell-territorial-de-dones-dempresa-de-catalunya\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/JVF6296-300x200.jpg\" alt=\"El talento femenino se organiza desde el territorio: Foment pone en marcha el Consell Territorial de Dones d\u2019Empresa de Catalunya\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/el-talento-femenino-se-organiza-desde-el-territorio-foment-pone-en-marcha-el-consell-territorial-de-dones-dempresa-de-catalunya\/\" target=\"_self\">El talento femenino se organiza desde el territorio: Foment pone en marcha el Consell ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>23 de marzo de 2026<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1657 bdpp-post-cat-igualdad\" href=\"https:\/\/www.foment.com\/es\/category\/igualdad\/\">Igualdad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-8189 bdpp-post-cat-territorial-es\" href=\"https:\/\/www.foment.com\/es\/category\/territorial-es\/\">Territorial<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-215463 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-del-treball-impulsa-el-debate-sobre-soberania-tecnologica-europea-en-el-mwc\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/JVF4553-300x200.jpg\" alt=\"Foment del Treball impulsa el debate sobre soberan\u00eda tecnol\u00f3gica europea en el MWC\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-del-treball-impulsa-el-debate-sobre-soberania-tecnologica-europea-en-el-mwc\/\" target=\"_self\">Foment del Treball impulsa el debate sobre soberan\u00eda tecnol\u00f3gica europea en el MWC<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>3 de marzo de 2026<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-201572 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/transformacion-digital-con-impacto-real-mas-de-1200-pymes-acompanadas-por-foment-a-traves-acelera-pyme\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2025\/05\/JJVF9130-1-300x200.jpg\" alt=\"Transformaci\u00f3n digital con impacto real: m\u00e1s de 1.200 pymes acompa\u00f1adas por Foment a trav\u00e9s de Accelera Pyme\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/transformacion-digital-con-impacto-real-mas-de-1200-pymes-acompanadas-por-foment-a-traves-acelera-pyme\/\" target=\"_self\">Transformaci\u00f3n digital con impacto real: m\u00e1s de 1.200 pymes acompa\u00f1adas por Foment ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>14 de mayo de 2025<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-193597 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/el-world-token-congress-concluye-con-gran-acogida-y-anuncia-su-segunda-edicion-para-2025\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/11\/Portada-300x200.jpg\" alt=\"El World Token Congress concluye con gran acogida y anuncia su segunda edici\u00f3n para 2025\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/el-world-token-congress-concluye-con-gran-acogida-y-anuncia-su-segunda-edicion-para-2025\/\" target=\"_self\">El World Token Congress concluye con gran acogida y anuncia su segunda edici\u00f3n para 2025<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>28 de noviembre de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-69 bdpp-post-cat-economia-y-fiscalidad\" href=\"https:\/\/www.foment.com\/es\/category\/economia-y-fiscalidad\/\">Econom\u00eda y Fiscalidad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-193361 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/exito-en-la-jornada-inaugural-del-world-token-congress-que-se-celebra-en-foment-del-treball\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/11\/2b46db6c-8f68-4239-9cbd-6c80f5c68be8-300x200.jpg\" alt=\"\u00c9xito en la jornada inaugural del World Token Congress que se celebra en Foment del Treball\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/exito-en-la-jornada-inaugural-del-world-token-congress-que-se-celebra-en-foment-del-treball\/\" target=\"_self\">\u00c9xito en la jornada inaugural del World Token Congress que se celebra en Foment ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>27 de noviembre de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-69 bdpp-post-cat-economia-y-fiscalidad\" href=\"https:\/\/www.foment.com\/es\/category\/economia-y-fiscalidad\/\">Econom\u00eda y Fiscalidad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-193311 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/futuro-la-tecnologia-blockchain-tokenizacion-cita-manana-barcelona-world-token-congress\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-26-at-11.15.44-300x169.jpeg\" alt=\"El futuro de la tecnolog\u00eda blockchain y la tokenizaci\u00f3n se da cita ma\u00f1ana en Barcelona con el World Token Congress\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/futuro-la-tecnologia-blockchain-tokenizacion-cita-manana-barcelona-world-token-congress\/\" target=\"_self\">El futuro de la tecnolog\u00eda blockchain y la tokenizaci\u00f3n se da cita ma\u00f1ana en Barcelona ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>26 de noviembre de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-68 bdpp-post-cat-general-2\" href=\"https:\/\/www.foment.com\/es\/category\/general-2\/\">General<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-190343 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-y-el-consulado-general-de-estados-unidos-reafirman-su-alianza-en-la-promocion-del-liderazgo-femenino-y-la-conexion-boston-barcelona-en-la-clausura-del-jump4women\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/09\/photo_6039446741369078823_y-300x200.jpg\" alt=\"Foment y el Consulado General de Estados Unidos revalidan su alianza en la promoci\u00f3n del liderazgo femenino y la conexi\u00f3n Boston-Barcelona en la clausura del Jump4Women\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-y-el-consulado-general-de-estados-unidos-reafirman-su-alianza-en-la-promocion-del-liderazgo-femenino-y-la-conexion-boston-barcelona-en-la-clausura-del-jump4women\/\" target=\"_self\">Foment y el Consulado General de Estados Unidos revalidan su alianza en la promoci\u00f3n ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>30 de septiembre de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1657 bdpp-post-cat-igualdad\" href=\"https:\/\/www.foment.com\/es\/category\/igualdad\/\">Igualdad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-72 bdpp-post-cat-internacionalizacion\" href=\"https:\/\/www.foment.com\/es\/category\/internacionalizacion\/\">Internacionalizaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-189528 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-fortalece-la-conexion-entre-barcelona-y-boston-en-materia-economica-y-de-innovacion\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/09\/Boston-4-300x205.jpeg\" alt=\"Foment fortalece la conexi\u00f3n entre Barcelona y Boston en materia econ\u00f3mica y de innovaci\u00f3n\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-fortalece-la-conexion-entre-barcelona-y-boston-en-materia-economica-y-de-innovacion\/\" target=\"_self\">Foment fortalece la conexi\u00f3n entre Barcelona y Boston en materia econ\u00f3mica y de ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>12 de septiembre de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1657 bdpp-post-cat-igualdad\" href=\"https:\/\/www.foment.com\/es\/category\/igualdad\/\">Igualdad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-72 bdpp-post-cat-internacionalizacion\" href=\"https:\/\/www.foment.com\/es\/category\/internacionalizacion\/\">Internacionalizaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-189272 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-y-el-consulado-general-de-eeuu-lideran-una-mision-en-boston-con-una-veintena-de-emprendedoras\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/09\/boston-300x200.png\" alt=\"Foment y el Consulado General de EE.UU. lideran una misi\u00f3n en Boston con una veintena de emprendedoras\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-y-el-consulado-general-de-eeuu-lideran-una-mision-en-boston-con-una-veintena-de-emprendedoras\/\" target=\"_self\">Foment y el Consulado General de EE.UU. lideran una misi\u00f3n en Boston con una veintena ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>8 de septiembre de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1657 bdpp-post-cat-igualdad\" href=\"https:\/\/www.foment.com\/es\/category\/igualdad\/\">Igualdad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-72 bdpp-post-cat-internacionalizacion\" href=\"https:\/\/www.foment.com\/es\/category\/internacionalizacion\/\">Internacionalizaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-187510 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/demoday-para-dar-impulso-a-los-proyectos-de-las-18-emprendedoras-del-programa-jump4women\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/07\/portader-2-1-300x155.jpg\" alt=\"Demoday para dar impulso a los proyectos de las emprendedoras del programa Jump4Women\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/demoday-para-dar-impulso-a-los-proyectos-de-las-18-emprendedoras-del-programa-jump4women\/\" target=\"_self\">Demoday para dar impulso a los proyectos de las emprendedoras del programa Jump4Women<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>11 de julio de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-8407 bdpp-post-cat-noticias-revista\" href=\"https:\/\/www.foment.com\/es\/category\/revista-f\/noticias-revista\/\">Noticias<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-185819 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-del-treball-y-amazon-colaboran-en-un-nuevo-programa-para-acelerar-la-digitalizacion-de-15-pymes-catalanas\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/06\/banner_amazonimpulsa-1-300x103.png\" alt=\"Foment del Treball y Amazon colaboran en un nuevo programa para acelerar la digitalizaci\u00f3n de 15 pymes catalanas\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-del-treball-y-amazon-colaboran-en-un-nuevo-programa-para-acelerar-la-digitalizacion-de-15-pymes-catalanas\/\" target=\"_self\">Foment del Treball y Amazon colaboran en un nuevo programa para acelerar la digitalizaci\u00f3n ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>18 de junio de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-8407 bdpp-post-cat-noticias-revista\" href=\"https:\/\/www.foment.com\/es\/category\/revista-f\/noticias-revista\/\">Noticias<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-184233 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/barcelona-acogera-el-world-token-congress-27-y-28-de-noviembre-en-foment\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/05\/1.Portada-300x200.jpg\" alt=\"Barcelona acoger\u00e1 el World Token Congress los d\u00edas 27 y 28 de noviembre en Foment del Treball\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/barcelona-acogera-el-world-token-congress-27-y-28-de-noviembre-en-foment\/\" target=\"_self\">Barcelona acoger\u00e1 el World Token Congress los d\u00edas 27 y 28 de noviembre en Foment ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>28 de mayo de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-182452 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-crea-comision-inteligencia-artificial\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/05\/giu-vicente-FMArg2k3qOU-unsplash-300x199.jpg\" alt=\"Foment del Treball crea una Comisi\u00f3n de Inteligencia Artificial\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-crea-comision-inteligencia-artificial\/\" target=\"_self\">Foment del Treball crea una Comisi\u00f3n de Inteligencia Artificial<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>8 de mayo de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-8495 bdpp-post-cat-inteligencia-artificial-es\" href=\"https:\/\/www.foment.com\/es\/category\/inteligencia-artificial-es\/\">Inteligencia Artificial<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-179947 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-y-consulado-general-estados-unidos-presentan-20-emprendedoras-seleccionadas-con-beca-jump-startup-for-women-in-deeptech\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/03\/20240322114103__OB_1797-300x200.jpg\" alt=\"Foment y el Consulado General de los Estados Unidos presentan a las 20 emprendedoras seleccionadas con la beca Jump Startup for Women in Deeptech\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-y-consulado-general-estados-unidos-presentan-20-emprendedoras-seleccionadas-con-beca-jump-startup-for-women-in-deeptech\/\" target=\"_self\">Foment y el Consulado General de los Estados Unidos presentan a las 20 emprendedoras ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>22 de marzo de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-179778 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-del-treball-alza-el-vuelo-con-la-incorporacion-de-level-como-socio\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/03\/DSC_1063-300x200.jpg\" alt=\"Foment del Treball alza el vuelo con la incorporaci\u00f3n de LEVEL como socio\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-del-treball-alza-el-vuelo-con-la-incorporacion-de-level-como-socio\/\" target=\"_self\">Foment del Treball alza el vuelo con la incorporaci\u00f3n de LEVEL como socio<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>21 de marzo de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-344 bdpp-post-cat-mujer-empresa\" href=\"https:\/\/www.foment.com\/es\/category\/mujer-empresa\/\">Mujer y Empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-178388 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/sanchez-llibre-ensalza-barcelona-como-marca-invencible-en-el-mwc-2024\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/02\/PVC09708-scaled-1-300x200.jpeg\" alt=\"S\u00e1nchez Llibre ensalza Barcelona como marca invencible en el MWC 2024\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/sanchez-llibre-ensalza-barcelona-como-marca-invencible-en-el-mwc-2024\/\" target=\"_self\">S\u00e1nchez Llibre ensalza Barcelona como marca invencible en el MWC 2024<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>28 de febrero de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-178270 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/jump\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/02\/banner4_en-300x103.png\" alt=\"Presenta tu candidatura para el \u2018Jump Startup for Women in deeptech: biotech and healthtech\u2019\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/jump\/\" target=\"_self\">Presenta tu candidatura para el \u2018Jump Startup for Women in deeptech: biotech and ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>23 de febrero de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-176749 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-y-el-consulado-general-de-ee-uu-reafirman-su-apuesta-por-las-lideres-emprendedoras-con-el-lanzamiento-de-jump-startup-for-women-in-deeptech\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/01\/DSC_0980-300x200.jpg\" alt=\"Foment y el Consulado General de EE.UU. reafirman su apuesta por las l\u00edderes emprendedoras con el lanzamiento de Jump Startup for Women in Deeptech\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-y-el-consulado-general-de-ee-uu-reafirman-su-apuesta-por-las-lideres-emprendedoras-con-el-lanzamiento-de-jump-startup-for-women-in-deeptech\/\" target=\"_self\">Foment y el Consulado General de EE.UU. reafirman su apuesta por las l\u00edderes emprendedoras ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>12 de enero de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-344 bdpp-post-cat-mujer-empresa\" href=\"https:\/\/www.foment.com\/es\/category\/mujer-empresa\/\">Mujer y Empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-175719 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/edicion-programa-emprendimiento-awe-2023-finaliza-entregando-premios-proyectos-destacados-innovadoras\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2023\/12\/photo1702557293-9-300x200.jpeg\" alt=\"La edici\u00f3n del programa de emprendimiento AWE 2023 finaliza con la entrega de los premios a los proyectos m\u00e1s destacados de las innovadoras\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/edicion-programa-emprendimiento-awe-2023-finaliza-entregando-premios-proyectos-destacados-innovadoras\/\" target=\"_self\">La edici\u00f3n del programa de emprendimiento AWE 2023 finaliza con la entrega de los ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>14 de diciembre de 2023<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-171850 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/cepyme-cea-y-foment-de-treball-apuestan-por-celebrar-del-dia-de-la-empresa-a-nivel-nacional\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2023\/10\/bd1afb83-25db-44be-9797-f362f74c46a1-300x225.jpg\" alt=\"CEPYME, CEA y Foment de Treball apuestan por celebrar del D\u00eda de la Empresa a nivel nacional\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/cepyme-cea-y-foment-de-treball-apuestan-por-celebrar-del-dia-de-la-empresa-a-nivel-nacional\/\" target=\"_self\">CEPYME, CEA y Foment de Treball apuestan por celebrar del D\u00eda de la Empresa a nivel ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>26 de octubre de 2023<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-170242 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/encuentro-entre-foment-del-treball-y-multinacionales-con-espana\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2023\/10\/DSC_0428-300x200.jpg\" alt=\"Encuentro entre Foment del Treball y Multinacionales con Espa\u00f1a\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/encuentro-entre-foment-del-treball-y-multinacionales-con-espana\/\" target=\"_self\">Encuentro entre Foment del Treball y Multinacionales con Espa\u00f1a<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>4 de octubre de 2023<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-69 bdpp-post-cat-economia-y-fiscalidad\" href=\"https:\/\/www.foment.com\/es\/category\/economia-y-fiscalidad\/\">Econom\u00eda y Fiscalidad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row bg_color=\u00bb#efefef\u00bb][vc_column width=\u00bb1\/1&#8243;][vc_row_inner][vc_column_inner offset=\u00bbvc_hidden-lg vc_hidden-md\u00bb]<h1 class=\"headline font-inherit fontsize-xxxl fontweight-700 lh-inherit align-center transform-inherit \" style=\"margin: 0 0 20px 0; color: #000000;\">ACTUALIDAD<\/h1>[vc_column_text]<style type=\"text\/css\">.bdpp-style-mngr-3 .bdpp-post-title {font-size: 16px !important;}.bdpp-style-mngr-3 .bdpp-post-title {line-height: 22px !important;}.bdpp-style-mngr-3 .bdpp-post-title a,\r\n\t\t\t\t   .bdpp-style-mngr-3 .bdpp-post-title a:visited, bdpp-style-mngr-3 .bdpp-post-title a:focus\r\n\t\t\t\t   {color: #000000 !important;}.bdpp-style-mngr-3 .bdpp-post-meta span {font-size: 10px !important;}.bdpp-style-mngr-3 .bdpp-post-meta span, .bdpp-style-mngr-3 .bdpp-post-meta, .bdpp-style-mngr-3 .bdpp-post-meta .bdpp-post-tags a.bdpp-post-cat-link {color: #969696 !important;}<\/style><div id=\"bdpp-post-carousel-wrap-2\" class=\"bdpp-wrap bdpp-post-carousel-wrap owl-carousel bdpp-design-1 botons bdpp-style-mngr-3 bdpp-clearfix\" data-conf=\"{&quot;slide_show&quot;:1,&quot;loop&quot;:true,&quot;slide_margin&quot;:20,&quot;start_position&quot;:0,&quot;arrows&quot;:false,&quot;dots&quot;:true,&quot;autoplay&quot;:false,&quot;autoplay_interval&quot;:5000,&quot;speed&quot;:500,&quot;autoplay_hover_pause&quot;:false,&quot;nav_text&quot;:[&quot;&amp;#x2039;&quot;,&quot;&amp;#x203a;&quot;],&quot;lazyload&quot;:false,&quot;url_hash_listener&quot;:false,&quot;stage_padding&quot;:0,&quot;center&quot;:false,&quot;slide_scroll&quot;:1,&quot;auto_height&quot;:false}\"><div class=\"bdpp-post-slide bdpp-post-216817 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/el-talento-femenino-se-organiza-desde-el-territorio-foment-pone-en-marcha-el-consell-territorial-de-dones-dempresa-de-catalunya\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/JVF6296-300x200.jpg\" alt=\"El talento femenino se organiza desde el territorio: Foment pone en marcha el Consell Territorial de Dones d\u2019Empresa de Catalunya\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/el-talento-femenino-se-organiza-desde-el-territorio-foment-pone-en-marcha-el-consell-territorial-de-dones-dempresa-de-catalunya\/\" target=\"_self\">El talento femenino se organiza desde el territorio: Foment pone en marcha el Consell ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>23 de marzo de 2026<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1657 bdpp-post-cat-igualdad\" href=\"https:\/\/www.foment.com\/es\/category\/igualdad\/\">Igualdad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-8189 bdpp-post-cat-territorial-es\" href=\"https:\/\/www.foment.com\/es\/category\/territorial-es\/\">Territorial<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-215463 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-del-treball-impulsa-el-debate-sobre-soberania-tecnologica-europea-en-el-mwc\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/JVF4553-300x200.jpg\" alt=\"Foment del Treball impulsa el debate sobre soberan\u00eda tecnol\u00f3gica europea en el MWC\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/foment-del-treball-impulsa-el-debate-sobre-soberania-tecnologica-europea-en-el-mwc\/\" target=\"_self\">Foment del Treball impulsa el debate sobre soberan\u00eda tecnol\u00f3gica europea en el MWC<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>3 de marzo de 2026<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-201572 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/transformacion-digital-con-impacto-real-mas-de-1200-pymes-acompanadas-por-foment-a-traves-acelera-pyme\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2025\/05\/JJVF9130-1-300x200.jpg\" alt=\"Transformaci\u00f3n digital con impacto real: m\u00e1s de 1.200 pymes acompa\u00f1adas por Foment a trav\u00e9s de Accelera Pyme\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/transformacion-digital-con-impacto-real-mas-de-1200-pymes-acompanadas-por-foment-a-traves-acelera-pyme\/\" target=\"_self\">Transformaci\u00f3n digital con impacto real: m\u00e1s de 1.200 pymes acompa\u00f1adas por Foment ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>14 de mayo de 2025<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-193597 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/el-world-token-congress-concluye-con-gran-acogida-y-anuncia-su-segunda-edicion-para-2025\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/11\/Portada-300x200.jpg\" alt=\"El World Token Congress concluye con gran acogida y anuncia su segunda edici\u00f3n para 2025\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/el-world-token-congress-concluye-con-gran-acogida-y-anuncia-su-segunda-edicion-para-2025\/\" target=\"_self\">El World Token Congress concluye con gran acogida y anuncia su segunda edici\u00f3n para 2025<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>28 de noviembre de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-69 bdpp-post-cat-economia-y-fiscalidad\" href=\"https:\/\/www.foment.com\/es\/category\/economia-y-fiscalidad\/\">Econom\u00eda y Fiscalidad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><div class=\"bdpp-post-slide bdpp-post-193361 bdpp-post-standard bdpp-has-thumb\" >\n\t<div class=\"bdpp-post-carousel-content\">\n\t\t\t\t<div class=\"bdpp-post-img-bg\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/exito-en-la-jornada-inaugural-del-world-token-congress-que-se-celebra-en-foment-del-treball\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/11\/2b46db6c-8f68-4239-9cbd-6c80f5c68be8-300x200.jpg\" alt=\"\u00c9xito en la jornada inaugural del World Token Congress que se celebra en Foment del Treball\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\n\t\t<div class=\"titledate0408\">\n\t\t<h2 class=\"bdpp-post-title0408\">\n\t\t\t<a href=\"https:\/\/www.foment.com\/es\/exito-en-la-jornada-inaugural-del-world-token-congress-que-se-celebra-en-foment-del-treball\/\" target=\"_self\">\u00c9xito en la jornada inaugural del World Token Congress que se celebra en Foment ...<\/a>\n\t\t<\/h2>\n\n\t\t\t\t\t<div class=\"bdpp-post-meta bdpp-post-meta-up\">\n\t\t\t\t<span class=\"bdpp-post-meta-data bdpp-post-date\"><i class=\"fa fa-clock-o\"><\/i>27 de noviembre de 2024<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bdpp-post-cats0408\"><a class=\"bdpp-post-cat-link bdpp-post-cat-114 bdpp-post-cat-destacamos\" href=\"https:\/\/www.foment.com\/es\/category\/destacamos\/\">Destacamos<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-69 bdpp-post-cat-economia-y-fiscalidad\" href=\"https:\/\/www.foment.com\/es\/category\/economia-y-fiscalidad\/\">Econom\u00eda y Fiscalidad<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-67 bdpp-post-cat-emprendedores\" href=\"https:\/\/www.foment.com\/es\/category\/emprendedores\/\">Emprendedores y empresa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-71 bdpp-post-cat-innovacion\" href=\"https:\/\/www.foment.com\/es\/category\/innovacion\/\">Innovaci\u00f3n<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-5714 bdpp-post-cat-prensa\" href=\"https:\/\/www.foment.com\/es\/category\/prensa\/\">Prensa<\/a> <a class=\"bdpp-post-cat-link bdpp-post-cat-1661 bdpp-post-cat-sociedad-digital\" href=\"https:\/\/www.foment.com\/es\/category\/sociedad-digital\/\">Sociedad Digital<\/a><\/div>\n\t\t\n\n\n\n\t\t\t<\/div>\n<\/div><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_section css=\u00bb.vc_custom_1621669472452{margin-top: px !important;padding-top: px !important;}\u00bb][vc_row top_padding=\u00bb70&#8243; bottom_padding=\u00bb70&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_column_text]<\/p>\n<ul style=\"list-style-type: disc; font-size: 25px; color: #d2112d;\">\n<li class=\"black\" style=\"text-align: left;\"><span style=\"color: #000000; font-size: 14px; line-height: 22px;\">Impulso de un clima favorable para el emprendimiento.<\/span><\/li>\n<\/ul>\n<ul style=\"list-style-type: disc; font-size: 25px; color: #d2112d;\">\n<li class=\"black\" style=\"text-align: left;\"><span style=\"color: #000000; font-size: 14px; line-height: 22px;\">Identificaci\u00f3n de los problemas de acceso al cr\u00e9dito para las actividades empresariales viables. En la medida de lo posible, identificar y fomentar la articulaci\u00f3n de mecanismos facilitadores de nueva financiaci\u00f3n.<\/span><\/li>\n<\/ul>\n<ul style=\"list-style-type: disc; font-size: 25px; color: #d2112d;\">\n<li class=\"black\" style=\"text-align: left;\"><span style=\"color: #000000; font-size: 14px; line-height: 22px;\">Facilitar la reorientaci\u00f3n de la actividad a trav\u00e9s de la innovaci\u00f3n.<\/span><\/li>\n<\/ul>\n<ul style=\"list-style-type: disc; font-size: 25px; color: #d2112d;\">\n<li class=\"black\" style=\"text-align: left;\"><span style=\"color: #000000; font-size: 14px; line-height: 22px;\">Informar de toda la normativa, proyectos y l\u00edneas p\u00fablicas de apoyo al emprendimiento.<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column width=\u00bb1\/1&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_row section_arrow=\u00bbfalse\u00bb top_padding=\u00bb70&#8243; bottom_padding=\u00bb60&#8243;][vc_column width=\u00bb1\/1&#8243;]<h2 class=\"headline font-inherit fontsize-xxxl fontweight-700 lh-inherit align-center transform-inherit \" style=\"margin: 0 0 50px 0; color: #000000;\">ACTIVIDADES DESTACADAS<\/h2>[vc_column_text]<div id=\"evcal_calendar_453\" class=\"ajde_evcal_calendar evoslider evosliderbox multiSlider cs_lr ss_def sltac\"><div class=\"evo_slider_outter\" >\r\n\t\t\t\t\t<div class=\"evo_slider_slide_out\">\r\n\t                <div class=\"eventon_events_list\" style=\"display:none\"><div  id=\"event_223452_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_223452_0\" data-event_id=\"223452\" data-ri=\"0r\" data-time=\"1783342800-1784124000\" data-colr=\"#ff91a2\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/founder-ceo-sprint\/'><\/a><meta itemprop='image' content=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260706_FounderSprint_Banner_ES.png\" \/><meta itemprop='startDate' content=\"2026-7-6T13:00+2:00\" \/><meta itemprop='endDate' content=\"2026-7-15T14:00+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/VirtualLocation\"><\/item><item style=\"display:none\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><span itemprop=\"name\">Online<\/span><span itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\"><item itemprop=\"streetAddress\">Online<\/item><\/span><\/item><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/MixedEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3n\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3n\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_223452_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/MixedEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"Founder &amp;#038; CEO Sprint\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/founder-ceo-sprint\/\",\n\t\t\t\t\t\"startDate\": \"2026-7-6T13:00+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-7-15T14:00+2:00\",\n\t\t\t\t\t\"image\":\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260706_FounderSprint_Banner_ES.png\", \n\t\t\t\t\t\"description\":\"<p class='isSelectedEnd'><span style='color: #d2112e; font-family: verdana, geneva, sans-serif;'><strong>6 d\u00edas \u00b7 6 momentos empresariales \u00b7 6 sesiones para desbloquear el siguiente paso de tu negocio.\u200b<\/strong><\/span><\/p> <p class='isSelectedEnd'><span style='font-family: verdana, geneva, sans-serif;'><strong>Foment Oficina Acelera Pym<\/strong>e y <strong>Startups Institute<\/strong> organizan un ciclo de sesiones cortas, pr\u00e1cticas y en directo, para founders, pymes, aut\u00f3nomos, startups y perfiles de innovaci\u00f3n.\u200b<\/span><\/p> <p class='isSelectedEnd'><span style='font-family: verdana, geneva, sans-serif;'>Cada sesi\u00f3n aborda un momento distinto del negocio. Ap\u00fantate a todas, o a las que te interesen, seg\u00fan el punto en el que est\u00e9s. Sesiones de 1 hora, impartidas por <strong>Miguel \u00c1ngel D\u00edez Ferreira, <\/strong>fundador de Startups Institute.\u200b<\/span><\/p> <p class='isSelectedEnd'><span style='color: #d2112e; font-family: verdana, geneva, sans-serif;'><strong>Bloque Founders \u00b7 13:00\u201314:00 h<\/strong> <\/span><\/p> <ul> <li class='isSelectedEnd'><span style='font-family: verdana, geneva, sans-serif;'><strong>Lun 6 jul<\/strong> \u2014 C\u00f3mo crear un negocio sin dejar tu trabajo <\/span><\/li> <li class='isSelectedEnd'><span style='font-family: verdana, geneva, sans-serif;'><strong>Mar 7 jul<\/strong> \u2014 Emprender en tiempos de IA <\/span><\/li> <li class='isSelectedEnd'><span style='font-family: verdana, geneva, sans-serif;'><strong>Mi\u00e9 8 jul<\/strong> \u2014 Qu\u00e9 es una startup y c\u00f3mo funciona<\/span><\/li> <\/ul> <p class='isSelectedEnd'><span style='font-family: verdana, geneva, sans-serif;'>\u200b<span style='color: #d2112e;'><strong>Bloque CEOs \u00b7 13:00\u201314:00 h<\/strong><\/span>\u00a0<\/span><\/p> <ul> <li><span style='font-family: verdana, geneva, sans-serif;'><strong>Lun 13 jul<\/strong> \u2014 Las 8 barreras de entrada (moats) para proteger tu negocio\u00a0 <\/span><\/li> <li><span style='font-family: verdana, geneva, sans-serif;'><strong>Mar 14 jul<\/strong> \u2014 C\u00f3mo preparar una ronda de inversi\u00f3n\u00a0 <\/span><\/li> <li><span style='font-family: verdana, geneva, sans-serif;'><strong>Mi\u00e9 15 jul<\/strong> \u2014 C\u00f3mo escalar un negocio (bien)<\/span><\/li> <\/ul> <p class='isSelectedEnd'><span style='font-family: verdana, geneva, sans-serif;'><em><strong>\u200b\u26a0\ufe0f Importante: todas las sesiones son online. Unas horas antes de cada una, se enviar\u00e1 el enlace correspondiente.<\/strong><\/em><\/span><\/p> <p style='text-align: center;'><span style='color: #d2112e;'><a style='color: #d2112e;' href='https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=jZN882U4iUq5m7AAx2p0v1sudKHVcspJmbHzaYM5-MBUMDdLODlQRTVUSk1TN1VQRTkwVktVUlBKVSQlQCNjPTEkJUAjdD1n'><span style='font-family: verdana, geneva, sans-serif;'><strong>Ap\u00fantate aqu\u00ed<\/strong><\/span><\/a><\/span><\/p> <p><span style='font-family: verdana, geneva, sans-serif; font-size: 13px;'><strong>Foment del Treball <\/strong>ha sido acreditada como Oficina Acelera Pyme, una iniciativa del Ministerio de Transformaci\u00f3n Digital y de la Funci\u00f3n P\u00fablica, desarrollada por Red.es, destinada a construir el ecosistema de referencia de la transformaci\u00f3n digital de las pymes. Convocatoria de ayudas 2025 para la creaci\u00f3n de la red de Oficinas Acelera Pyme, expediente C004\/25-ED CV7<\/span><\/p> \",\"location\":[{\"@type\":\"VirtualLocation\"},{\"@type\":\"Place\",\"name\":\"Online\",\"address\":{\"@type\": \"PostalAddress\",\"streetAddress\":\"Online\"}}],\"organizer\":{\"@type\":\"Organization\",\"name\":\"Innovaci\u00f3n\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Innovaci\u00f3n\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"0\" style=\"border-color: #ff91a2;\" id=\"evc_1783342800223452\" class=\"hasFtIMG desc_trig evo_jornades-oap mul_val evcal_list_a\" data-ux_val=\"3\"  ><span class='ev_ftImg' data-img='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260706_FounderSprint_Banner_ES.png' data-thumb='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260706_FounderSprint_Banner_ES-300x169.png' style='background-image:url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260706_FounderSprint_Banner_ES-300x169.png\")'><\/span><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#ff91a2 !important;' class='evcal_cblock ' data-smon='julio' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>06<\/em><em class='month'>jul<\/em><em class='time'><i t=\"y\">(jul 6)<\/i>13:00<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end '><em class='date'>15<\/em><em class='time'><i t=\"y\">(jul 15)<\/i>14:00<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  data-location_address=\"Online\" data-location_type=\"lonlat\" data-location_name=\"Online\" data-location_url=\"https:\/\/www.foment.com\/es\/event-location\/online\/\" data-location_status=\"true\" data-latlng=\"Online,Online\" ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>Founder &#038; CEO Sprint<\/span><span class='evo_below_title'><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>13:00 - 14:00 <em class=\"evo_endday\">(15)<\/em><\/em> <\/span><span class='evcal_desc3'><em class=\"evcal_location\"  data-latlng=\"Online,Online\" data-add_str=\"\"><em class=\"event_location_name\">Online<\/em><\/em><\/span><span style='height: 60px;'  class='evcal_desc3' ><span class='evcal_event_types ett1'><em>C =<\/em><em data-filter='event_type'>Jornades OAP<\/em><i class='clear'><\/i><\/span><span class='evo_event_progress' ><span class='evo_epbar_o'><span class='evo_ep_bar'><b style='width:95%'><\/b><\/span><\/span><span class='evo_ep_time evo_countdowner' data-gap='36681' data-dur='781200' data-exp_act='' data-n='' data-ds='d\u00edas' data-d='D\u00eda' data-t='de tiempo restante'><\/span><\/span><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evo_metarow_fimg evorow evcal_evdata_img evcal_evdata_row  evo_imghover' data-imgheight='941' data-imgwidth='1672'  style='background-image: url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260706_FounderSprint_Banner_ES.png\")' data-imgstyle='full' data-minheight='400' data-status=''><\/div><div class='evcal_evdata_row evorow_2b evo_metarow_time_location evorow  '>\n\t\t\t\t\t\t\t\t<div class='evorow_b evorow_b1 evo_time'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p><span class='evo_eventcard_time_t'>6 (Lunes) 13:00 - 15 (Mi\u00e9rcoles) 14:00<\/span><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class='evorow_b evo_location'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell' data-loc_tax_id='3362'><h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>Lugar<\/h3><p class='evo_location_name'>Online<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>6 d\u00edas \u00b7 6 momentos empresariales \u00b7 6 sesiones para desbloquear el siguiente paso de tu negocio.\u200b\nFoment Oficina<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p class=\"isSelectedEnd\"><span style=\"color: #d2112e; font-family: verdana, geneva, sans-serif;\"><strong>6 d\u00edas \u00b7 6 momentos empresariales \u00b7 6 sesiones para desbloquear el siguiente paso de tu negocio.\u200b<\/strong><\/span><\/p>\n<p class=\"isSelectedEnd\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Foment Oficina Acelera Pym<\/strong>e y <strong>Startups Institute<\/strong> organizan un ciclo de sesiones cortas, pr\u00e1cticas y en directo, para founders, pymes, aut\u00f3nomos, startups y perfiles de innovaci\u00f3n.\u200b<\/span><\/p>\n<p class=\"isSelectedEnd\"><span style=\"font-family: verdana, geneva, sans-serif;\">Cada sesi\u00f3n aborda un momento distinto del negocio. Ap\u00fantate a todas, o a las que te interesen, seg\u00fan el punto en el que est\u00e9s. Sesiones de 1 hora, impartidas por <strong>Miguel \u00c1ngel D\u00edez Ferreira, <\/strong>fundador de Startups Institute.\u200b<\/span><\/p>\n<p class=\"isSelectedEnd\"><span style=\"color: #d2112e; font-family: verdana, geneva, sans-serif;\"><strong>Bloque Founders \u00b7 13:00\u201314:00 h<\/strong> <\/span><\/p>\n<ul>\n<li class=\"isSelectedEnd\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Lun 6 jul<\/strong> \u2014 C\u00f3mo crear un negocio sin dejar tu trabajo <\/span><\/li>\n<li class=\"isSelectedEnd\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Mar 7 jul<\/strong> \u2014 Emprender en tiempos de IA <\/span><\/li>\n<li class=\"isSelectedEnd\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Mi\u00e9 8 jul<\/strong> \u2014 Qu\u00e9 es una startup y c\u00f3mo funciona<\/span><\/li>\n<\/ul>\n<p class=\"isSelectedEnd\"><span style=\"font-family: verdana, geneva, sans-serif;\">\u200b<span style=\"color: #d2112e;\"><strong>Bloque CEOs \u00b7 13:00\u201314:00 h<\/strong><\/span>\u00a0<\/span><\/p>\n<ul>\n<li><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Lun 13 jul<\/strong> \u2014 Las 8 barreras de entrada (moats) para proteger tu negocio\u00a0 <\/span><\/li>\n<li><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Mar 14 jul<\/strong> \u2014 C\u00f3mo preparar una ronda de inversi\u00f3n\u00a0 <\/span><\/li>\n<li><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Mi\u00e9 15 jul<\/strong> \u2014 C\u00f3mo escalar un negocio (bien)<\/span><\/li>\n<\/ul>\n<p class=\"isSelectedEnd\"><span style=\"font-family: verdana, geneva, sans-serif;\"><em><strong>\u200b\u26a0\ufe0f Importante: todas las sesiones son online. Unas horas antes de cada una, se enviar\u00e1 el enlace correspondiente.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #d2112e;\"><a style=\"color: #d2112e;\" href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=jZN882U4iUq5m7AAx2p0v1sudKHVcspJmbHzaYM5-MBUMDdLODlQRTVUSk1TN1VQRTkwVktVUlBKVSQlQCNjPTEkJUAjdD1n\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Ap\u00fantate aqu\u00ed<\/strong><\/span><\/a><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 13px;\"><strong>Foment del Treball <\/strong>ha sido acreditada como Oficina Acelera Pyme, una iniciativa del Ministerio de Transformaci\u00f3n Digital y de la Funci\u00f3n P\u00fablica, desarrollada por Red.es, destinada a construir el ecosistema de referencia de la transformaci\u00f3n digital de las pymes. Convocatoria de ayudas 2025 para la creaci\u00f3n de la red de Oficinas Acelera Pyme, expediente C004\/25-ED CV7<\/span><\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t<p class='evo_data_val evo_card_organizer_image'><img src='https:\/\/www.foment.com\/wp-content\/uploads\/2016\/10\/innovacio-competitiva.png'\/><\/p>\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Innovaci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_address'>Innovaci\u00f3 Competitiva<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=223452&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=Founder+%26%23038%3B+CEO+Sprint&amp;dates=20260706T110000Z\/20260715T120000Z&amp;ctz=Europe\/Madrid&amp;details=Founder+%26%23038%3B+CEO+Sprint&amp;location=OnlineOnline' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class='evo_metarow_rel_events evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-calendar-plus'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Eventos relacionados<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='evcal_cell_rel_events'>\n\t\t\t\t\t\t\t\t\t\t<a href='https:\/\/www.foment.com\/es\/events\/como-hacer-que-chatgpt-recomiende-tu-negocio\/'><b>C\u00f3mo hacer que ChatGPT recomiende tu negocio.<\/b><em>10 de julio de 2026 10:00 - 12:00<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/ia-per-millorar-el-marqueting-i-lexperiencia-de-client\/'><b>IA para mejorar el m\u00e1rqueting y la experiencia de cliente<\/b><em>30 de junio de 2026 12:00 - 13:30<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/estrategia-digital-para-pymes\/'><b>Estrategia digital para pymes.<\/b><em>22 de julio de 2026 11:00 - 12:30<\/em><\/a><a href='https:\/\/www.foment.com\/en\/events\/como-potenciar-las-ventas-con-ia\/'><b>C\u00f3mo potenciar las ventas con IA<\/b><em>2 de julio de 2026 11:30 - 13:30<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/como-potenciar-las-ventas-con-ia\/'><b>C\u00f3mo potenciar las ventas con IA<\/b><em>2 de julio de 2026 11:30 - 13:30<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/te-escuchamos-focus-group-e-ia-sin-ruido\/'><b>Te escuchamos: Focus group e IA sin ruido<\/b><em>23 de septiembre de 2026 12:00 - 13:30<\/em><\/a>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><div  id=\"event_223331_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_223331_0\" data-event_id=\"223331\" data-ri=\"0r\" data-time=\"1784106000-1784116800\" data-colr=\"#4bb5d8\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/defensa-i-empresa-industria-financament-i-cultura-de-defensa-a-catalunya\/'><\/a><meta itemprop='image'  \/><meta itemprop='startDate' content=\"2026-7-15T09:00+2:00\" \/><meta itemprop='endDate' content=\"2026-7-15T12:00+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><span itemprop=\"name\">Foment del Treball<\/span><span itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\"><item itemprop=\"streetAddress\">Via Laietana 32<\/item><\/span><\/item><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/OfflineEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Comissi\u00f3 de Seguretat\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Comissi\u00f3 de Seguretat\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_223331_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"Defensa y empresa: industria, financiaci\u00f3n y cultura de defensa en Catalunya\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/defensa-i-empresa-industria-financament-i-cultura-de-defensa-a-catalunya\/\",\n\t\t\t\t\t\"startDate\": \"2026-7-15T09:00+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-7-15T12:00+2:00\",\n\t\t\t\t\t\"image\":\"\", \n\t\t\t\t\t\"description\":\"<p>[vc_row][vc_column][vc_column_text]En un contexto internacional marcado por la inestabilidad geopol\u00edtica, el refuerzo de las capacidades de seguridad y defensa y la necesidad de avanzar hacia una mayor autonom\u00eda estrat\u00e9gica europea, la industria adquiere un papel cada vez m\u00e1s decisivo.<\/p> <p>Defensa, energ\u00eda, comunicaciones, industria tecnol\u00f3gica, ciberseguridad, infraestructuras cr\u00edticas y cadenas de suministro son hoy \u00e1mbitos estrechamente conectados con la seguridad econ\u00f3mica y la resiliencia de Europa. En este escenario, Catalu\u00f1a cuenta con un tejido empresarial, industrial y tecnol\u00f3gico con capacidades relevantes para contribuir a las nuevas prioridades estrat\u00e9gicas.<\/p> <p>Con este prop\u00f3sito, celebraremos la jornada \u201cDefensa y empresa: industria, financiaci\u00f3n y cultura de defensa en Catalu\u00f1a\u201d, un encuentro dirigido a empresas e instituciones interesadas en el papel de la industria ante el nuevo contexto de seguridad europeo.<\/p> <p>&nbsp;<\/p> <table style='border-collapse: collapse; width: 100%; height: 28px;'> <tbody> <tr style='height: 28px;'> <td style='width: 50%; text-align: center; height: 28px;'><a href='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/Programa-Provisional-ESP-6.pdf'><strong style='text-align: center;'><span style='color: #d2112d;'>PROGRAMA<\/span><\/strong><\/a><\/td> <td style='width: 50%; text-align: center; height: 28px;'><a href='https:\/\/www.foment.com\/es\/inscripciones-eventos\/?idevento=C306DEA8-436A-F111-A826-000D3ABA73B5'>\u00a0<strong><span style='color: #d2112d;'>INSCRIPCI\u00d3N<\/span><\/strong><\/a><\/td> <\/tr> <\/tbody> <\/table> <p>&nbsp;<\/p> <p>&nbsp;<\/p> <p style='text-align: center;'><strong>En colaboraci\u00f3n con:<\/strong><\/p> <p>[\/vc_column_text]<div class='single_image wpb_content_element align-center    ' data-animation='none' data-delay='0'><img width='662' height='81' src='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/patros-defensa_15.7.26.png' class='attachment-full' alt='' loading='lazy' title='patros defensa_15.7.26' srcset='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/patros-defensa_15.7.26.png 662w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/patros-defensa_15.7.26-300x37.png 300w' sizes='(max-width: 662px) 100vw, 662px' \/><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p> <p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p> \",\"location\":[{\"@type\":\"Place\",\"name\":\"Foment del Treball\",\"address\":{\"@type\": \"PostalAddress\",\"streetAddress\":\"Via Laietana 32\"}}],\"organizer\":{\"@type\":\"Organization\",\"name\":\"Comissi\u00f3 de Seguretat\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Comissi\u00f3 de Seguretat\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"0\" style=\"border-color: #4bb5d8;\" id=\"evc_1784106000223331\" class=\"desc_trig evo_seguretat-es sin_val evcal_list_a\" data-ux_val=\"3\"  ><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#4bb5d8 !important;' class='evcal_cblock ' data-smon='julio' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>15<\/em><em class='month'>jul<\/em><em class='time'>9:00<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end only_time'><em class='time'>12:00<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  data-location_address=\"Via Laietana 32\" data-location_type=\"address\" data-location_name=\"Foment del Treball\" data-location_url=\"https:\/\/www.foment.com\/es\/event-location\/foment-del-treball\/\" data-location_status=\"true\" ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>Defensa y empresa: industria, financiaci\u00f3n y cultura de defensa en Catalunya<\/span><span class='evo_below_title'><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>9:00 - 12:00<\/em> <\/span><span class='evcal_desc3'><em class=\"evcal_location\"  data-add_str=\"\"><em class=\"event_location_name\">Foment del Treball<\/em><\/em><\/span><span style='height: 60px;'  class='evcal_desc3' ><span class='evcal_event_types ett1'><em>C =<\/em><em data-filter='event_type'>Seguretat<\/em><i class='clear'><\/i><\/span><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evcal_evdata_row evorow_2b evo_metarow_time_location evorow  '>\n\t\t\t\t\t\t\t\t<div class='evorow_b evorow_b1 evo_time'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p><span class='evo_eventcard_time_t'>(Mi\u00e9rcoles) 9:00 - 12:00<\/span><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class='evorow_b evo_location'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell' data-loc_tax_id='98'><h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>Lugar<\/h3><p class='evo_location_name'>Foment del Treball<\/p><p class='evo_location_address'>Via Laietana 32<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>[vc_row][vc_column][vc_column_text]En un contexto internacional marcado por la inestabilidad geopol\u00edtica, el refuerzo de las capacidades de seguridad y defensa y la necesidad de avanzar hacia una mayor autonom\u00eda estrat\u00e9gica europea, la<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p>[vc_row][vc_column][vc_column_text]En un contexto internacional marcado por la inestabilidad geopol\u00edtica, el refuerzo de las capacidades de seguridad y defensa y la necesidad de avanzar hacia una mayor autonom\u00eda estrat\u00e9gica europea, la industria adquiere un papel cada vez m\u00e1s decisivo.<\/p>\n<p>Defensa, energ\u00eda, comunicaciones, industria tecnol\u00f3gica, ciberseguridad, infraestructuras cr\u00edticas y cadenas de suministro son hoy \u00e1mbitos estrechamente conectados con la seguridad econ\u00f3mica y la resiliencia de Europa. En este escenario, Catalu\u00f1a cuenta con un tejido empresarial, industrial y tecnol\u00f3gico con capacidades relevantes para contribuir a las nuevas prioridades estrat\u00e9gicas.<\/p>\n<p>Con este prop\u00f3sito, celebraremos la jornada \u201cDefensa y empresa: industria, financiaci\u00f3n y cultura de defensa en Catalu\u00f1a\u201d, un encuentro dirigido a empresas e instituciones interesadas en el papel de la industria ante el nuevo contexto de seguridad europeo.<\/p>\n<p>&nbsp;<\/p>\n<table style=\"border-collapse: collapse; width: 100%; height: 28px;\">\n<tbody>\n<tr style=\"height: 28px;\">\n<td style=\"width: 50%; text-align: center; height: 28px;\"><a href=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/Programa-Provisional-ESP-6.pdf\"><strong style=\"text-align: center;\"><span style=\"color: #d2112d;\">PROGRAMA<\/span><\/strong><\/a><\/td>\n<td style=\"width: 50%; text-align: center; height: 28px;\"><a href=\"https:\/\/www.foment.com\/es\/inscripciones-eventos\/?idevento=C306DEA8-436A-F111-A826-000D3ABA73B5\">\u00a0<strong><span style=\"color: #d2112d;\">INSCRIPCI\u00d3N<\/span><\/strong><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>En colaboraci\u00f3n con:<\/strong><\/p>\n<p>[\/vc_column_text]<\/p>\n<div class=\"single_image wpb_content_element align-center    \" data-animation=\"none\" data-delay=\"0\"><img width=\"662\" height=\"81\" src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/patros-defensa_15.7.26.png\" class=\"attachment-full\" alt=\"\" loading=\"lazy\" title=\"patros defensa_15.7.26\" srcset=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/patros-defensa_15.7.26.png 662w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/patros-defensa_15.7.26-300x37.png 300w\" sizes=\"(max-width: 662px) 100vw, 662px\" \/><\/div>\n<p>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Comissi\u00f3 de Seguretat<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evcal_evdata_row evo_metarow_locImg evorow ' style='height:400px; background-image:url(https:\/\/www.foment.com\/wp-content\/uploads\/2023\/11\/Edifici-Foment-2020-1-scaled.jpg)' id='173055_locimg' ><\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=223331&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=Defensa+y+empresa%3A+industria%2C+financiaci%C3%B3n+y+cultura+de+defensa+en+Catalunya&amp;dates=20260715T070000Z\/20260715T100000Z&amp;ctz=Europe\/Madrid&amp;details=Defensa+y+empresa%3A+industria%2C+financiaci%C3%B3n+y+cultura+de+defensa+en+Catalunya&amp;location=Foment+del+TreballVia+Laietana+32' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><div  id=\"event_223839_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_223839_0\" data-event_id=\"223839\" data-ri=\"0r\" data-time=\"1784107800-1784118600\" data-colr=\"#ff91a2\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/sistema-operativo-del-liderazgo\/'><\/a><meta itemprop='image' content=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-3-jul-2026-14_39_31.png\" \/><meta itemprop='startDate' content=\"2026-7-15T09:30+2:00\" \/><meta itemprop='endDate' content=\"2026-7-15T12:30+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><span itemprop=\"name\">Foment del Treball<\/span><span itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\"><item itemprop=\"streetAddress\">Via Laietana 32<\/item><\/span><\/item><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/OfflineEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3n\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3n\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_223839_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"Sistema operativo del liderazgo\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/sistema-operativo-del-liderazgo\/\",\n\t\t\t\t\t\"startDate\": \"2026-7-15T09:30+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-7-15T12:30+2:00\",\n\t\t\t\t\t\"image\":\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-3-jul-2026-14_39_31.png\", \n\t\t\t\t\t\"description\":\"<p class='PDq2pG_selectionAnchorContainer' data-start='0' data-end='248'><span style='font-family: verdana, geneva, sans-serif;'>Te invitamos a la jornada formativa <strong data-start='36' data-end='73'>\u201cSistema operativo del liderazgo\u201d<\/strong>, en el marco del programa DIH4CAT, el Digital Innovation Hub de Catalunya, que tendr\u00e1 lugar el <strong data-start='169' data-end='228'>15 de julio, de 9.30 h a 12.30 h, en Foment del Treball<\/strong> (Via Laietana, 32).<\/span><\/p> <p data-start='250' data-end='545'><span style='font-family: verdana, geneva, sans-serif;'><strong>\u00bfHas incorporado nuevas herramientas, procesos digitales o soluciones de inteligencia artificial, pero el cambio no avanza como esperabas?<\/strong> A menudo, el bloqueo no est\u00e1 en la tecnolog\u00eda, sino en la falta de claridad en la manera en que los equipos la entienden, la adoptan y la ponen en pr\u00e1ctica.<\/span><\/p> <p data-start='547' data-end='886'><span style='font-family: verdana, geneva, sans-serif;'>En esta jornada formativa trabajaremos una de las piezas clave para que la transformaci\u00f3n digital genere resultados reales: el liderazgo. La sesi\u00f3n ayudar\u00e1 a las personas participantes a identificar d\u00f3nde se rompe la claridad en su liderazgo y c\u00f3mo esto impacta en la adopci\u00f3n real de la tecnolog\u00eda, la IA y los nuevos procesos de trabajo.<\/span><\/p> <p data-start='888' data-end='1225'><span style='font-family: verdana, geneva, sans-serif;'>Durante el taller, las personas participantes realizar\u00e1n un diagn\u00f3stico pr\u00e1ctico de su liderazgo a partir del <strong data-start='998' data-end='1027'>4Ps Leadership Framework\u2122<\/strong> y trabajar\u00e1n dos herramientas concretas para aplicar en el d\u00eda a d\u00eda: <strong data-start='1098' data-end='1110'>SBI Lite<\/strong>, para dar feedback que impulse cambios de comportamiento, y <strong data-start='1171' data-end='1180'>SMART<\/strong>, para delegar de forma m\u00e1s clara y efectiva.<\/span><\/p> <p data-start='1227' data-end='1413'><span style='font-family: verdana, geneva, sans-serif;'>La sesi\u00f3n se dirige a propietarios y gerentes de pymes, jefes de departamento, mandos intermedios y profesionales que lideran equipos en momentos de crecimiento, cambio o transformaci\u00f3n.<\/span><\/p> <p data-start='1415' data-end='1769'><span style='font-family: verdana, geneva, sans-serif;'>Esta jornada ir\u00e1 a cargo de <strong data-start='1443' data-end='1458'>Alicia Rius<\/strong>, coach ejecutiva y de equipos acreditada PCC por la ICF, fundadora de Hive Leadership &amp; Team Coaching, creadora del <strong data-start='1575' data-end='1604'>4Ps Leadership Framework\u2122<\/strong> y autora de <em data-start='1617' data-end='1636'>Lead With Clarity<\/em>. Alicia acompa\u00f1a a pymes en crecimiento a convertir buenos profesionales en l\u00edderes capaces de escalar ejecuci\u00f3n, cultura y equipos.<\/span><\/p> <p data-start='1771' data-end='1861' data-is-last-node='' data-is-only-node=''><span style='font-family: verdana, geneva, sans-serif;'>Para poder asistir a la sesi\u00f3n, es<em><strong> necesaria la inscripci\u00f3n previa en el siguiente enlace:<\/strong><\/em><\/span><\/p> <p><span style='font-family: verdana, geneva, sans-serif;'><strong><em>\u00a0<\/em><\/strong><\/span><\/p> <p style='text-align: center;'><span style='color: #d2112e;'><strong><span style='font-family: verdana, geneva, sans-serif;'>Inscripci\u00f3n, <a style='color: #d2112e;' title='L'URL original: https:\/\/public-eur.mkt.dynamics.com\/api\/orgs\/8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43\/r\/JRVNAJJBXUyn1O0xbzABAAoAAAA?msdynmkt_target=%7B%22TargetUrl%22%3A%22https%253A%252F%252Fwww.foment.com%252Finscripcions-events%252F%253Fidevento%253DA0E0152F-D276-F111-AB0E-000D3ADCC39A%22%2C%22RedirectOptions%22%3A%7B%221%22%3Anull%7D%7D&amp;msdynmkt_digest=VbUZXPPHiKgEAjzGqmHOjgi7iu11KkmtDefr9f9XU9Q%3D&amp;msdynmkt_secretVersion=7bb221762d0c46939816d3a5592b1359. Feu clic o premeu si confieu en aquest enlla\u00e7.' href='https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FJRVNAJJBXUyn1O0xbzABAAoAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Fwww.foment.com%25252Finscripcions-events%25252F%25253Fidevento%25253DA0E0152F-D276-F111-AB0E-000D3ADCC39A%2522%252C%2522RedirectOptions%2522%253A%257B%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3DVbUZXPPHiKgEAjzGqmHOjgi7iu11KkmtDefr9f9XU9Q%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Cmgarriga%40foment.com%7Ca51b70610ad941c19fba08ded8f82b28%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639186757560684249%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=85CWMuWKQhPwEnHv%2F5eegyQkgJlnF3%2FIUu4BJlJ0cQE%3D&amp;reserved=0' data-auth='NotApplicable' data-linkindex='0'>aqu\u00ed<\/a><\/span><\/strong><\/span><\/p> \",\"location\":[{\"@type\":\"Place\",\"name\":\"Foment del Treball\",\"address\":{\"@type\": \"PostalAddress\",\"streetAddress\":\"Via Laietana 32\"}}],\"organizer\":{\"@type\":\"Organization\",\"name\":\"Innovaci\u00f3n\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Innovaci\u00f3n\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"0\" style=\"border-color: #ff91a2;\" id=\"evc_1784107800223839\" class=\"hasFtIMG desc_trig sin_val evcal_list_a\" data-ux_val=\"3\"  ><span class='ev_ftImg' data-img='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-3-jul-2026-14_39_31.png' data-thumb='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-3-jul-2026-14_39_31-300x169.png' style='background-image:url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-3-jul-2026-14_39_31-300x169.png\")'><\/span><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#ff91a2 !important;' class='evcal_cblock ' data-smon='julio' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>15<\/em><em class='month'>jul<\/em><em class='time'>9:30<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end only_time'><em class='time'>12:30<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  data-location_address=\"Via Laietana 32\" data-location_type=\"address\" data-location_name=\"Foment del Treball\" data-location_url=\"https:\/\/www.foment.com\/es\/event-location\/foment-del-treball\/\" data-location_status=\"true\" ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>Sistema operativo del liderazgo<\/span><span class='evo_below_title'><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>9:30 - 12:30<\/em> <\/span><span class='evcal_desc3'><em class=\"evcal_location\"  data-add_str=\"\"><em class=\"event_location_name\">Foment del Treball<\/em><\/em><\/span><span style='height: 60px;'  class='evcal_desc3' ><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evo_metarow_fimg evorow evcal_evdata_img evcal_evdata_row  evo_imghover' data-imgheight='941' data-imgwidth='1672'  style='background-image: url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/ChatGPT-Image-3-jul-2026-14_39_31.png\")' data-imgstyle='full' data-minheight='400' data-status=''><\/div><div class='evcal_evdata_row evorow_2b evo_metarow_time_location evorow  '>\n\t\t\t\t\t\t\t\t<div class='evorow_b evorow_b1 evo_time'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p><span class='evo_eventcard_time_t'>(Mi\u00e9rcoles) 9:30 - 12:30<\/span><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class='evorow_b evo_location'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell' data-loc_tax_id='98'><h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>Lugar<\/h3><p class='evo_location_name'>Foment del Treball<\/p><p class='evo_location_address'>Via Laietana 32<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>Te invitamos a la jornada formativa \u201cSistema operativo del liderazgo\u201d, en el marco del programa DIH4CAT, el Digital Innovation Hub de<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"0\" data-end=\"248\"><span style=\"font-family: verdana, geneva, sans-serif;\">Te invitamos a la jornada formativa <strong data-start=\"36\" data-end=\"73\">\u201cSistema operativo del liderazgo\u201d<\/strong>, en el marco del programa DIH4CAT, el Digital Innovation Hub de Catalunya, que tendr\u00e1 lugar el <strong data-start=\"169\" data-end=\"228\">15 de julio, de 9.30 h a 12.30 h, en Foment del Treball<\/strong> (Via Laietana, 32).<\/span><\/p>\n<p data-start=\"250\" data-end=\"545\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>\u00bfHas incorporado nuevas herramientas, procesos digitales o soluciones de inteligencia artificial, pero el cambio no avanza como esperabas?<\/strong> A menudo, el bloqueo no est\u00e1 en la tecnolog\u00eda, sino en la falta de claridad en la manera en que los equipos la entienden, la adoptan y la ponen en pr\u00e1ctica.<\/span><\/p>\n<p data-start=\"547\" data-end=\"886\"><span style=\"font-family: verdana, geneva, sans-serif;\">En esta jornada formativa trabajaremos una de las piezas clave para que la transformaci\u00f3n digital genere resultados reales: el liderazgo. La sesi\u00f3n ayudar\u00e1 a las personas participantes a identificar d\u00f3nde se rompe la claridad en su liderazgo y c\u00f3mo esto impacta en la adopci\u00f3n real de la tecnolog\u00eda, la IA y los nuevos procesos de trabajo.<\/span><\/p>\n<p data-start=\"888\" data-end=\"1225\"><span style=\"font-family: verdana, geneva, sans-serif;\">Durante el taller, las personas participantes realizar\u00e1n un diagn\u00f3stico pr\u00e1ctico de su liderazgo a partir del <strong data-start=\"998\" data-end=\"1027\">4Ps Leadership Framework\u2122<\/strong> y trabajar\u00e1n dos herramientas concretas para aplicar en el d\u00eda a d\u00eda: <strong data-start=\"1098\" data-end=\"1110\">SBI Lite<\/strong>, para dar feedback que impulse cambios de comportamiento, y <strong data-start=\"1171\" data-end=\"1180\">SMART<\/strong>, para delegar de forma m\u00e1s clara y efectiva.<\/span><\/p>\n<p data-start=\"1227\" data-end=\"1413\"><span style=\"font-family: verdana, geneva, sans-serif;\">La sesi\u00f3n se dirige a propietarios y gerentes de pymes, jefes de departamento, mandos intermedios y profesionales que lideran equipos en momentos de crecimiento, cambio o transformaci\u00f3n.<\/span><\/p>\n<p data-start=\"1415\" data-end=\"1769\"><span style=\"font-family: verdana, geneva, sans-serif;\">Esta jornada ir\u00e1 a cargo de <strong data-start=\"1443\" data-end=\"1458\">Alicia Rius<\/strong>, coach ejecutiva y de equipos acreditada PCC por la ICF, fundadora de Hive Leadership &amp; Team Coaching, creadora del <strong data-start=\"1575\" data-end=\"1604\">4Ps Leadership Framework\u2122<\/strong> y autora de <em data-start=\"1617\" data-end=\"1636\">Lead With Clarity<\/em>. Alicia acompa\u00f1a a pymes en crecimiento a convertir buenos profesionales en l\u00edderes capaces de escalar ejecuci\u00f3n, cultura y equipos.<\/span><\/p>\n<p data-start=\"1771\" data-end=\"1861\" data-is-last-node=\"\" data-is-only-node=\"\"><span style=\"font-family: verdana, geneva, sans-serif;\">Para poder asistir a la sesi\u00f3n, es<em><strong> necesaria la inscripci\u00f3n previa en el siguiente enlace:<\/strong><\/em><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\"><strong><em>\u00a0<\/em><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #d2112e;\"><strong><span style=\"font-family: verdana, geneva, sans-serif;\">Inscripci\u00f3n, <a style=\"color: #d2112e;\" title=\"L'URL original: https:\/\/public-eur.mkt.dynamics.com\/api\/orgs\/8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43\/r\/JRVNAJJBXUyn1O0xbzABAAoAAAA?msdynmkt_target=%7B%22TargetUrl%22%3A%22https%253A%252F%252Fwww.foment.com%252Finscripcions-events%252F%253Fidevento%253DA0E0152F-D276-F111-AB0E-000D3ADCC39A%22%2C%22RedirectOptions%22%3A%7B%221%22%3Anull%7D%7D&amp;msdynmkt_digest=VbUZXPPHiKgEAjzGqmHOjgi7iu11KkmtDefr9f9XU9Q%3D&amp;msdynmkt_secretVersion=7bb221762d0c46939816d3a5592b1359. Feu clic o premeu si confieu en aquest enlla\u00e7.\" href=\"https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FJRVNAJJBXUyn1O0xbzABAAoAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Fwww.foment.com%25252Finscripcions-events%25252F%25253Fidevento%25253DA0E0152F-D276-F111-AB0E-000D3ADCC39A%2522%252C%2522RedirectOptions%2522%253A%257B%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3DVbUZXPPHiKgEAjzGqmHOjgi7iu11KkmtDefr9f9XU9Q%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Cmgarriga%40foment.com%7Ca51b70610ad941c19fba08ded8f82b28%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639186757560684249%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=85CWMuWKQhPwEnHv%2F5eegyQkgJlnF3%2FIUu4BJlJ0cQE%3D&amp;reserved=0\" data-auth=\"NotApplicable\" data-linkindex=\"0\">aqu\u00ed<\/a><\/span><\/strong><\/span><\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t<p class='evo_data_val evo_card_organizer_image'><img src='https:\/\/www.foment.com\/wp-content\/uploads\/2016\/10\/innovacio-competitiva.png'\/><\/p>\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Innovaci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_address'>Innovaci\u00f3 Competitiva<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evcal_evdata_row evo_metarow_locImg evorow ' style='height:400px; background-image:url(https:\/\/www.foment.com\/wp-content\/uploads\/2023\/11\/Edifici-Foment-2020-1-scaled.jpg)' id='173055_locimg' ><\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=223839&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=Sistema+operativo+del+liderazgo&amp;dates=20260715T073000Z\/20260715T103000Z&amp;ctz=Europe\/Madrid&amp;details=Sistema+operativo+del+liderazgo&amp;location=Foment+del+TreballVia+Laietana+32' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class='evo_metarow_rel_events evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-calendar-plus'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Eventos relacionados<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='evcal_cell_rel_events'>\n\t\t\t\t\t\t\t\t\t\t<a href='https:\/\/www.foment.com\/es\/events\/founder-ceo-sprint\/'><b>Founder & CEO Sprint<\/b><em>6 de julio de 2026 13:00 - 15 de julio de 2026 14:00<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/como-hacer-que-chatgpt-recomiende-tu-negocio\/'><b>C\u00f3mo hacer que ChatGPT recomiende tu negocio.<\/b><em>10 de julio de 2026 10:00 - 12:00<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/ia-per-millorar-el-marqueting-i-lexperiencia-de-client\/'><b>IA para mejorar el m\u00e1rqueting y la experiencia de cliente<\/b><em>30 de junio de 2026 12:00 - 13:30<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/estrategia-digital-para-pymes\/'><b>Estrategia digital para pymes.<\/b><em>22 de julio de 2026 11:00 - 12:30<\/em><\/a><a href='https:\/\/www.foment.com\/en\/events\/como-potenciar-las-ventas-con-ia\/'><b>C\u00f3mo potenciar las ventas con IA<\/b><em>2 de julio de 2026 11:30 - 13:30<\/em><\/a>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><div  id=\"event_217566_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_217566_0\" data-event_id=\"217566\" data-ri=\"0r\" data-time=\"1784624400-1784629800\" data-colr=\"#0db270\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/webinar-participar-amb-exit-en-fires-internacionals\/'><\/a><meta itemprop='image' content=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-8-1-scaled.jpg\" \/><meta itemprop='startDate' content=\"2026-7-21T09:00+2:00\" \/><meta itemprop='endDate' content=\"2026-7-21T10:30+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/OfflineEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Internacional\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Internacional\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_217566_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"Webinar | Participar amb \u00e8xit en fires internacionals\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/webinar-participar-amb-exit-en-fires-internacionals\/\",\n\t\t\t\t\t\"startDate\": \"2026-7-21T09:00+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-7-21T10:30+2:00\",\n\t\t\t\t\t\"image\":\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-8-1-scaled.jpg\", \n\t\t\t\t\t\"description\":\"<p>[vc_row][vc_column][vc_btn title=\u00bbINSCRIPCI\u00d3 GRATU\u00cfTA\u00bb style=\u00bb3d\u00bb color=\u00bbdanger\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb button_block=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Fwww.foment.com%2Finscripcions-events%2F%3Fidevento%3DC9ED99B5-6F32-F111-88B4-000D3ADCCDB0&#8243;][vc_column_text]<span style='font-size: 16pt; font-family: verdana, geneva, sans-serif; color: #d2112d;'>VOLS COMEN\u00c7AR A EXPORTAR?<\/span><br \/> <span style='font-family: verdana, geneva, sans-serif; color: #d2112d;'>T&#8217;ajudem a fer el primer pas, amb acompanyament expert i sense cost per a l&#8217;empresa<\/span><\/p> <p style='text-align: justify;'><span style='font-family: verdana, geneva, sans-serif; font-size: 13px;'>Internacionalitzar-se \u00e9s una oportunitat de creixement, per\u00f2 sovint tamb\u00e9 genera dubtes: per on comen\u00e7ar, quins mercats prioritzar, quins recursos calen i quins aspectes cal tenir en compte.<\/span><\/p> <p style='text-align: justify;'><span style='font-family: verdana, geneva, sans-serif; font-size: 13px;'>Per ajudar a les empreses catalanes a iniciar aquest cam\u00ed amb seguretat, ACCI\u00d3 impulsa el programa <a href='https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FdplJYjVJ_EuMAaJkHY8CABAAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Feur04.safelinks.protection.outlook.com%25252F%25253Furl%25253Dhttps%2525253A%2525252F%2525252Fpublic-eur.mkt.dynamics.com%2525252Fapi%2525252Forgs%2525252F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2525252Fr%2525252FubNm8_1fYkKKybgcijEBAAEAAAA%2525253Fmsdynmkt_target%2525253D%252525257B%2525252522TargetUrl%2525252522%252525253A%2525252522https%25252525253A%25252525252F%25252525252Feur04.safelinks.protection.outlook.com%25252525252F%25252525253Furl%25252525253Dhttps%2525252525253A%2525252525252F%2525252525252Fpublic-eur.mkt.dynamics.com%2525252525252Fapi%2525252525252Forgs%2525252525252F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2525252525252Fr%2525252525252FaITv1hKS8kSs6wB3jXECAAsAAAA%2525252525253Fmsdynmkt_target%2525252525253D%252525252525257B%2525252525252522TargetUrl%2525252525252522%252525252525253A%2525252525252522https%25252525252525253A%25252525252525252F%25252525252525252Feur04.safelinks.protection.outlook.com%25252525252525252F%25252525252525253Furl%25252525252525253Dhttps%2525252525252525253A%2525252525252525252F%2525252525252525252Fpublic-eur.mkt.dynamics.com%2525252525252525252Fapi%2525252525252525252Forgs%2525252525252525252F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2525252525252525252Fr%2525252525252525252FLn5gxxoARECGTxqFI30DAAsAAAA%2525252525252525253Fmsdynmkt_target%2525252525252525253D%252525252525252525257B%2525252525252525252522TargetUrl%2525252525252525252522%252525252525252525253A%2525252525252525252522https%25252525252525252525253A%25252525252525252525252F%25252525252525252525252Fformularis.accio.gencat.cat%25252525252525252525252Fweb%25252525252525252525252Fformularis%25252525252525252525252Finscripcions%25252525252525252525252F-%25252525252525252525252Finscripcio%25252525252525252525252F2026%25252525252525252525252F02%25252525252525252525252F03%25252525252525252525252FOnkrUbTR_SM9nz_z85jUAA%25252525252525252525252Fsollicitud-de-diagnostic-pie-foment%25252525252525252525252F%25252525252525252525253Flang%25252525252525252525253Dca_ES%252525252525252525252526portal%25252525252525252525253Daccio%252525252525252525252526_gl%25252525252525252525253D1%25252525252525252525252A9dm0zh%25252525252525252525252A_ga%25252525252525252525252AMTI0NzIzNzQyMC4xNzEyODIyOTgy%25252525252525252525252A_ga_6HSVZS0K1X%25252525252525252525252AczE3NzI3MjM4MjckbzE4OSRnMCR0MTc3MjcyMzgzMiRqNTUkbDAkaDA%2525252525252525252522%252525252525252525252C%2525252525252525252522RedirectOptions%2525252525252525252522%252525252525252525253A%252525252525252525257B%25252525252525252525225%2525252525252525252522%252525252525252525253Anull%252525252525252525252C%25252525252525252525221%2525252525252525252522%252525252525252525253Anull%252525252525252525257D%252525252525252525257D%25252525252525252526msdynmkt_digest%2525252525252525253DA1vZltR2b3nESlG%252525252525252525252BdOmS7YeZ5GTW3dinAdHW2pwAZaw%252525252525252525253D%25252525252525252526msdynmkt_secretVersion%2525252525252525253D7bb221762d0c46939816d3a5592b1359%252525252525252526data%25252525252525253D05%2525252525252525257C02%2525252525252525257Csramirez%25252525252525252540foment.com%2525252525252525257Cc7e7a4617105465e160408de83531847%2525252525252525257Cf37c938d38654a89b99bb000c76a74bf%2525252525252525257C1%2525252525252525257C0%2525252525252525257C639092590089463447%2525252525252525257CUnknown%2525252525252525257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%2525252525252525253D%2525252525252525253D%2525252525252525257C0%2525252525252525257C%2525252525252525257C%2525252525252525257C%252525252525252526sdata%25252525252525253D8wWi3Z4S7N5i5VCO2QP6AvtWJylRMKEZbvPje18Pg90%2525252525252525253D%252525252525252526reserved%25252525252525253D0%2525252525252522%252525252525252C%2525252525252522RedirectOptions%2525252525252522%252525252525253A%252525252525257B%25252525252525225%2525252525252522%252525252525253Anull%252525252525252C%25252525252525221%2525252525252522%252525252525253Anull%252525252525257D%252525252525257D%25252525252526msdynmkt_digest%2525252525253DYIZexQWs7uZ2WhUfgJqeZuryKVb2vajIvtYv5qE8oRY%252525252525253D%25252525252526msdynmkt_secretVersion%2525252525253D7bb221762d0c46939816d3a5592b1359%252525252526data%25252525253D05%2525252525257C02%2525252525257Csramirez%25252525252540foment.com%2525252525257C565760556e6c4cf5c35308de84384967%2525252525257Cf37c938d38654a89b99bb000c76a74bf%2525252525257C1%2525252525257C0%2525252525257C639093574480490085%2525252525257CUnknown%2525252525257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%2525252525253D%2525252525253D%2525252525257C0%2525252525257C%2525252525257C%2525252525257C%252525252526sdata%25252525253DN3y2QAkHHQEwnwslqril%2525252525252B%2525252525252BjbsTmbpaH1gsQUjqlx6ho%2525252525253D%252525252526reserved%25252525253D0%2525252522%252525252C%2525252522RedirectOptions%2525252522%252525253A%252525257B%25252525225%2525252522%252525253Anull%252525252C%25252525221%2525252522%252525253Anull%252525257D%252525257D%25252526msdynmkt_digest%2525253DHxSIjxqNyMzq4m6G1OWkNS%252525252FYEFefhiIl8o9iQscMDnI%252525253D%25252526msdynmkt_secretVersion%2525253D7bb221762d0c46939816d3a5592b1359%252526data%25253D05%2525257C02%2525257Csramirez%25252540foment.com%2525257C1d01451646264e7fca2308de88baf1ef%2525257Cf37c938d38654a89b99bb000c76a74bf%2525257C1%2525257C0%2525257C639098533660479269%2525257CUnknown%2525257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%2525253D%2525253D%2525257C0%2525257C%2525257C%2525257C%252526sdata%25253DF6gmzEwyPcPCX%2525252FFmsqBkWV3LiHiEx0w4lH5lts42Hng%2525253D%252526reserved%25253D0%2522%252C%2522RedirectOptions%2522%253A%257B%25225%2522%253Anull%252C%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3D3pnr7eA2jjjY5%252F04VJpOmyfkKAFHOW2zndgIqJQ0jxA%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Csramirez%40foment.com%7C23b351ae016143229c6d08de8c12d3d6%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639102209641121264%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=yoLLv4PRfv2xjZrHwBgWZXD0aIuobZl%2FLoaBtC4V5is%3D&amp;reserved=0'>CATALUNYA EXPORTA<\/a>, adre\u00e7at a empreses que volen iniciar-se en la internacionalitzaci\u00f3 amb un enfocament pr\u00e0ctic i personalitzat. <\/span><\/p> <p><span style='font-family: verdana, geneva, sans-serif; font-size: 13px;'>Des de <a href='https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FdplJYjVJ_EuMAaJkHY8CABEAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Feur04.safelinks.protection.outlook.com%25252F%25253Furl%25253Dhttps%2525253A%2525252F%2525252Fpublic-eur.mkt.dynamics.com%2525252Fapi%2525252Forgs%2525252F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2525252Fr%2525252FubNm8_1fYkKKybgcijEBAAIAAAA%2525253Fmsdynmkt_target%2525253D%252525257B%2525252522TargetUrl%2525252522%252525253A%2525252522https%25252525253A%25252525252F%25252525252Fwww.foment.com%25252525252Fes%25252525252Fcatalunya-exporta%25252525252F%2525252525231767799497417-fa3ae53f-0b5b%2525252522%252525252C%2525252522RedirectOptions%2525252522%252525253A%252525257B%25252525220%2525252522%252525253Anull%252525257D%252525257D%25252526msdynmkt_digest%2525253DbK7c94w0eFraOy9eOgKfYNJ21gIDfLiaSBNv7Ob%252525252FUbc%252525253D%25252526msdynmkt_secretVersion%2525253D7bb221762d0c46939816d3a5592b1359%252526data%25253D05%2525257C02%2525257Csramirez%25252540foment.com%2525257C1d01451646264e7fca2308de88baf1ef%2525257Cf37c938d38654a89b99bb000c76a74bf%2525257C1%2525257C0%2525257C639098533660503029%2525257CUnknown%2525257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%2525253D%2525253D%2525257C0%2525257C%2525257C%2525257C%252526sdata%25253DnU%2525252FdP3SzDdBLN%2525252BjGlM%2525252BfjpHC30Tp2sKQXa53D7Snr8M%2525253D%252526reserved%25253D0%2522%252C%2522RedirectOptions%2522%253A%257B%25225%2522%253Anull%252C%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3DTMCFNOfb0%252BXu2BCcvcmDJAmwBhXs4eG0zaVP3L6%252BdE8%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Csramirez%40foment.com%7C23b351ae016143229c6d08de8c12d3d6%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639102209641147248%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=daHoyG1ZgccCVp8G6HuKQMd9CnWk7pYkM%2FVO%2F7PF6wM%3D&amp;reserved=0'>Foment del Treball<\/a>, t&#8217;acompanyem en el proc\u00e9s d&#8217;internacionalitzaci\u00f3 perqu\u00e8 puguis identificar el teu potencial exportador i definir els primers passos amb criteri i confian\u00e7a.<\/span><\/p> <p style='text-align: justify;'><span style='font-family: verdana, geneva, sans-serif; font-size: 13px;'>Com a entitat col\u00b7laboradora i agent de suport a la internacionalitzaci\u00f3, al llarg de l&#8217;any organitzarem sessions de capacitaci\u00f3 perqu\u00e8 les empreses coneguin els conceptes, les tend\u00e8ncies i les normatives clau per obrir-se als mercats internacionals.<\/span><\/p> <p style='text-align: justify;'><span style='font-family: verdana, geneva, sans-serif; font-size: 13px;'>Aquesta sessi\u00f3, \u00abParticipar amb \u00e8xit en fires internacionals \u00ab, t\u00e9 com a objectiu t\u00e9 com a objectiu oferir a les empreses eines pr\u00e0ctiques per aprofitar al m\u00e0xim la seva participaci\u00f3 en fires internacionals com a via per impulsar la seva estrat\u00e8gia d&#8217;internacionalitzaci\u00f3. Durant la sessi\u00f3 es treballaran\u00a0 aspectes clau com la selecci\u00f3 de fires m\u00e9s adequades, la preparaci\u00f3 de la participaci\u00f3, la captaci\u00f3 de contactes i el seguiment necess\u00e0ri despr\u00e9s de la fira.\u00a0<\/span><\/p> <p><strong><span style='color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;'>PROGRAMA<\/span><\/strong><\/p> <p><span style='color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;'>09:00 h. Benvinguda i presentaci\u00f3 del Programa Catalunya Exporta<\/span><\/p> <p><span style='color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;'>09:10 h. <strong>Participar amb \u00e8xit a fires internacionals<\/strong><\/span><\/p> <p><span style='color: #000000; font-family: verdana, geneva, sans-serif; font-size: 13px;'><strong>Isabel Garcia<\/strong>, Senior International Consultant, <strong>BarcelonaExport<\/strong><\/span><\/p> <p><span style='color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;'>10:20 h. Torn de preguntes<\/span><\/p> <p><span style='color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;'>10:30 h. Fi de la sesi\u00f3<\/span>[\/vc_column_text]<div class='single_image wpb_content_element align-left    ' data-animation='none' data-delay='0'><img width='1900' height='300' src='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1.png' class='attachment-full' alt='' loading='lazy' title='ACCI\u00d3' srcset='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1.png 1900w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1-300x47.png 300w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1-1024x162.png 1024w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1-768x121.png 768w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1-1536x243.png 1536w' sizes='(max-width: 1900px) 100vw, 1900px' \/><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<span style='font-family: verdana, geneva, sans-serif; font-size: 10px;'>Amb el suport de:<\/span>[\/vc_column_text]<div class='single_image wpb_content_element align-left    ' data-animation='none' data-delay='0'><a href='http:\/\/www.accio.gencat.cat' target='_self'><img width='300' height='68' src='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-integrat-Horitzontal-CAT-color-300x68.png' class='attachment-medium' alt='' loading='lazy' title='ACCIO-integrat-Horitzontal-CAT-color' srcset='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-integrat-Horitzontal-CAT-color-300x68.png 300w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-integrat-Horitzontal-CAT-color.png 559w' sizes='(max-width: 300px) 100vw, 300px' \/><\/a><\/div>[\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<span style='font-family: verdana, geneva, sans-serif; font-size: 10px;'>Agent de suport a la Internacionalitzaci\u00f3<\/span>[\/vc_column_text]<div class='single_image wpb_content_element align-left    ' data-animation='none' data-delay='0'><img width='274' height='300' src='https:\/\/www.foment.com\/wp-content\/uploads\/2025\/10\/logo-Accio-2-274x300.png' class='attachment-medium' alt='' loading='lazy' title='logo Accio 2' srcset='https:\/\/www.foment.com\/wp-content\/uploads\/2025\/10\/logo-Accio-2-274x300.png 274w, https:\/\/www.foment.com\/wp-content\/uploads\/2025\/10\/logo-Accio-2-768x842.png 768w, https:\/\/www.foment.com\/wp-content\/uploads\/2025\/10\/logo-Accio-2.png 778w' sizes='(max-width: 274px) 100vw, 274px' \/><\/div>[\/vc_column][\/vc_row]<\/p> \",\"organizer\":{\"@type\":\"Organization\",\"name\":\"Internacional\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Internacional\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"1\"  style=\"border-color: #0db270;\" id=\"evc_1784624400217566\" class=\"hasFtIMG desc_trig evo_internacional-es evo_webinar-es sin_val evcal_list_a\" data-ux_val=\"3\"  ><span class='ev_ftImg' data-img='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-8-1-scaled.jpg' data-thumb='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-8-1-300x150.jpg' style='background-image:url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-8-1-300x150.jpg\")'><\/span><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#0db270 !important;' class='evcal_cblock ' data-smon='julio' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>21<\/em><em class='month'>jul<\/em><em class='time'>9:00<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end only_time'><em class='time'>10:30<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>Webinar | Participar amb \u00e8xit en fires internacionals<\/span><span class='evo_below_title'><span class='evcal_event_subtitle' >Programa Catalunya Exporta<\/span><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>9:00 - 10:30<\/em> <\/span><span class='evcal_desc3'><em class=\"evcal_location\"  data-add_str=\"\"><em class=\"event_location_name\">Zoom<\/em><\/em><\/span><span style='height: 60px;'  class='evcal_desc3' ><span class='evcal_event_types ett1'><em>C =<\/em><em data-filter='event_type'>Internacional,<\/em><em data-filter='event_type'>Webinar<\/em><i class='clear'><\/i><\/span><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evo_metarow_fimg evorow evcal_evdata_img evcal_evdata_row  evo_imghover' data-imgheight='1280' data-imgwidth='2560'  style='background-image: url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-8-1-scaled.jpg\")' data-imgstyle='full' data-minheight='400' data-status=''><\/div><div class='evcal_evdata_row evorow_2b evo_metarow_time_location evorow  '>\n\t\t\t\t\t\t\t\t<div class='evorow_b evorow_b1 evo_time'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p><span class='evo_eventcard_time_t'>(Martes) 9:00 - 10:30<\/span><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class='evorow_b evo_location'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell' data-loc_tax_id='4869'><h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>Lugar<\/h3><p class='evo_location_name'>Zoom<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>[vc_row][vc_column][vc_btn title=\u00bbINSCRIPCI\u00d3 GRATU\u00cfTA\u00bb style=\u00bb3d\u00bb color=\u00bbdanger\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb button_block=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Fwww.foment.com%2Finscripcions-events%2F%3Fidevento%3DC9ED99B5-6F32-F111-88B4-000D3ADCCDB0&#8243;][vc_column_text]VOLS COMEN\u00c7AR A EXPORTAR?\nT&#8217;ajudem a fer el<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p>[vc_row][vc_column][vc_btn title=\u00bbINSCRIPCI\u00d3 GRATU\u00cfTA\u00bb style=\u00bb3d\u00bb color=\u00bbdanger\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb button_block=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Fwww.foment.com%2Finscripcions-events%2F%3Fidevento%3DC9ED99B5-6F32-F111-88B4-000D3ADCCDB0&#8243;][vc_column_text]<span style=\"font-size: 16pt; font-family: verdana, geneva, sans-serif; color: #d2112d;\">VOLS COMEN\u00c7AR A EXPORTAR?<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; color: #d2112d;\">T&#8217;ajudem a fer el primer pas, amb acompanyament expert i sense cost per a l&#8217;empresa<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 13px;\">Internacionalitzar-se \u00e9s una oportunitat de creixement, per\u00f2 sovint tamb\u00e9 genera dubtes: per on comen\u00e7ar, quins mercats prioritzar, quins recursos calen i quins aspectes cal tenir en compte.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 13px;\">Per ajudar a les empreses catalanes a iniciar aquest cam\u00ed amb seguretat, ACCI\u00d3 impulsa el programa <a href=\"https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FdplJYjVJ_EuMAaJkHY8CABAAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Feur04.safelinks.protection.outlook.com%25252F%25253Furl%25253Dhttps%2525253A%2525252F%2525252Fpublic-eur.mkt.dynamics.com%2525252Fapi%2525252Forgs%2525252F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2525252Fr%2525252FubNm8_1fYkKKybgcijEBAAEAAAA%2525253Fmsdynmkt_target%2525253D%252525257B%2525252522TargetUrl%2525252522%252525253A%2525252522https%25252525253A%25252525252F%25252525252Feur04.safelinks.protection.outlook.com%25252525252F%25252525253Furl%25252525253Dhttps%2525252525253A%2525252525252F%2525252525252Fpublic-eur.mkt.dynamics.com%2525252525252Fapi%2525252525252Forgs%2525252525252F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2525252525252Fr%2525252525252FaITv1hKS8kSs6wB3jXECAAsAAAA%2525252525253Fmsdynmkt_target%2525252525253D%252525252525257B%2525252525252522TargetUrl%2525252525252522%252525252525253A%2525252525252522https%25252525252525253A%25252525252525252F%25252525252525252Feur04.safelinks.protection.outlook.com%25252525252525252F%25252525252525253Furl%25252525252525253Dhttps%2525252525252525253A%2525252525252525252F%2525252525252525252Fpublic-eur.mkt.dynamics.com%2525252525252525252Fapi%2525252525252525252Forgs%2525252525252525252F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2525252525252525252Fr%2525252525252525252FLn5gxxoARECGTxqFI30DAAsAAAA%2525252525252525253Fmsdynmkt_target%2525252525252525253D%252525252525252525257B%2525252525252525252522TargetUrl%2525252525252525252522%252525252525252525253A%2525252525252525252522https%25252525252525252525253A%25252525252525252525252F%25252525252525252525252Fformularis.accio.gencat.cat%25252525252525252525252Fweb%25252525252525252525252Fformularis%25252525252525252525252Finscripcions%25252525252525252525252F-%25252525252525252525252Finscripcio%25252525252525252525252F2026%25252525252525252525252F02%25252525252525252525252F03%25252525252525252525252FOnkrUbTR_SM9nz_z85jUAA%25252525252525252525252Fsollicitud-de-diagnostic-pie-foment%25252525252525252525252F%25252525252525252525253Flang%25252525252525252525253Dca_ES%252525252525252525252526portal%25252525252525252525253Daccio%252525252525252525252526_gl%25252525252525252525253D1%25252525252525252525252A9dm0zh%25252525252525252525252A_ga%25252525252525252525252AMTI0NzIzNzQyMC4xNzEyODIyOTgy%25252525252525252525252A_ga_6HSVZS0K1X%25252525252525252525252AczE3NzI3MjM4MjckbzE4OSRnMCR0MTc3MjcyMzgzMiRqNTUkbDAkaDA%2525252525252525252522%252525252525252525252C%2525252525252525252522RedirectOptions%2525252525252525252522%252525252525252525253A%252525252525252525257B%25252525252525252525225%2525252525252525252522%252525252525252525253Anull%252525252525252525252C%25252525252525252525221%2525252525252525252522%252525252525252525253Anull%252525252525252525257D%252525252525252525257D%25252525252525252526msdynmkt_digest%2525252525252525253DA1vZltR2b3nESlG%252525252525252525252BdOmS7YeZ5GTW3dinAdHW2pwAZaw%252525252525252525253D%25252525252525252526msdynmkt_secretVersion%2525252525252525253D7bb221762d0c46939816d3a5592b1359%252525252525252526data%25252525252525253D05%2525252525252525257C02%2525252525252525257Csramirez%25252525252525252540foment.com%2525252525252525257Cc7e7a4617105465e160408de83531847%2525252525252525257Cf37c938d38654a89b99bb000c76a74bf%2525252525252525257C1%2525252525252525257C0%2525252525252525257C639092590089463447%2525252525252525257CUnknown%2525252525252525257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%2525252525252525253D%2525252525252525253D%2525252525252525257C0%2525252525252525257C%2525252525252525257C%2525252525252525257C%252525252525252526sdata%25252525252525253D8wWi3Z4S7N5i5VCO2QP6AvtWJylRMKEZbvPje18Pg90%2525252525252525253D%252525252525252526reserved%25252525252525253D0%2525252525252522%252525252525252C%2525252525252522RedirectOptions%2525252525252522%252525252525253A%252525252525257B%25252525252525225%2525252525252522%252525252525253Anull%252525252525252C%25252525252525221%2525252525252522%252525252525253Anull%252525252525257D%252525252525257D%25252525252526msdynmkt_digest%2525252525253DYIZexQWs7uZ2WhUfgJqeZuryKVb2vajIvtYv5qE8oRY%252525252525253D%25252525252526msdynmkt_secretVersion%2525252525253D7bb221762d0c46939816d3a5592b1359%252525252526data%25252525253D05%2525252525257C02%2525252525257Csramirez%25252525252540foment.com%2525252525257C565760556e6c4cf5c35308de84384967%2525252525257Cf37c938d38654a89b99bb000c76a74bf%2525252525257C1%2525252525257C0%2525252525257C639093574480490085%2525252525257CUnknown%2525252525257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%2525252525253D%2525252525253D%2525252525257C0%2525252525257C%2525252525257C%2525252525257C%252525252526sdata%25252525253DN3y2QAkHHQEwnwslqril%2525252525252B%2525252525252BjbsTmbpaH1gsQUjqlx6ho%2525252525253D%252525252526reserved%25252525253D0%2525252522%252525252C%2525252522RedirectOptions%2525252522%252525253A%252525257B%25252525225%2525252522%252525253Anull%252525252C%25252525221%2525252522%252525253Anull%252525257D%252525257D%25252526msdynmkt_digest%2525253DHxSIjxqNyMzq4m6G1OWkNS%252525252FYEFefhiIl8o9iQscMDnI%252525253D%25252526msdynmkt_secretVersion%2525253D7bb221762d0c46939816d3a5592b1359%252526data%25253D05%2525257C02%2525257Csramirez%25252540foment.com%2525257C1d01451646264e7fca2308de88baf1ef%2525257Cf37c938d38654a89b99bb000c76a74bf%2525257C1%2525257C0%2525257C639098533660479269%2525257CUnknown%2525257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%2525253D%2525253D%2525257C0%2525257C%2525257C%2525257C%252526sdata%25253DF6gmzEwyPcPCX%2525252FFmsqBkWV3LiHiEx0w4lH5lts42Hng%2525253D%252526reserved%25253D0%2522%252C%2522RedirectOptions%2522%253A%257B%25225%2522%253Anull%252C%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3D3pnr7eA2jjjY5%252F04VJpOmyfkKAFHOW2zndgIqJQ0jxA%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Csramirez%40foment.com%7C23b351ae016143229c6d08de8c12d3d6%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639102209641121264%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=yoLLv4PRfv2xjZrHwBgWZXD0aIuobZl%2FLoaBtC4V5is%3D&amp;reserved=0\">CATALUNYA EXPORTA<\/a>, adre\u00e7at a empreses que volen iniciar-se en la internacionalitzaci\u00f3 amb un enfocament pr\u00e0ctic i personalitzat. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 13px;\">Des de <a href=\"https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FdplJYjVJ_EuMAaJkHY8CABEAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Feur04.safelinks.protection.outlook.com%25252F%25253Furl%25253Dhttps%2525253A%2525252F%2525252Fpublic-eur.mkt.dynamics.com%2525252Fapi%2525252Forgs%2525252F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2525252Fr%2525252FubNm8_1fYkKKybgcijEBAAIAAAA%2525253Fmsdynmkt_target%2525253D%252525257B%2525252522TargetUrl%2525252522%252525253A%2525252522https%25252525253A%25252525252F%25252525252Fwww.foment.com%25252525252Fes%25252525252Fcatalunya-exporta%25252525252F%2525252525231767799497417-fa3ae53f-0b5b%2525252522%252525252C%2525252522RedirectOptions%2525252522%252525253A%252525257B%25252525220%2525252522%252525253Anull%252525257D%252525257D%25252526msdynmkt_digest%2525253DbK7c94w0eFraOy9eOgKfYNJ21gIDfLiaSBNv7Ob%252525252FUbc%252525253D%25252526msdynmkt_secretVersion%2525253D7bb221762d0c46939816d3a5592b1359%252526data%25253D05%2525257C02%2525257Csramirez%25252540foment.com%2525257C1d01451646264e7fca2308de88baf1ef%2525257Cf37c938d38654a89b99bb000c76a74bf%2525257C1%2525257C0%2525257C639098533660503029%2525257CUnknown%2525257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%2525253D%2525253D%2525257C0%2525257C%2525257C%2525257C%252526sdata%25253DnU%2525252FdP3SzDdBLN%2525252BjGlM%2525252BfjpHC30Tp2sKQXa53D7Snr8M%2525253D%252526reserved%25253D0%2522%252C%2522RedirectOptions%2522%253A%257B%25225%2522%253Anull%252C%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3DTMCFNOfb0%252BXu2BCcvcmDJAmwBhXs4eG0zaVP3L6%252BdE8%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Csramirez%40foment.com%7C23b351ae016143229c6d08de8c12d3d6%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639102209641147248%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=daHoyG1ZgccCVp8G6HuKQMd9CnWk7pYkM%2FVO%2F7PF6wM%3D&amp;reserved=0\">Foment del Treball<\/a>, t&#8217;acompanyem en el proc\u00e9s d&#8217;internacionalitzaci\u00f3 perqu\u00e8 puguis identificar el teu potencial exportador i definir els primers passos amb criteri i confian\u00e7a.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 13px;\">Com a entitat col\u00b7laboradora i agent de suport a la internacionalitzaci\u00f3, al llarg de l&#8217;any organitzarem sessions de capacitaci\u00f3 perqu\u00e8 les empreses coneguin els conceptes, les tend\u00e8ncies i les normatives clau per obrir-se als mercats internacionals.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 13px;\">Aquesta sessi\u00f3, \u00abParticipar amb \u00e8xit en fires internacionals \u00ab, t\u00e9 com a objectiu t\u00e9 com a objectiu oferir a les empreses eines pr\u00e0ctiques per aprofitar al m\u00e0xim la seva participaci\u00f3 en fires internacionals com a via per impulsar la seva estrat\u00e8gia d&#8217;internacionalitzaci\u00f3. Durant la sessi\u00f3 es treballaran\u00a0 aspectes clau com la selecci\u00f3 de fires m\u00e9s adequades, la preparaci\u00f3 de la participaci\u00f3, la captaci\u00f3 de contactes i el seguiment necess\u00e0ri despr\u00e9s de la fira.\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;\">PROGRAMA<\/span><\/strong><\/p>\n<p><span style=\"color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;\">09:00 h. Benvinguda i presentaci\u00f3 del Programa Catalunya Exporta<\/span><\/p>\n<p><span style=\"color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;\">09:10 h. <strong>Participar amb \u00e8xit a fires internacionals<\/strong><\/span><\/p>\n<p><span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 13px;\"><strong>Isabel Garcia<\/strong>, Senior International Consultant, <strong>BarcelonaExport<\/strong><\/span><\/p>\n<p><span style=\"color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;\">10:20 h. Torn de preguntes<\/span><\/p>\n<p><span style=\"color: #d2112d; font-family: verdana, geneva, sans-serif; font-size: 13px;\">10:30 h. Fi de la sesi\u00f3<\/span>[\/vc_column_text]<\/p>\n<div class=\"single_image wpb_content_element align-left    \" data-animation=\"none\" data-delay=\"0\"><img width=\"1900\" height=\"300\" src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1.png\" class=\"attachment-full\" alt=\"\" loading=\"lazy\" title=\"ACCI\u00d3\" srcset=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1.png 1900w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1-300x47.png 300w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1-1024x162.png 1024w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1-768x121.png 768w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-1-1536x243.png 1536w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/><\/div>\n<p>[\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<span style=\"font-family: verdana, geneva, sans-serif; font-size: 10px;\">Amb el suport de:<\/span>[\/vc_column_text]<\/p>\n<div class=\"single_image wpb_content_element align-left    \" data-animation=\"none\" data-delay=\"0\"><a href=\"http:\/\/www.accio.gencat.cat\" target=\"_self\"><img width=\"300\" height=\"68\" src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-integrat-Horitzontal-CAT-color-300x68.png\" class=\"attachment-medium\" alt=\"\" loading=\"lazy\" title=\"ACCIO-integrat-Horitzontal-CAT-color\" srcset=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-integrat-Horitzontal-CAT-color-300x68.png 300w, https:\/\/www.foment.com\/wp-content\/uploads\/2026\/03\/ACCIO-integrat-Horitzontal-CAT-color.png 559w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<p>[\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_column_text]<span style=\"font-family: verdana, geneva, sans-serif; font-size: 10px;\">Agent de suport a la Internacionalitzaci\u00f3<\/span>[\/vc_column_text]<\/p>\n<div class=\"single_image wpb_content_element align-left    \" data-animation=\"none\" data-delay=\"0\"><img width=\"274\" height=\"300\" src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2025\/10\/logo-Accio-2-274x300.png\" class=\"attachment-medium\" alt=\"\" loading=\"lazy\" title=\"logo Accio 2\" srcset=\"https:\/\/www.foment.com\/wp-content\/uploads\/2025\/10\/logo-Accio-2-274x300.png 274w, https:\/\/www.foment.com\/wp-content\/uploads\/2025\/10\/logo-Accio-2-768x842.png 768w, https:\/\/www.foment.com\/wp-content\/uploads\/2025\/10\/logo-Accio-2.png 778w\" sizes=\"(max-width: 274px) 100vw, 274px\" \/><\/div>\n<p>[\/vc_column][\/vc_row]<\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t<p class='evo_data_val evo_card_organizer_image'><img src='https:\/\/www.foment.com\/wp-content\/uploads\/2017\/04\/InternacionalEmpresabitotransCAT-200x80.png'\/><\/p>\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Internacional<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evcal_evdata_row evo_metarow_locImg evorow ' style='height:400px; background-image:url(https:\/\/www.foment.com\/wp-content\/uploads\/2017\/03\/002damm-0334.jpg)' id='31599_locimg' ><\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=217566&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=Webinar+%7C+Participar+amb+%C3%A8xit+en+fires+internacionals&amp;dates=20260721T070000Z\/20260721T083000Z&amp;ctz=Europe\/Madrid&amp;details=Webinar+%7C+Participar+amb+%C3%A8xit+en+fires+internacionals&amp;location=Zoom' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><div  id=\"event_222444_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_222444_0\" data-event_id=\"222444\" data-ri=\"0r\" data-time=\"1784718000-1784723400\" data-colr=\"#ff91a2\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/estrategia-digital-para-pymes\/'><\/a><meta itemprop='image' content=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260722_EstrategiaDigital_Banner_ES.png\" \/><meta itemprop='startDate' content=\"2026-7-22T11:00+2:00\" \/><meta itemprop='endDate' content=\"2026-7-22T12:30+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><span itemprop=\"name\">Online i Presencial a Foment del Treball Nacional<\/span><span itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\"><item itemprop=\"streetAddress\">Via Laietana, 32- 08003 Barcelona \/ Zoom<\/item><\/span><\/item><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/OfflineEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_222444_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"Estrategia digital para pymes.\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/estrategia-digital-para-pymes\/\",\n\t\t\t\t\t\"startDate\": \"2026-7-22T11:00+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-7-22T12:30+2:00\",\n\t\t\t\t\t\"image\":\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260722_EstrategiaDigital_Banner_ES.png\", \n\t\t\t\t\t\"description\":\"<p class='PDq2pG_selectionAnchorContainer' data-start='15' data-end='210'><span style='font-family: verdana, geneva, sans-serif;'>Os invitamos a la pr\u00f3xima jornada de <strong data-start='52' data-end='83'>Foment Oficina Acelera Pyme<\/strong>, <strong data-start='85' data-end='120'>\u201cEstrategia digital para pymes\u201d<\/strong>, que se celebrar\u00e1 el pr\u00f3ximo <strong data-start='150' data-end='187'>22 de julio, de 11:00 h a 12:30 h<\/strong>, en modalidad h\u00edbrida.<\/span><\/p> <p data-start='212' data-end='350'><span style='font-family: verdana, geneva, sans-serif;'>Redes sociales, web, campa\u00f1as, IA, contenidos, automatizaciones\u2026 Cuando todo parece importante, lo m\u00e1s dif\u00edcil es saber por d\u00f3nde empezar.<\/span><\/p> <p data-start='352' data-end='626'><span style='font-family: verdana, geneva, sans-serif;'>Esta jornada nace precisamente para poner orden. Durante la sesi\u00f3n, trabajaremos c\u00f3mo entender en qu\u00e9 punto se encuentra cada empresa, qu\u00e9 canales digitales pueden aportar valor real y c\u00f3mo construir un plan de acci\u00f3n asumible, pensado para aplicarse desde el d\u00eda siguiente.<\/span><\/p> <p data-start='628' data-end='835'><span style='font-family: verdana, geneva, sans-serif;'>La sesi\u00f3n ayudar\u00e1 a las personas asistentes a realizar un diagn\u00f3stico r\u00e1pido de su presencia digital, definir objetivos realistas y priorizar acciones seg\u00fan el tiempo, el equipo y el presupuesto disponibles.<\/span><\/p> <p data-start='837' data-end='862'><span style='font-family: verdana, geneva, sans-serif;'><strong data-start='837' data-end='862'>Resumen de contenidos<\/strong><\/span><\/p> <p data-start='864' data-end='1317'><span style='font-family: verdana, geneva, sans-serif;'>La sesi\u00f3n se dividir\u00e1 en tres bloques pr\u00e1cticos. En primer lugar, se revisar\u00e1 el mapa digital actual para entender qu\u00e9 canales, herramientas y formatos pueden ser m\u00e1s relevantes para una pyme. A continuaci\u00f3n, se realizar\u00e1 un diagn\u00f3stico de la presencia digital de la empresa para identificar puntos fuertes, \u00e1reas de mejora e indicadores clave. Finalmente, se trabajar\u00e1 c\u00f3mo priorizar acciones y construir un plan aplicable con los recursos disponibles.<\/span><\/p> <p data-start='1319' data-end='1447'><span style='font-family: verdana, geneva, sans-serif;'>Tambi\u00e9n se compartir\u00e1n herramientas, automatizaciones b\u00e1sicas y ejemplos reales de pymes que han ordenado su estrategia digital.<\/span><\/p> <p data-start='1449' data-end='1717'><span style='font-family: verdana, geneva, sans-serif;'>La sesi\u00f3n ir\u00e1 a cargo de <strong data-start='1474' data-end='1492'>Dani Casanovas<\/strong>, CEO de <strong data-start='1501' data-end='1520'>Imagina Digital<\/strong>, y <strong data-start='1524' data-end='1543'>Patricia Schilt<\/strong>, account manager de <strong data-start='1564' data-end='1583'>Imagina Digital<\/strong>. <strong data-start='1585' data-end='1604'>Imagina Digital<\/strong> es una agencia especializada en marketing digital, redes sociales e inteligencia artificial aplicada a empresas.<\/span><\/p> <p data-start='1719' data-end='1796'><span style='font-family: verdana, geneva, sans-serif;'>Es imprescindible <strong>confirmar previamente la asistencia en el siguiente enlace:<\/strong><\/span><\/p> <p style='text-align: center;' data-start='1719' data-end='1796'><span style='font-family: verdana, geneva, sans-serif;'><strong>Inscripci\u00f3n al evento, <a title='L'URL original: https:\/\/8d5eafb0f8ac4ccba7c1a2767b978f43.108.eu.prod.marketingusercontent.com\/api\/orgs\/8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43\/r\/WcwKwgqKT0C526qH8n4DAAEAAAA?msdynmkt_target=%7B%22TargetUrl%22%3A%22https%253A%252F%252Fwww.foment.com%252Finscripcions-events%252F%253Fidevento%253DB88AF66F-3775-F111-AB0E-7CED8D3FACC9%22%2C%22RedirectOptions%22%3A%7B%221%22%3Anull%7D%7D&amp;msdynmkt_digest=yaf5eBSpTCI%2B6hijhykLGhxwUiMu2MeaPv6RlPREVqk%3D&amp;msdynmkt_secretVersion=7bb221762d0c46939816d3a5592b1359. Feu clic o premeu si confieu en aquest enlla\u00e7.' href='https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2F8d5eafb0f8ac4ccba7c1a2767b978f43.108.eu.prod.marketingusercontent.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FWcwKwgqKT0C526qH8n4DAAEAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Fwww.foment.com%25252Finscripcions-events%25252F%25253Fidevento%25253DB88AF66F-3775-F111-AB0E-7CED8D3FACC9%2522%252C%2522RedirectOptions%2522%253A%257B%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3Dyaf5eBSpTCI%252B6hijhykLGhxwUiMu2MeaPv6RlPREVqk%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Cmgarriga%40foment.com%7C7d7963941c1840a167d608dee0b90899%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639195282532394193%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=BpTkW8KvPMpyNPQFDRsxPZARVJdFpYg3gMLiQQvHBkU%3D&amp;reserved=0' data-auth='NotApplicable' data-linkindex='1'>aqu\u00ed<\/a><\/strong><\/span><\/p> <p><strong>Foment del Treball <\/strong>ha sido acreditada como Oficina Acelera Pyme, una iniciativa del Ministerio de Transformaci\u00f3n Digital y de la Funci\u00f3n P\u00fablica, desarrollada por Red.es, destinada a construir el ecosistema de referencia de la transformaci\u00f3n digital de las pymes. Convocatoria de ayudas 2025 para la creaci\u00f3n de la red de Oficinas Acelera Pyme, expediente C004\/25-ED CV7<\/p> \",\"location\":[{\"@type\":\"Place\",\"name\":\"Online i Presencial a Foment del Treball Nacional\",\"address\":{\"@type\": \"PostalAddress\",\"streetAddress\":\"Via Laietana, 32- 08003 Barcelona \/ Zoom\"}}],\"organizer\":{\"@type\":\"Organization\",\"name\":\"Innovaci\u00f3\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Innovaci\u00f3\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"0\" style=\"border-color: #ff91a2;\" id=\"evc_1784718000222444\" class=\"hasFtIMG desc_trig sin_val evcal_list_a\" data-ux_val=\"3\"  ><span class='ev_ftImg' data-img='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260722_EstrategiaDigital_Banner_ES.png' data-thumb='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260722_EstrategiaDigital_Banner_ES-300x169.png' style='background-image:url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260722_EstrategiaDigital_Banner_ES-300x169.png\")'><\/span><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#ff91a2 !important;' class='evcal_cblock ' data-smon='julio' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>22<\/em><em class='month'>jul<\/em><em class='time'>11:00<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end only_time'><em class='time'>12:30<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  data-location_address=\"Via Laietana, 32- 08003 Barcelona \/ Zoom\" data-location_type=\"address\" data-location_name=\"Online i Presencial a Foment del Treball Nacional\" data-location_url=\"https:\/\/www.foment.com\/es\/event-location\/online-i-presencial-a-foment-del-treball-nacional\/\" data-location_status=\"true\" ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>Estrategia digital para pymes.<\/span><span class='evo_below_title'><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>11:00 - 12:30<\/em> <\/span><span class='evcal_desc3'><em class=\"evcal_location\"  data-add_str=\"\"><em class=\"event_location_name\">Online i Presencial a Foment del Treball Nacional<\/em><\/em><\/span><span style='height: 60px;'  class='evcal_desc3' ><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evo_metarow_fimg evorow evcal_evdata_img evcal_evdata_row  evo_imghover' data-imgheight='1080' data-imgwidth='1920'  style='background-image: url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260722_EstrategiaDigital_Banner_ES.png\")' data-imgstyle='full' data-minheight='400' data-status=''><\/div><div class='evcal_evdata_row evorow_2b evo_metarow_time_location evorow  '>\n\t\t\t\t\t\t\t\t<div class='evorow_b evorow_b1 evo_time'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p><span class='evo_eventcard_time_t'>(Mi\u00e9rcoles) 11:00 - 12:30<\/span><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class='evorow_b evo_location'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell' data-loc_tax_id='6606'><h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>Lugar<\/h3><p class='evo_location_name'>Online i Presencial a Foment del Treball Nacional<\/p><p class='evo_location_address'>Via Laietana, 32- 08003 Barcelona \/ Zoom<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>Os invitamos a la pr\u00f3xima jornada de Foment Oficina Acelera Pyme, \u201cEstrategia digital para pymes\u201d, que se celebrar\u00e1 el<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"15\" data-end=\"210\"><span style=\"font-family: verdana, geneva, sans-serif;\">Os invitamos a la pr\u00f3xima jornada de <strong data-start=\"52\" data-end=\"83\">Foment Oficina Acelera Pyme<\/strong>, <strong data-start=\"85\" data-end=\"120\">\u201cEstrategia digital para pymes\u201d<\/strong>, que se celebrar\u00e1 el pr\u00f3ximo <strong data-start=\"150\" data-end=\"187\">22 de julio, de 11:00 h a 12:30 h<\/strong>, en modalidad h\u00edbrida.<\/span><\/p>\n<p data-start=\"212\" data-end=\"350\"><span style=\"font-family: verdana, geneva, sans-serif;\">Redes sociales, web, campa\u00f1as, IA, contenidos, automatizaciones\u2026 Cuando todo parece importante, lo m\u00e1s dif\u00edcil es saber por d\u00f3nde empezar.<\/span><\/p>\n<p data-start=\"352\" data-end=\"626\"><span style=\"font-family: verdana, geneva, sans-serif;\">Esta jornada nace precisamente para poner orden. Durante la sesi\u00f3n, trabajaremos c\u00f3mo entender en qu\u00e9 punto se encuentra cada empresa, qu\u00e9 canales digitales pueden aportar valor real y c\u00f3mo construir un plan de acci\u00f3n asumible, pensado para aplicarse desde el d\u00eda siguiente.<\/span><\/p>\n<p data-start=\"628\" data-end=\"835\"><span style=\"font-family: verdana, geneva, sans-serif;\">La sesi\u00f3n ayudar\u00e1 a las personas asistentes a realizar un diagn\u00f3stico r\u00e1pido de su presencia digital, definir objetivos realistas y priorizar acciones seg\u00fan el tiempo, el equipo y el presupuesto disponibles.<\/span><\/p>\n<p data-start=\"837\" data-end=\"862\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong data-start=\"837\" data-end=\"862\">Resumen de contenidos<\/strong><\/span><\/p>\n<p data-start=\"864\" data-end=\"1317\"><span style=\"font-family: verdana, geneva, sans-serif;\">La sesi\u00f3n se dividir\u00e1 en tres bloques pr\u00e1cticos. En primer lugar, se revisar\u00e1 el mapa digital actual para entender qu\u00e9 canales, herramientas y formatos pueden ser m\u00e1s relevantes para una pyme. A continuaci\u00f3n, se realizar\u00e1 un diagn\u00f3stico de la presencia digital de la empresa para identificar puntos fuertes, \u00e1reas de mejora e indicadores clave. Finalmente, se trabajar\u00e1 c\u00f3mo priorizar acciones y construir un plan aplicable con los recursos disponibles.<\/span><\/p>\n<p data-start=\"1319\" data-end=\"1447\"><span style=\"font-family: verdana, geneva, sans-serif;\">Tambi\u00e9n se compartir\u00e1n herramientas, automatizaciones b\u00e1sicas y ejemplos reales de pymes que han ordenado su estrategia digital.<\/span><\/p>\n<p data-start=\"1449\" data-end=\"1717\"><span style=\"font-family: verdana, geneva, sans-serif;\">La sesi\u00f3n ir\u00e1 a cargo de <strong data-start=\"1474\" data-end=\"1492\">Dani Casanovas<\/strong>, CEO de <strong data-start=\"1501\" data-end=\"1520\">Imagina Digital<\/strong>, y <strong data-start=\"1524\" data-end=\"1543\">Patricia Schilt<\/strong>, account manager de <strong data-start=\"1564\" data-end=\"1583\">Imagina Digital<\/strong>. <strong data-start=\"1585\" data-end=\"1604\">Imagina Digital<\/strong> es una agencia especializada en marketing digital, redes sociales e inteligencia artificial aplicada a empresas.<\/span><\/p>\n<p data-start=\"1719\" data-end=\"1796\"><span style=\"font-family: verdana, geneva, sans-serif;\">Es imprescindible <strong>confirmar previamente la asistencia en el siguiente enlace:<\/strong><\/span><\/p>\n<p style=\"text-align: center;\" data-start=\"1719\" data-end=\"1796\"><span style=\"font-family: verdana, geneva, sans-serif;\"><strong>Inscripci\u00f3n al evento, <a title=\"L'URL original: https:\/\/8d5eafb0f8ac4ccba7c1a2767b978f43.108.eu.prod.marketingusercontent.com\/api\/orgs\/8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43\/r\/WcwKwgqKT0C526qH8n4DAAEAAAA?msdynmkt_target=%7B%22TargetUrl%22%3A%22https%253A%252F%252Fwww.foment.com%252Finscripcions-events%252F%253Fidevento%253DB88AF66F-3775-F111-AB0E-7CED8D3FACC9%22%2C%22RedirectOptions%22%3A%7B%221%22%3Anull%7D%7D&amp;msdynmkt_digest=yaf5eBSpTCI%2B6hijhykLGhxwUiMu2MeaPv6RlPREVqk%3D&amp;msdynmkt_secretVersion=7bb221762d0c46939816d3a5592b1359. Feu clic o premeu si confieu en aquest enlla\u00e7.\" href=\"https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2F8d5eafb0f8ac4ccba7c1a2767b978f43.108.eu.prod.marketingusercontent.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FWcwKwgqKT0C526qH8n4DAAEAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Fwww.foment.com%25252Finscripcions-events%25252F%25253Fidevento%25253DB88AF66F-3775-F111-AB0E-7CED8D3FACC9%2522%252C%2522RedirectOptions%2522%253A%257B%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3Dyaf5eBSpTCI%252B6hijhykLGhxwUiMu2MeaPv6RlPREVqk%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Cmgarriga%40foment.com%7C7d7963941c1840a167d608dee0b90899%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639195282532394193%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=BpTkW8KvPMpyNPQFDRsxPZARVJdFpYg3gMLiQQvHBkU%3D&amp;reserved=0\" data-auth=\"NotApplicable\" data-linkindex=\"1\">aqu\u00ed<\/a><\/strong><\/span><\/p>\n<p><strong>Foment del Treball <\/strong>ha sido acreditada como Oficina Acelera Pyme, una iniciativa del Ministerio de Transformaci\u00f3n Digital y de la Funci\u00f3n P\u00fablica, desarrollada por Red.es, destinada a construir el ecosistema de referencia de la transformaci\u00f3n digital de las pymes. Convocatoria de ayudas 2025 para la creaci\u00f3n de la red de Oficinas Acelera Pyme, expediente C004\/25-ED CV7<\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t<p class='evo_data_val evo_card_organizer_image'><img src='https:\/\/www.foment.com\/wp-content\/uploads\/2016\/10\/innovacio-competitiva.png'\/><\/p>\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Innovaci\u00f3<\/span><span class='evo_card_organizer_contact'>innovacio@foment.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=222444&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=Estrategia+digital+para+pymes.&amp;dates=20260722T090000Z\/20260722T103000Z&amp;ctz=Europe\/Madrid&amp;details=Estrategia+digital+para+pymes.&amp;location=Online+i+Presencial+a+Foment+del+Treball+NacionalVia+Laietana%2C+32-+08003+Barcelona+%2F+Zoom' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class='evo_metarow_rel_events evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-calendar-plus'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Eventos relacionados<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='evcal_cell_rel_events'>\n\t\t\t\t\t\t\t\t\t\t<a href='https:\/\/www.foment.com\/en\/events\/como-potenciar-las-ventas-con-ia\/'><b>C\u00f3mo potenciar las ventas con IA<\/b><em>2 de julio de 2026 11:30 - 13:30<\/em><\/a><a href='https:\/\/www.foment.com\/es\/?post_type=ajde_events&p=222425'><b>IA para mejorar el marketing y la experiencia de cliente<\/b><em>30 de junio de 2026 12:00 - 13:30<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/te-escuchamos-focus-group-e-ia-sin-ruido\/'><b>Te escuchamos: Focus group e IA sin ruido<\/b><em>23 de septiembre de 2026 12:00 - 13:30<\/em><\/a><a href='https:\/\/www.foment.com\/es\/events\/opciones-para-incrementar-la-adopcion-de-la-ia\/'><b>Opciones para incrementar la adopci\u00f3n de la IA<\/b><em>21 de septiembre de 2026 10:00 - 11:30<\/em><\/a>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><div  id=\"event_222098_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_222098_0\" data-event_id=\"222098\" data-ri=\"0r\" data-time=\"1789984800-1789990200\" data-colr=\"#ff91a2\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/opciones-para-incrementar-la-adopcion-de-la-ia\/'><\/a><meta itemprop='image' content=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260921_OpcionsIA_Banner_ES.png\" \/><meta itemprop='startDate' content=\"2026-9-21T10:00+2:00\" \/><meta itemprop='endDate' content=\"2026-9-21T11:30+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><span itemprop=\"name\">Foment del Treball<\/span><span itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\"><item itemprop=\"streetAddress\">Via Laietana 32<\/item><\/span><\/item><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/OfflineEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_222098_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"Opciones para incrementar la adopci\u00f3n de la IA\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/opciones-para-incrementar-la-adopcion-de-la-ia\/\",\n\t\t\t\t\t\"startDate\": \"2026-9-21T10:00+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-9-21T11:30+2:00\",\n\t\t\t\t\t\"image\":\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260921_OpcionsIA_Banner_ES.png\", \n\t\t\t\t\t\"description\":\"<p>Desde la Oficina Acelera Pyme de Fomento del Trabajo te invitamos a la sesi\u00f3n <strong>\u00abOpciones para incrementar la adopci\u00f3n de la IA\u00bb<\/strong>, a cargo de <strong>Emili Bonilla,<\/strong> partner de Propelling Tech.<\/p> <p>La sesi\u00f3n se enmarca dentro de la <strong>Semana de la IA<\/strong> y tendr\u00e1 lugar el pr\u00f3ximo <strong>21 de septiembre de 2026 de 10.00 a 11.30 h en la sede de Fomento del Trabajo.<\/strong><\/p> <p>La inteligencia artificial generativa ha ido mucho m\u00e1s all\u00e1 del chat. En pocos a\u00f1os hemos pasado de sorprendernos con sistemas capaces de mantener una conversaci\u00f3n en construir sistemas que pueden hacer cosas: planificar, decidir y ejecutar flujos de trabajo complejos de manera aut\u00f3noma, con una intervenci\u00f3n humana m\u00ednima.<\/p> <p>En esta sesi\u00f3n recorreremos este camino de autonom\u00eda de la IA, desde las herramientas de mercado m\u00e1s conocidas hasta la IA ag\u00e9ntica, que opera a trav\u00e9s de herramientas, sistemas y datos de maneras que transforman c\u00f3mo trabajamos. Veremos, con ejemplos pr\u00e1cticos, c\u00f3mo las organizaciones est\u00e1n pasando de \u00abhacer preguntas a la IA\u00bb a \u00abdelegar tareas en la IA\u00bb, y qu\u00e9 oportunidades abre esto en t\u00e9rminos de productividad, automatizaci\u00f3n de procesos y valor de negocio.<\/p> <p>Tanto si haces tus primeros pasos con la IA como si ya est\u00e1s construyendo soluciones, te ayudar\u00e1 a entender d\u00f3nde est\u00e1 la tecnolog\u00eda hoy, hacia d\u00f3nde se dirige y qu\u00e9 necesitas para no quedarte atr\u00e1s.<\/p> <p style='text-align: center;'><strong>Inscripci\u00f3n al evento, <a href='https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2Fbn43QRmZ_Em962cz_7cAAAoAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Fwww.foment.com%25252Finscripcions-events%25252F%25253Fidevento%25253D7D4503B0-C264-F111-A825-000D3ADCC77A%2522%252C%2522RedirectOptions%2522%253A%257B%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3DDQwkrqNQKzAX0FQW%252BOQMErFTlWmOcz2o4csCgXcCXP4%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Cdoller%40foment.com%7C1ed1a1666181416d2e5e08dec6e7c4d3%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639166895907166048%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=5k%2BEmdyEzB5JLxSbpbs2x80Bk%2BNHEexgnIuh%2Ba%2FnlT4%3D&amp;reserved=0'>aqu\u00ed<\/a><\/strong><\/p> \",\"location\":[{\"@type\":\"Place\",\"name\":\"Foment del Treball\",\"address\":{\"@type\": \"PostalAddress\",\"streetAddress\":\"Via Laietana 32\"}}],\"organizer\":{\"@type\":\"Organization\",\"name\":\"Innovaci\u00f3\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Innovaci\u00f3\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"1\"  style=\"border-color: #ff91a2;\" id=\"evc_1789984800222098\" class=\"hasFtIMG desc_trig evo_innovacion evo_jornades-oap sin_val evcal_list_a\" data-ux_val=\"3\"  ><span class='ev_ftImg' data-img='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260921_OpcionsIA_Banner_ES.png' data-thumb='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260921_OpcionsIA_Banner_ES-300x169.png' style='background-image:url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260921_OpcionsIA_Banner_ES-300x169.png\")'><\/span><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#ff91a2 !important;' class='evcal_cblock ' data-smon='septiembre' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>21<\/em><em class='month'>sep<\/em><em class='time'>10:00<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end only_time'><em class='time'>11:30<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  data-location_address=\"Via Laietana 32\" data-location_type=\"address\" data-location_name=\"Foment del Treball\" data-location_url=\"https:\/\/www.foment.com\/es\/event-location\/foment-del-treball\/\" data-location_status=\"true\" ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>Opciones para incrementar la adopci\u00f3n de la IA<\/span><span class='evo_below_title'><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>10:00 - 11:30<\/em> <\/span><span class='evcal_desc3'><em class=\"evcal_location\"  data-add_str=\"\"><em class=\"event_location_name\">Foment del Treball<\/em><\/em><\/span><span style='height: 60px;'  class='evcal_desc3' ><span class='evcal_event_types ett1'><em>C =<\/em><em data-filter='event_type'>Innovaci\u00f3n,<\/em><em data-filter='event_type'>Jornades OAP<\/em><i class='clear'><\/i><\/span><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evo_metarow_fimg evorow evcal_evdata_img evcal_evdata_row  evo_imghover' data-imgheight='1080' data-imgwidth='1920'  style='background-image: url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260921_OpcionsIA_Banner_ES.png\")' data-imgstyle='full' data-minheight='400' data-status=''><\/div><div class='evcal_evdata_row evorow_2b evo_metarow_time_location evorow  '>\n\t\t\t\t\t\t\t\t<div class='evorow_b evorow_b1 evo_time'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p><span class='evo_eventcard_time_t'>(Lunes) 10:00 - 11:30<\/span><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class='evorow_b evo_location'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell' data-loc_tax_id='98'><h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>Lugar<\/h3><p class='evo_location_name'>Foment del Treball<\/p><p class='evo_location_address'>Via Laietana 32<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>Desde la Oficina Acelera Pyme de Fomento del Trabajo te invitamos a la sesi\u00f3n \u00abOpciones para incrementar la adopci\u00f3n de la IA\u00bb, a cargo de Emili Bonilla, partner de Propelling<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p>Desde la Oficina Acelera Pyme de Fomento del Trabajo te invitamos a la sesi\u00f3n <strong>\u00abOpciones para incrementar la adopci\u00f3n de la IA\u00bb<\/strong>, a cargo de <strong>Emili Bonilla,<\/strong> partner de Propelling Tech.<\/p>\n<p>La sesi\u00f3n se enmarca dentro de la <strong>Semana de la IA<\/strong> y tendr\u00e1 lugar el pr\u00f3ximo <strong>21 de septiembre de 2026 de 10.00 a 11.30 h en la sede de Fomento del Trabajo.<\/strong><\/p>\n<p>La inteligencia artificial generativa ha ido mucho m\u00e1s all\u00e1 del chat. En pocos a\u00f1os hemos pasado de sorprendernos con sistemas capaces de mantener una conversaci\u00f3n en construir sistemas que pueden hacer cosas: planificar, decidir y ejecutar flujos de trabajo complejos de manera aut\u00f3noma, con una intervenci\u00f3n humana m\u00ednima.<\/p>\n<p>En esta sesi\u00f3n recorreremos este camino de autonom\u00eda de la IA, desde las herramientas de mercado m\u00e1s conocidas hasta la IA ag\u00e9ntica, que opera a trav\u00e9s de herramientas, sistemas y datos de maneras que transforman c\u00f3mo trabajamos. Veremos, con ejemplos pr\u00e1cticos, c\u00f3mo las organizaciones est\u00e1n pasando de \u00abhacer preguntas a la IA\u00bb a \u00abdelegar tareas en la IA\u00bb, y qu\u00e9 oportunidades abre esto en t\u00e9rminos de productividad, automatizaci\u00f3n de procesos y valor de negocio.<\/p>\n<p>Tanto si haces tus primeros pasos con la IA como si ya est\u00e1s construyendo soluciones, te ayudar\u00e1 a entender d\u00f3nde est\u00e1 la tecnolog\u00eda hoy, hacia d\u00f3nde se dirige y qu\u00e9 necesitas para no quedarte atr\u00e1s.<\/p>\n<p style=\"text-align: center;\"><strong>Inscripci\u00f3n al evento, <a href=\"https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2Fbn43QRmZ_Em962cz_7cAAAoAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Fwww.foment.com%25252Finscripcions-events%25252F%25253Fidevento%25253D7D4503B0-C264-F111-A825-000D3ADCC77A%2522%252C%2522RedirectOptions%2522%253A%257B%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3DDQwkrqNQKzAX0FQW%252BOQMErFTlWmOcz2o4csCgXcCXP4%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Cdoller%40foment.com%7C1ed1a1666181416d2e5e08dec6e7c4d3%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639166895907166048%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=5k%2BEmdyEzB5JLxSbpbs2x80Bk%2BNHEexgnIuh%2Ba%2FnlT4%3D&amp;reserved=0\">aqu\u00ed<\/a><\/strong><\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Innovaci\u00f3<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evcal_evdata_row evo_metarow_locImg evorow ' style='height:400px; background-image:url(https:\/\/www.foment.com\/wp-content\/uploads\/2023\/11\/Edifici-Foment-2020-1-scaled.jpg)' id='173055_locimg' ><\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=222098&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=Opciones+para+incrementar+la+adopci%C3%B3n+de+la+IA&amp;dates=20260921T080000Z\/20260921T093000Z&amp;ctz=Europe\/Madrid&amp;details=Opciones+para+incrementar+la+adopci%C3%B3n+de+la+IA&amp;location=Foment+del+TreballVia+Laietana+32' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><div  id=\"event_222107_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_222107_0\" data-event_id=\"222107\" data-ri=\"0r\" data-time=\"1790164800-1790170200\" data-colr=\"#ff91a2\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/te-escuchamos-focus-group-e-ia-sin-ruido\/'><\/a><meta itemprop='image' content=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260923_FocusGroup_Banner_ES.png\" \/><meta itemprop='startDate' content=\"2026-9-23T12:00+2:00\" \/><meta itemprop='endDate' content=\"2026-9-23T13:30+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><span itemprop=\"name\">Foment del Treball<\/span><span itemprop=\"address\" itemscope itemtype=\"http:\/\/schema.org\/PostalAddress\"><item itemprop=\"streetAddress\">Via Laietana 32<\/item><\/span><\/item><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/OfflineEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Innovaci\u00f3\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_222107_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"Te escuchamos: Focus group e IA sin ruido\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/te-escuchamos-focus-group-e-ia-sin-ruido\/\",\n\t\t\t\t\t\"startDate\": \"2026-9-23T12:00+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-9-23T13:30+2:00\",\n\t\t\t\t\t\"image\":\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260923_FocusGroup_Banner_ES.png\", \n\t\t\t\t\t\"description\":\"<p>Te invitamos, el pr\u00f3ximo 23 de septiembre a la sede de Fomento del Trabajo, a una jornada con un formato nuevo, en el marco de la Fomento Oficina Acelera Pyme.<\/p> <p>No es una jornada como las que hacemos habitualmente. Es un formato a puerta cerrada y sin grabaci\u00f3n, pensado para ser una conversaci\u00f3n abierta y cercana. Lo impulsamos porque queremos que nuestras acciones vayan en l\u00ednea con tus necesidades reales y por eso, antes de nada, te queremos escuchar.<\/p> <p><strong>\ud83d\udcc5<\/strong><strong> 23 de septiembre | 12h-13.30h | Fomento del Trabajo<\/strong><\/p> <p>\u00bfC\u00f3mo funcionar\u00e1? La sesi\u00f3n tiene tres partes:<\/p> <p><strong>\u2014 Grupo Focal <\/strong>| 12:00h<\/p> <p>Empezamos presentando los servicios de la Oficina Acelera Pyme y abrimos un espacio de escucha activa para entender cu\u00e1les son las necesidades reales de las empresas como la tuya en materia de digitalizaci\u00f3n. Ser\u00e1 un espacio seguro para compartir y hablar abierta y libremente. Tu opini\u00f3n nos ayudar\u00e1 a adaptar nuestras actividades a la realidad del tejido empresarial catal\u00e1n.<\/p> <p><strong>\u2014 Ponencia: IA sin ruido <\/strong>| 12.40h<\/p> <p>\u00bfC\u00f3mo saber si tu pyme est\u00e1 preparada y qu\u00e9 debe gobernar?<\/p> <p>Artefacto nos ofrecer\u00e1 una mirada clara y sin hype sobre la inteligencia artificial aplicada a la empresa. La sesi\u00f3n no va a presentar herramientas ni de prometer productividad inmediata: va a ayudarte a entender en qu\u00e9 punto se encuentra tu organizaci\u00f3n y c\u00f3mo tomar decisiones sobre IA con criterio.<\/p> <p><strong>\u2014 AMA: Preg\u00fantame lo que <\/strong>quieras | 13:00h<\/p> <p>Una sesi\u00f3n de preguntas y respuestas con el equipo de Artefacto. Podr\u00e1s preguntar lo que quieras, sin filtro.<\/p> <p>Los bloques tem\u00e1ticos ser\u00e1n:<\/p> <ol> <li>Bloque 1: Qu\u00e9 es la IA para empresas y por d\u00f3nde se empieza<\/li> <li>Bloque 2: Adopci\u00f3n, gobierno y datos. C\u00f3mo garantizar que la adopci\u00f3n de IA sea segura y controlada<\/li> <li>Bloque 3: Casos pr\u00e1cticos<\/li> <\/ol> <p>Las plazas son muy limitadas para garantizar que sea una conversaci\u00f3n real, no una ponencia unidireccional.<\/p> <p>Si quieres reservar tu plaza, <strong><u>rellena el formulario<\/u><\/strong>. Una vez recibas la confirmaci\u00f3n, te enviaremos m\u00e1s informaci\u00f3n sobre el funcionamiento de las din\u00e1micas<\/p> <p style='text-align: center;'><strong>Inscripci\u00f3n al evento, <\/strong><a href='https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FZJi2qW-M8UeT3WMPwUEBAAoAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Fwww.foment.com%25252Finscripcions-events%25252F%25253Fidevento%25253D0C0ED3DB-C664-F111-A825-000D3ADCC77A%2522%252C%2522RedirectOptions%2522%253A%257B%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3DtMofJimhzHVUydwaeovLSH343RDP1wnoZTArxLYq%252BXc%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Cdoller%40foment.com%7Cde1351cacce54b7db2da08dec6ebf266%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639166913865441133%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=7ZJul5o2u6OlZ64TB6hB7fQTl%2BCP2PRvNnXc%2B1UNMjs%3D&amp;reserved=0'><strong>aqu\u00ed<\/strong><\/a><\/p> \",\"location\":[{\"@type\":\"Place\",\"name\":\"Foment del Treball\",\"address\":{\"@type\": \"PostalAddress\",\"streetAddress\":\"Via Laietana 32\"}}],\"organizer\":{\"@type\":\"Organization\",\"name\":\"Innovaci\u00f3\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Innovaci\u00f3\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"1\"  style=\"border-color: #ff91a2;\" id=\"evc_1790164800222107\" class=\"hasFtIMG desc_trig evo_innovacion evo_jornades-oap sin_val evcal_list_a\" data-ux_val=\"3\"  ><span class='ev_ftImg' data-img='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260923_FocusGroup_Banner_ES.png' data-thumb='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260923_FocusGroup_Banner_ES-300x169.png' style='background-image:url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260923_FocusGroup_Banner_ES-300x169.png\")'><\/span><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#ff91a2 !important;' class='evcal_cblock ' data-smon='septiembre' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>23<\/em><em class='month'>sep<\/em><em class='time'>12:00<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end only_time'><em class='time'>13:30<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  data-location_address=\"Via Laietana 32\" data-location_type=\"address\" data-location_name=\"Foment del Treball\" data-location_url=\"https:\/\/www.foment.com\/es\/event-location\/foment-del-treball\/\" data-location_status=\"true\" ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>Te escuchamos: Focus group e IA sin ruido<\/span><span class='evo_below_title'><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>12:00 - 13:30<\/em> <\/span><span class='evcal_desc3'><em class=\"evcal_location\"  data-add_str=\"\"><em class=\"event_location_name\">Foment del Treball<\/em><\/em><\/span><span style='height: 60px;'  class='evcal_desc3' ><span class='evcal_event_types ett1'><em>C =<\/em><em data-filter='event_type'>Innovaci\u00f3n,<\/em><em data-filter='event_type'>Jornades OAP<\/em><i class='clear'><\/i><\/span><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evo_metarow_fimg evorow evcal_evdata_img evcal_evdata_row  evo_imghover' data-imgheight='1080' data-imgwidth='1920'  style='background-image: url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/06\/20260923_FocusGroup_Banner_ES.png\")' data-imgstyle='full' data-minheight='400' data-status=''><\/div><div class='evcal_evdata_row evorow_2b evo_metarow_time_location evorow  '>\n\t\t\t\t\t\t\t\t<div class='evorow_b evorow_b1 evo_time'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p><span class='evo_eventcard_time_t'>(Mi\u00e9rcoles) 12:00 - 13:30<\/span><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class='evorow_b evo_location'>\n\t\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell' data-loc_tax_id='98'><h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-map-marker-alt'><\/i><\/span>Lugar<\/h3><p class='evo_location_name'>Foment del Treball<\/p><p class='evo_location_address'>Via Laietana 32<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>Te invitamos, el pr\u00f3ximo 23 de septiembre a la sede de Fomento del Trabajo, a una jornada con un formato nuevo, en el marco de la Fomento Oficina Acelera Pyme.\nNo<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p>Te invitamos, el pr\u00f3ximo 23 de septiembre a la sede de Fomento del Trabajo, a una jornada con un formato nuevo, en el marco de la Fomento Oficina Acelera Pyme.<\/p>\n<p>No es una jornada como las que hacemos habitualmente. Es un formato a puerta cerrada y sin grabaci\u00f3n, pensado para ser una conversaci\u00f3n abierta y cercana. Lo impulsamos porque queremos que nuestras acciones vayan en l\u00ednea con tus necesidades reales y por eso, antes de nada, te queremos escuchar.<\/p>\n<p><strong>\ud83d\udcc5<\/strong><strong> 23 de septiembre | 12h-13.30h | Fomento del Trabajo<\/strong><\/p>\n<p>\u00bfC\u00f3mo funcionar\u00e1? La sesi\u00f3n tiene tres partes:<\/p>\n<p><strong>\u2014 Grupo Focal <\/strong>| 12:00h<\/p>\n<p>Empezamos presentando los servicios de la Oficina Acelera Pyme y abrimos un espacio de escucha activa para entender cu\u00e1les son las necesidades reales de las empresas como la tuya en materia de digitalizaci\u00f3n. Ser\u00e1 un espacio seguro para compartir y hablar abierta y libremente. Tu opini\u00f3n nos ayudar\u00e1 a adaptar nuestras actividades a la realidad del tejido empresarial catal\u00e1n.<\/p>\n<p><strong>\u2014 Ponencia: IA sin ruido <\/strong>| 12.40h<\/p>\n<p>\u00bfC\u00f3mo saber si tu pyme est\u00e1 preparada y qu\u00e9 debe gobernar?<\/p>\n<p>Artefacto nos ofrecer\u00e1 una mirada clara y sin hype sobre la inteligencia artificial aplicada a la empresa. La sesi\u00f3n no va a presentar herramientas ni de prometer productividad inmediata: va a ayudarte a entender en qu\u00e9 punto se encuentra tu organizaci\u00f3n y c\u00f3mo tomar decisiones sobre IA con criterio.<\/p>\n<p><strong>\u2014 AMA: Preg\u00fantame lo que <\/strong>quieras | 13:00h<\/p>\n<p>Una sesi\u00f3n de preguntas y respuestas con el equipo de Artefacto. Podr\u00e1s preguntar lo que quieras, sin filtro.<\/p>\n<p>Los bloques tem\u00e1ticos ser\u00e1n:<\/p>\n<ol>\n<li>Bloque 1: Qu\u00e9 es la IA para empresas y por d\u00f3nde se empieza<\/li>\n<li>Bloque 2: Adopci\u00f3n, gobierno y datos. C\u00f3mo garantizar que la adopci\u00f3n de IA sea segura y controlada<\/li>\n<li>Bloque 3: Casos pr\u00e1cticos<\/li>\n<\/ol>\n<p>Las plazas son muy limitadas para garantizar que sea una conversaci\u00f3n real, no una ponencia unidireccional.<\/p>\n<p>Si quieres reservar tu plaza, <strong><u>rellena el formulario<\/u><\/strong>. Una vez recibas la confirmaci\u00f3n, te enviaremos m\u00e1s informaci\u00f3n sobre el funcionamiento de las din\u00e1micas<\/p>\n<p style=\"text-align: center;\"><strong>Inscripci\u00f3n al evento, <\/strong><a href=\"https:\/\/eur04.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpublic-eur.mkt.dynamics.com%2Fapi%2Forgs%2F8d5eafb0-f8ac-4ccb-a7c1-a2767b978f43%2Fr%2FZJi2qW-M8UeT3WMPwUEBAAoAAAA%3Fmsdynmkt_target%3D%257B%2522TargetUrl%2522%253A%2522https%25253A%25252F%25252Fwww.foment.com%25252Finscripcions-events%25252F%25253Fidevento%25253D0C0ED3DB-C664-F111-A825-000D3ADCC77A%2522%252C%2522RedirectOptions%2522%253A%257B%25221%2522%253Anull%257D%257D%26msdynmkt_digest%3DtMofJimhzHVUydwaeovLSH343RDP1wnoZTArxLYq%252BXc%253D%26msdynmkt_secretVersion%3D7bb221762d0c46939816d3a5592b1359&amp;data=05%7C02%7Cdoller%40foment.com%7Cde1351cacce54b7db2da08dec6ebf266%7Cf37c938d38654a89b99bb000c76a74bf%7C1%7C0%7C639166913865441133%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=7ZJul5o2u6OlZ64TB6hB7fQTl%2BCP2PRvNnXc%2B1UNMjs%3D&amp;reserved=0\"><strong>aqu\u00ed<\/strong><\/a><\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Innovaci\u00f3<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evcal_evdata_row evo_metarow_locImg evorow ' style='height:400px; background-image:url(https:\/\/www.foment.com\/wp-content\/uploads\/2023\/11\/Edifici-Foment-2020-1-scaled.jpg)' id='173055_locimg' ><\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=222107&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=Te+escuchamos%3A+Focus+group+e+IA+sin+ruido&amp;dates=20260923T100000Z\/20260923T113000Z&amp;ctz=Europe\/Madrid&amp;details=Te+escuchamos%3A+Focus+group+e+IA+sin+ruido&amp;location=Foment+del+TreballVia+Laietana+32' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><div  id=\"event_223664_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_223664_0\" data-event_id=\"223664\" data-ri=\"0r\" data-time=\"1790674200-1790688300\" data-colr=\"#00a499\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/el-coste-del-malestar-bienestar-organizacional-como-ventaja-competitiva\/'><\/a><meta itemprop='image' content=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/Caratula-coste-del-malestar-CAST.jpg\" \/><meta itemprop='startDate' content=\"2026-9-29T09:30+2:00\" \/><meta itemprop='endDate' content=\"2026-9-29T13:25+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/OfflineEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_223664_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"El coste del malestar: bienestar organizacional como ventaja competitiva\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/el-coste-del-malestar-bienestar-organizacional-como-ventaja-competitiva\/\",\n\t\t\t\t\t\"startDate\": \"2026-9-29T09:30+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-9-29T13:25+2:00\",\n\t\t\t\t\t\"image\":\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/Caratula-coste-del-malestar-CAST.jpg\", \n\t\t\t\t\t\"description\":\"<p>[vc_row][vc_column][vc_column_text]<\/p> <p>&nbsp;<\/p> <p style='text-align: center;'><span style='color: #d21100; font-family: verdana, geneva, sans-serif;'><span style='font-size: 24px;'>El coste del malestar: bienestar organizacional como ventaja competitiva<\/span><\/span><\/p> <p>&nbsp;<\/p> <p style='text-align: justify;'><span style='font-family: verdana, geneva, sans-serif; font-size: 14px;'><strong>El bienestar corporativo<\/strong> ya no es un beneficio opcional: <strong>es una estrategia de negocio con impacto directo en la productividad, el talento y la sostenibilidad de las organizaciones<\/strong>. Hoy, el absentismo y el presentismo representan uno de los mayores costes ocultos para las empresas, mientras que los riesgos psicosociales se consolidan como la primera causa de baja laboral en Europa.<\/span><\/p> <p><span style='font-family: verdana, geneva, sans-serif; font-size: 14px;'>La Organizaci\u00f3n Mundial de la Salud define el bienestar laboral como un entorno de trabajo que promueve la salud integral de los trabajadores -f\u00edsica, mental, social y financiera- alineado con los Objetivos de Desarrollo Sostenible de la ONU (ODS 3 y ODS 8) y la Declaraci\u00f3n de Luxemburgo de la Red Europea de Promoci\u00f3n de la Salud en el Trabajo.<\/span><\/p> <p style='text-align: justify;'><span style='font-family: verdana, geneva, sans-serif; font-size: 14px;'>Esta jornada re\u00fane a cinco referentes del sector para <strong>ofrecer una visi\u00f3n integral y pr\u00e1ctica: desde el an\u00e1lisis del coste del malestar y la evidencia cient\u00edfica, hasta las estrategias reales implantadas en grandes empresas y su integraci\u00f3n en en el Sistema de Prevenci\u00f3n de Riesgos Laborales<\/strong>. Se presentar\u00e1 adem\u00e1s el\u00a0<strong>Manual de Bienestar Corporativo<\/strong> impulsado por la Enfermer\u00eda del Trabajo, una herramienta de referencia para directivos, t\u00e9cnicos de PRL, profesionales sanitarios y responsables de personas que quieran transformar su organizaci\u00f3n desde dentro.<\/span><\/p> <p>&nbsp;<\/p> <p style='text-align: center;'><span style='font-family: verdana, geneva, sans-serif; font-size: 14px; color: #d21100;'>La jornada \u00fanicamente se realizar\u00e1 en formato presencial.<\/span><\/p> <p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bbDescargar programa\u00bb style=\u00bboutline-custom\u00bb outline_custom_color=\u00bb#dd3333&#8243; outline_custom_hover_background=\u00bb#000000&#8243; outline_custom_hover_text=\u00bb#ffffff\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Ffomentdeltreball.sharepoint.com%2F%3Ab%3A%2Fg%2FIQC09f0iSVpgSZIkw1PfMeUEAURqqDZYGJmunlfuAcYMzBY%3Fe%3DQIAbm0|target:_blank\u00bb css=\u00bb.vc_custom_1783499966427{background-color: #ffffff !important;}\u00bb][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bbInscripci\u00f3n\u00bb style=\u00bboutline-custom\u00bb outline_custom_color=\u00bb#dd3333&#8243; outline_custom_hover_background=\u00bb#000000&#8243; outline_custom_hover_text=\u00bb#ffffff\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Fwww.foment.com%2Fes%2Finscripciones-eventos%2F%3Fidevento%3D3B026246-2B79-F111-AB0F-000D3ADCC39A|target:_blank\u00bb css=\u00bb.vc_custom_1783412528380{background-color: #ffffff !important;}\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<br \/> [\/vc_column_text][vc_single_image image=\u00bb213981&#8243; img_size=\u00bblarge\u00bb][\/vc_column][\/vc_row]<\/p> \",\"organizer\":{\"@type\":\"Organization\",\"name\":\"Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"1\"  style=\"border-color: #00a499;\" id=\"evc_1790674200223664\" class=\"hasFtIMG desc_trig evo_prevencion-riesgos-laborales sin_val evcal_list_a\" data-ux_val=\"3\"  ><span class='ev_ftImg' data-img='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/Caratula-coste-del-malestar-CAST.jpg' data-thumb='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/Caratula-coste-del-malestar-CAST-300x169.jpg' style='background-image:url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/Caratula-coste-del-malestar-CAST-300x169.jpg\")'><\/span><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#00a499 !important;' class='evcal_cblock ' data-smon='septiembre' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>29<\/em><em class='month'>sep<\/em><em class='time'>9:30<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end only_time'><em class='time'>13:25<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>El coste del malestar: bienestar organizacional como ventaja competitiva<\/span><span class='evo_below_title'><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>9:30 - 13:25<\/em> <\/span><span class='evcal_desc3'><\/span><span style='height: 60px;'  class='evcal_desc3' ><span class='evcal_event_types ett1'><em>C =<\/em><em data-filter='event_type'>Prevenci\u00f3n Riesgos Laborales<\/em><i class='clear'><\/i><\/span><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evo_metarow_fimg evorow evcal_evdata_img evcal_evdata_row  evo_imghover' data-imgheight='1080' data-imgwidth='1920'  style='background-image: url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/07\/Caratula-coste-del-malestar-CAST.jpg\")' data-imgstyle='full' data-minheight='400' data-status=''><\/div><div class='evo_metarow_time evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3><p><span class='evo_eventcard_time_t'>(Martes) 9:30 - 13:25<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>[vc_row][vc_column][vc_column_text]\n&nbsp;\nEl coste del malestar: bienestar organizacional como ventaja competitiva\n&nbsp;\nEl bienestar corporativo ya<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #d21100; font-family: verdana, geneva, sans-serif;\"><span style=\"font-size: 24px;\">El coste del malestar: bienestar organizacional como ventaja competitiva<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14px;\"><strong>El bienestar corporativo<\/strong> ya no es un beneficio opcional: <strong>es una estrategia de negocio con impacto directo en la productividad, el talento y la sostenibilidad de las organizaciones<\/strong>. Hoy, el absentismo y el presentismo representan uno de los mayores costes ocultos para las empresas, mientras que los riesgos psicosociales se consolidan como la primera causa de baja laboral en Europa.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14px;\">La Organizaci\u00f3n Mundial de la Salud define el bienestar laboral como un entorno de trabajo que promueve la salud integral de los trabajadores -f\u00edsica, mental, social y financiera- alineado con los Objetivos de Desarrollo Sostenible de la ONU (ODS 3 y ODS 8) y la Declaraci\u00f3n de Luxemburgo de la Red Europea de Promoci\u00f3n de la Salud en el Trabajo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14px;\">Esta jornada re\u00fane a cinco referentes del sector para <strong>ofrecer una visi\u00f3n integral y pr\u00e1ctica: desde el an\u00e1lisis del coste del malestar y la evidencia cient\u00edfica, hasta las estrategias reales implantadas en grandes empresas y su integraci\u00f3n en en el Sistema de Prevenci\u00f3n de Riesgos Laborales<\/strong>. Se presentar\u00e1 adem\u00e1s el\u00a0<strong>Manual de Bienestar Corporativo<\/strong> impulsado por la Enfermer\u00eda del Trabajo, una herramienta de referencia para directivos, t\u00e9cnicos de PRL, profesionales sanitarios y responsables de personas que quieran transformar su organizaci\u00f3n desde dentro.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 14px; color: #d21100;\">La jornada \u00fanicamente se realizar\u00e1 en formato presencial.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bbDescargar programa\u00bb style=\u00bboutline-custom\u00bb outline_custom_color=\u00bb#dd3333&#8243; outline_custom_hover_background=\u00bb#000000&#8243; outline_custom_hover_text=\u00bb#ffffff\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Ffomentdeltreball.sharepoint.com%2F%3Ab%3A%2Fg%2FIQC09f0iSVpgSZIkw1PfMeUEAURqqDZYGJmunlfuAcYMzBY%3Fe%3DQIAbm0|target:_blank\u00bb css=\u00bb.vc_custom_1783499966427{background-color: #ffffff !important;}\u00bb][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bbInscripci\u00f3n\u00bb style=\u00bboutline-custom\u00bb outline_custom_color=\u00bb#dd3333&#8243; outline_custom_hover_background=\u00bb#000000&#8243; outline_custom_hover_text=\u00bb#ffffff\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Fwww.foment.com%2Fes%2Finscripciones-eventos%2F%3Fidevento%3D3B026246-2B79-F111-AB0F-000D3ADCC39A|target:_blank\u00bb css=\u00bb.vc_custom_1783412528380{background-color: #ffffff !important;}\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<br \/>\n[\/vc_column_text][vc_single_image image=\u00bb213981&#8243; img_size=\u00bblarge\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=223664&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=El+coste+del+malestar%3A+bienestar+organizacional+como+ventaja+competitiva&amp;dates=20260929T073000Z\/20260929T112500Z&amp;ctz=Europe\/Madrid&amp;details=El+coste+del+malestar%3A+bienestar+organizacional+como+ventaja+competitiva&amp;location=' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><div  id=\"event_218410_0\" class=\"eventon_list_event evo_eventtop scheduled  event event_218410_0\" data-event_id=\"218410\" data-ri=\"0r\" data-time=\"1790847000-1792679400\" data-colr=\"#00a499\" itemscope itemtype='http:\/\/schema.org\/Event'><div class=\"evo_event_schema\" style=\"display:none\" ><a itemprop='url'  href='https:\/\/www.foment.com\/es\/events\/curso-de-especializacion-en-la-investigacion-de-accidentes-2026\/'><\/a><meta itemprop='image' content=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/04\/Caratula-Curso-investigacion-accidentes.jpg\" \/><meta itemprop='startDate' content=\"2026-10-1T09:30+2:00\" \/><meta itemprop='endDate' content=\"2026-10-22T14:30+2:00\" \/><meta itemprop='eventStatus' content=\"https:\/\/schema.org\/EventScheduled\" \/><item style=\"display:none\" itemprop=\"eventAttendanceMode\" itemscope itemtype=\"https:\/\/schema.org\/OfflineEventAttendanceMode\"><\/item><div itemprop=\"organizer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Organization\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales\">\n\t\t\t\t\t    \t<\/div><div itemprop=\"performer\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\t\t\t\t\t    \t<meta itemprop=\"name\" content=\"Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales\">\n\t\t\t\t\t    <\/div><script type=\"application\/ld+json\">{\"@context\": \"http:\/\/schema.org\",\"@type\": \"Event\",\n\t\t\t\t\t\"@id\": \"event_218410_0\",\n\t\t\t\t\t\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\n\t\t\t\t\t\"name\": \"Curso de especializaci\u00f3n en investigaci\u00f3n de accidentes \u2013 2026\",\n\t\t\t\t\t\"url\": \"https:\/\/www.foment.com\/es\/events\/curso-de-especializacion-en-la-investigacion-de-accidentes-2026\/\",\n\t\t\t\t\t\"startDate\": \"2026-10-1T09:30+2:00\",\n\t\t\t\t\t\"endDate\": \"2026-10-22T14:30+2:00\",\n\t\t\t\t\t\"image\":\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/04\/Caratula-Curso-investigacion-accidentes.jpg\", \n\t\t\t\t\t\"description\":\"<p>[vc_row][vc_column][vc_column_text]<\/p> <p>&nbsp;<\/p> <p style='text-align: center;'><span style='color: #a60f0f; font-family: verdana, geneva, sans-serif;'><span style='font-size: 18pt;'>Curso de especializaci\u00f3n en investigaci\u00f3n de accidentes<\/span><\/span><\/p> <p>&nbsp;<\/p> <p style='text-align: justify;'><span style='font-family: verdana, geneva, sans-serif;'>La investigaci\u00f3n de accidentes es un \u00e1rea en constante evoluci\u00f3n, a medida que se van incorporando tecnolog\u00edas, metodolog\u00edas de an\u00e1lisis, as\u00ed como la experiencia y conocimiento que el estudio de siniestros aporta.<\/span><\/p> <p style='text-align: justify;'><span style='font-family: verdana, geneva, sans-serif;'>El objetivo del curso es facilitar al alumno un aprendizaje y conocimiento amplio de las principales t\u00e9cnicas empleadas a nivel internacional para la investigaci\u00f3n de accidentes\/incidentes, dot\u00e1ndolo de una amplia perspectiva sobre el proceso de la investigaci\u00f3n de accidentes, as\u00ed como m\u00faltiples herramientas para abordar el proceso de planificaci\u00f3n y gesti\u00f3n de la investigaci\u00f3n y el posterior aprendizaje y mejora en aspectos t\u00e9cnicos, organizativos, de gesti\u00f3n, culturales y comportamentales.<\/span><\/p> <hr \/> <p><span style='font-family: verdana, geneva, sans-serif;'>Plazas limitadas. Se confirmar\u00e1 la plaza personalmente.<\/span><\/p> <p><span style='font-family: verdana, geneva, sans-serif;'>La inscripci\u00f3n se puede realizar hasta el 15\/09\/2026.<\/span><\/p> <p><span style='font-family: verdana, geneva, sans-serif;'>El precio de la matr\u00edcula son 1.475\u20ac (IVA no incluido) susceptible de bonificaci\u00f3n parcial por la Fundaci\u00f3n Estatal para la Formaci\u00f3n en el Empleo.<\/span><\/p> <p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/1&#8243;][vc_btn title=\u00bbDescargar programa\u00bb style=\u00bboutline-custom\u00bb outline_custom_color=\u00bb#dd3333&#8243; outline_custom_hover_background=\u00bb#000000&#8243; outline_custom_hover_text=\u00bb#dd1818&#8243; align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Ffomentdeltreball.sharepoint.com%2F%3Ab%3A%2Fg%2FIQA0ea4vfNC1TKZb8HYU2n2lATYi4AwszoX0QW3iywjEtjc|target:_blank\u00bb css=\u00bb.vc_custom_1776348216532{background-color: #ffffff !important;}\u00bb][\/vc_column][\/vc_row]<\/p> \",\"organizer\":{\"@type\":\"Organization\",\"name\":\"Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales\"},\"performer\":{\"@type\":\"Person\",\"name\":\"Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales\"},\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\"}<\/script><\/div>\n\t\t\t\t<p class=\"desc_trig_outter\" style=\"background-color:#ffffff;flex-direction: row;\"><a data-gmap_status=\"null\" data-exlk=\"1\"  style=\"border-color: #00a499;\" id=\"evc_1790847000218410\" class=\"hasFtIMG desc_trig evo_prevencion-riesgos-laborales mul_val evcal_list_a\" data-ux_val=\"3\"  ><span class='ev_ftImg' data-img='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/04\/Caratula-Curso-investigacion-accidentes.jpg' data-thumb='https:\/\/www.foment.com\/wp-content\/uploads\/2026\/04\/Caratula-Curso-investigacion-accidentes-300x169.jpg' style='background-image:url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/04\/Caratula-Curso-investigacion-accidentes-300x169.jpg\")'><\/span><style>.ajde_evcal_calendar.boxy #evcal_list .eventon_list_event .evcal_desc em{color:black;}<\/style><span style='width:100%; background-color:#00a499 !important;' class='evcal_cblock ' data-smon='octubre' data-syr='2026'><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_start '><em class='date'>01<\/em><em class='month'>oct<\/em><em class='time'>9:30<\/em><\/span><span style='margin-top: 7px;margin-bottom: 7px;' class='evo_end '><em class='date'>22<\/em><em class='time'><i>(oct 22)<\/i>14:30<\/em><\/span><em class='clear'><\/em><\/span><span class='evcal_desc evo_info '  ><span class='evo_above_title'><\/span><span class='evcal_desc2 evcal_event_title hbaevatitle' itemprop='name'>Curso de especializaci\u00f3n en investigaci\u00f3n de accidentes \u2013 2026<\/span><span class='evo_below_title'><\/span><span class='evcal_desc_info' ><em class='evcal_time evo_tz_time'>9:30 - 14:30 <em class=\"evo_endday\">(22)<\/em><\/em> <\/span><span class='evcal_desc3'><\/span><span style='height: 60px;'  class='evcal_desc3' ><span class='evcal_event_types ett1'><em>C =<\/em><em data-filter='event_type'>Prevenci\u00f3n Riesgos Laborales<\/em><i class='clear'><\/i><\/span><\/span><\/span><em class='clear'><\/em><\/a><\/p><div class='event_description evcal_eventcard ' style=\"display:none\"><div class='evorow evcal_evdata_row bordb evcal_evrow_sm evo_metarow_rsvp' ><div class='evors_jdata' data-j='{\"etitle\":\"Curso de especializaci\\u00f3n en investigaci\\u00f3n de accidentes \\u2013 2026\",\"e_id\":218410,\"repeat_interval\":0,\"cap\":6,\"precap\":\"20\",\"uid\":\"na\",\"prefill\":false,\"lang\":\"L1\",\"incard\":\"no\",\"rsvpid\":null,\"rsvp\":null}'><\/div><span class='evcal_evdata_icons'><i class='fa fa-envelope'><\/i><\/span>\r\n\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\r\n\t\t\t\t\t\t\t\t<h3 class='evo_h3'>INSCR\u00cdBETE A LA ACTIVIDAD<\/h3><div class='evors_section evors_subtext'><p class='evo_data_val'>No te la pierdas<\/p><\/div><div class='evors_eventcard_content'><p class='evors_section evors_user_text'><span>\u00bfQuieres asistir?<\/span><\/p><div class='evoRS_status_option_selection'><p class='sin'><span data-val='y' class='evors_choices one '>S\u00cd<\/span><\/p><\/div>\t\t\t\t\t<div class=\"evors_incard_form\"><\/div>\r\n\t\t\t\t\t<div class='evors_information'><div class='evors_stat_data'><div class='evors_section evors_remaining_spots'><\/div><div class='clear'><\/div><\/div><\/div><div class='evors_section evors_change_rsvp'>\r\n\t\t\t\t\t\t\t\t<p class=''><span class=\"evors_change_rsvp_label\">\u00bfNo puedes asistir al evento?<\/span><span class='change evors_change_rsvp_trig' data-rsvpid='' data-val='ch'>Cambiar mi reserva<\/span>\r\n\t\t\t\t\t\t\t\t<\/p><\/div><\/div><\/div><\/div><div class='evo_metarow_fimg evorow evcal_evdata_img evcal_evdata_row  evo_imghover' data-imgheight='1080' data-imgwidth='1920'  style='background-image: url(\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/04\/Caratula-Curso-investigacion-accidentes.jpg\")' data-imgstyle='full' data-minheight='400' data-status=''><\/div><div class='evo_metarow_time evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-clock'><\/i><\/span>Horario<\/h3><p><span class='evo_eventcard_time_t'>1 (Jueves) 9:30 - 22 (Jueves) 14:30<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_details evorow evcal_evdata_row evcal_event_details'>\n\t\t\t\t\t\t\t\t<div class=\"event_excerpt\" style=\"display:none\"><h3 class=\"padb5 evo_h3\">Detalles del evento<\/h3><p>[vc_row][vc_column][vc_column_text]\n&nbsp;\nCurso de especializaci\u00f3n en investigaci\u00f3n de accidentes\n&nbsp;\nLa investigaci\u00f3n de accidentes es un \u00e1rea en<\/p><\/div><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell '>\n\t\t\t\t\t\t\t\t\t<div class='eventon_full_description'>\n\t\t\t\t\t\t\t\t\t\t<h3 class='padb5 evo_h3'><span class='evcal_evdata_icons'><i class='fa fa-align-justify'><\/i><\/span>Detalles del evento<\/h3>\n\t\t\t\t\t\t\t\t\t\t<div class='eventon_desc_in' itemprop='description'>\n\t\t\t\t\t\t\t\t\t\t<p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #a60f0f; font-family: verdana, geneva, sans-serif;\"><span style=\"font-size: 18pt;\">Curso de especializaci\u00f3n en investigaci\u00f3n de accidentes<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">La investigaci\u00f3n de accidentes es un \u00e1rea en constante evoluci\u00f3n, a medida que se van incorporando tecnolog\u00edas, metodolog\u00edas de an\u00e1lisis, as\u00ed como la experiencia y conocimiento que el estudio de siniestros aporta.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: verdana, geneva, sans-serif;\">El objetivo del curso es facilitar al alumno un aprendizaje y conocimiento amplio de las principales t\u00e9cnicas empleadas a nivel internacional para la investigaci\u00f3n de accidentes\/incidentes, dot\u00e1ndolo de una amplia perspectiva sobre el proceso de la investigaci\u00f3n de accidentes, as\u00ed como m\u00faltiples herramientas para abordar el proceso de planificaci\u00f3n y gesti\u00f3n de la investigaci\u00f3n y el posterior aprendizaje y mejora en aspectos t\u00e9cnicos, organizativos, de gesti\u00f3n, culturales y comportamentales.<\/span><\/p>\n<hr \/>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Plazas limitadas. Se confirmar\u00e1 la plaza personalmente.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">La inscripci\u00f3n se puede realizar hasta el 15\/09\/2026.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">El precio de la matr\u00edcula son 1.475\u20ac (IVA no incluido) susceptible de bonificaci\u00f3n parcial por la Fundaci\u00f3n Estatal para la Formaci\u00f3n en el Empleo.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/1&#8243;][vc_btn title=\u00bbDescargar programa\u00bb style=\u00bboutline-custom\u00bb outline_custom_color=\u00bb#dd3333&#8243; outline_custom_hover_background=\u00bb#000000&#8243; outline_custom_hover_text=\u00bb#dd1818&#8243; align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Ffomentdeltreball.sharepoint.com%2F%3Ab%3A%2Fg%2FIQA0ea4vfNC1TKZb8HYU2n2lATYi4AwszoX0QW3iywjEtjc|target:_blank\u00bb css=\u00bb.vc_custom_1776348216532{background-color: #ffffff !important;}\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div><div class='clear'><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><div class='evo_metarow_organizer evorow evcal_evdata_row evcal_evrow_sm '>\n\t\t\t\t\t\t\t\t<span class='evcal_evdata_icons'><i class='fa fa-headphones'><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class='evo_h3'>Organizador<\/h3>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class='evo_card_organizer'><p class='evo_data_val evo_card_organizer_name'>\n\t\t\t\t\t\t\t\t\t\t<span class='evo_card_organizer_name_t'>Of. T\u00e9cnica de Prevenci\u00f3n de Riesgos Laborales<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/p><\/div><div class='clear'><\/div>\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\t<div class='evo_metarow_ICS evorow evcal_evdata_row'>\n\t\t\t\t\t\t\t\t<span class=\"evcal_evdata_icons\"><i class=\"fa fa-calendar\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<div class='evcal_evdata_cell'>\n\t\t\t\t\t\t\t\t\t<p><a href='https:\/\/www.foment.com\/wp-admin\/admin-ajax.php?action=eventon_ics_download&amp;event_id=218410&amp;ri=0' class='evo_ics_nCal' title='Add to your calendar'>Calendar<\/a><a href='\/\/www.google.com\/calendar\/event?action=TEMPLATE&amp;text=Curso+de+especializaci%C3%B3n+en+investigaci%C3%B3n+de+accidentes+%E2%80%93+2026&amp;dates=20261001T073000Z\/20261022T123000Z&amp;ctz=Europe\/Madrid&amp;details=Curso+de+especializaci%C3%B3n+en+investigaci%C3%B3n+de+accidentes+%E2%80%93+2026&amp;location=' target='_blank' class='evo_ics_gCal' title='Add to google calendar'>GoogleCal<\/a><\/p>\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='evo_card_row_end evcal_close' title='Close'><\/div><\/div><div class='clear end'><\/div><\/div><\/div><\/div><\/div><div class=\"evosl_footer_outter\"><div class=\"evosl_footer\"><\/div><\/div>\t\t \t<div id='evcal_footer' class='evo_bottom' style='display:none'>\n\t\t \t\t<div class='evo_cal_data'  data-sc='{\"accord\":\"no\",\"bottom_nav\":\"no\",\"cal_id\":\"\",\"cal_init_nonajax\":\"no\",\"calendar_type\":\"default\",\"control_style\":\"lr\",\"el_type\":\"ue\",\"etc_override\":\"no\",\"evc_open\":\"no\",\"event_count\":\"0\",\"event_location\":\"all\",\"event_order\":\"ASC\",\"event_organizer\":\"all\",\"event_past_future\":\"all\",\"event_tag\":\"all\",\"event_type\":\"all\",\"event_type_2\":\"all\",\"event_type_3\":\"all\",\"event_type_4\":\"all\",\"event_type_5\":\"all\",\"eventtop_style\":\"0\",\"exp_jumper\":\"no\",\"exp_so\":\"no\",\"filter_relationship\":\"AND\",\"filter_show_set_only\":\"no\",\"filter_type\":\"default\",\"filters\":\"yes\",\"fixed_month\":\"7\",\"fixed_year\":\"2026\",\"focus_end_date_range\":\"1814399999\",\"focus_start_date_range\":\"1784087320\",\"ft_event_priority\":\"no\",\"hide_arrows\":\"no\",\"hide_empty_months\":\"no\",\"hide_end_time\":\"no\",\"hide_ft\":\"no\",\"hide_month_headers\":\"no\",\"hide_mult_occur\":\"no\",\"hide_past\":\"no\",\"hide_past_by\":\"ee\",\"hide_so\":\"no\",\"ics\":\"no\",\"jumper\":\"no\",\"jumper_count\":\"5\",\"jumper_offset\":\"0\",\"lang\":\"L1\",\"layout_changer\":\"no\",\"livenow_bar\":\"yes\",\"mapformat\":\"roadmap\",\"mapiconurl\":\"\",\"maps_load\":\"yes\",\"mapscroll\":\"true\",\"mapzoom\":\"18\",\"members_only\":\"no\",\"ml_priority\":\"no\",\"month_incre\":\"0\",\"number_of_months\":\"12\",\"only_ft\":\"no\",\"pec\":\"\",\"s\":\"\",\"search\":\"\",\"search_all\":\"no\",\"sep_month\":\"no\",\"show_et_ft_img\":\"yes\",\"show_limit\":\"no\",\"show_limit_ajax\":\"no\",\"show_limit_paged\":\"1\",\"show_limit_redir\":\"\",\"show_repeats\":\"no\",\"show_rsvp\":\"no\",\"show_upcoming\":\"0\",\"show_year\":\"no\",\"slide_auto\":\"no\",\"slide_hide_control\":\"no\",\"slide_loop\":\"no\",\"slide_nav_dots\":\"yes\",\"slide_pause_hover\":\"no\",\"slide_style\":\"def\",\"slider_pause\":\"2000\",\"slider_speed\":\"400\",\"slider_type\":\"multi\",\"slides_visible\":\"1\",\"sort_by\":\"sort_date\",\"tile_bg\":\"0\",\"tile_bg_size\":\"full\",\"tile_count\":\"2\",\"tile_height\":\"0\",\"tile_style\":\"0\",\"tiles\":\"no\",\"ux_val\":\"3\",\"view_switcher\":\"no\",\"wpml_l1\":\"\",\"wpml_l2\":\"\",\"wpml_l3\":\"\",\"yl_priority\":\"no\",\"fixed_date\":\"\",\"fixed_day\":\"15\",\"_cver\":\"3.1.6\"}' data-od='{\"lang_no_events\":\"_No hay eventos\"}'><\/div>\n\t\t \t\t<div class='evo_cal_events' data-events=\"\"><\/div>\n\t\t \t<\/div>\n\t\t\t<\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row bg_color=\u00bb#ffffff\u00bb top_padding=\u00bb40&#8243; bottom_padding=\u00bb60&#8243;][vc_column width=\u00bb1\/1&#8243;]<h2 class=\"headline font-special fontsize-xxxl fontweight-700 lh-inherit align-center transform-uppercase \" style=\"margin: 0 0 40px 0; color: #d2112d;\">NUESTRO EQUIPO<\/h2>[vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1621669212561{padding-top: px !important;padding-bottom: px !important;padding-left: px !important;}\u00bb el_id=\u00bbmpimp\u00bb]<div class=\"imagebox wpb_content_element style-2\"><div class=\"imagebox-img\"><img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2026\/05\/Estefania-Gonzalez.png\" alt=\"\" \/><\/div>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\">ESTEFAN\u00cdA GONZ\u00c1LEZ CAMPINS<\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Presidenta<\/span><a style=\"float: right;\" href=\"https:\/\/www.linkedin.com\/in\/estefaniagonzalezcampins\/?originalSubdomain=es\" target=\"_blank\" rel=\"noopener noreferrer\"><i class=\"fa fa-linkedin-square minti-icon\" style=\"color:#888888 !important; font-size: 16px; margin: 0px 0px 0px 0px\"><\/i><\/a><\/p>\n<\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; el_id=\u00bbmpimp\u00bb]<div class=\"imagebox wpb_content_element style-2\"><div class=\"imagebox-img\"><img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/07\/Maria-Mora.jpeg\" alt=\"\" \/><\/div>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\">MARIA MORA<\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Secretaria T\u00e9cnica<\/span><\/p>\n<\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; el_id=\u00bbmpimp\u00bb]<div class=\"imagebox wpb_content_element style-2\"><div class=\"imagebox-img\"><img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/07\/Thais-Carrera-scaled.jpg\" alt=\"\" \/><\/div>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\">THA\u00cdS CARRERA<\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">T\u00e9cnica<\/span><\/p>\n<\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; el_id=\u00bbmpimp\u00bb]<div class=\"imagebox wpb_content_element style-2\"><div class=\"imagebox-img\"><img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2025\/05\/photo_5879758774972043478_w-1.jpg\" alt=\"\" \/><\/div>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\">ALBA DOMINGO<\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">T\u00e9cnica<\/span><\/p>\n<\/div>[\/vc_column_inner][\/vc_row_inner][vc_empty_space][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1739807012377{padding-top: px !important;padding-bottom: px !important;padding-left: px !important;}\u00bb el_id=\u00bbmpimp\u00bb]<div class=\"imagebox wpb_content_element style-2\"><div class=\"imagebox-img\"><img src=\"https:\/\/www.foment.com\/wp-content\/uploads\/2024\/07\/Dolors-Oller.jpeg\" alt=\"\" \/><\/div>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\">DOLORS OLLER<\/span><\/h4>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Soporte Administrativo<\/span><\/p>\n<\/div>[\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_section][vc_row][vc_column width=\u00bb1\/1&#8243;]\n\t\t\t<!-- START Marketplace ESP REVOLUTION SLIDER 6.4.6 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_199_2_wrapper\" data-source=\"gallery\" style=\"background:linear-gradient(rgba(247,247,247,1) 0%, rgba(215,215,215,1) 100%);padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_199_2\" style=\"\" data-version=\"6.4.6\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide data-key=\"rs-250\" data-title=\"Slide\" data-anim=\"ms:600;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.foment.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"Mkpl\" width=\"875\" height=\"358\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.foment.com\/wp-content\/uploads\/2021\/05\/Mkpl.jpg\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-199-slide-250-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;yo:85px,149px,53px,52px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,28;l:90,74,56,34;fw:700;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:913px,753px,572px,352px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;font-family:Montserrat;\"\n\t\t\t\t\t\t\t>VISITA NUESTRO MARKETPLACE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-199-slide-250-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;yo:203px,247px,132px,145px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:23,22,18,16;l:30,24,21,20;fw:500;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:638px,526px,399px,324px;h:78px,64px,48px,42px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:Montserrat;\"\n\t\t\t\t\t\t\t>Encuentra las empresas asociadas a Foment que te puedan dar servicio. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-199-slide-250-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer rev-btn\"\n\t\t\t\t\t\t\t\thref=\"\/es\/marketplace\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;yo:326px,349px,211px,224px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:14,13,13,12;l:57,55,58,51;fw:600;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"minh:0,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-padding=\"r:36,35,38,34;l:36,35,38,34;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#ffffff;bow:1px,1px,1px,1px;bor:25px,25px,25px,25px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"bgc:rgba(0,0,0,0);boc:rgba(255,255,255,0.75);bor:25px,25px,25px,25px;bos:solid;bow:1px,1px,1px,1px;e:power1.inOut;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;background-color:#d2112d;font-family:Montserrat;\"\n\t\t\t\t\t\t\t>M\u00c1S INFORMACI\u00d3N \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_199_2',rl:[1240,1024,778,480],el:[500,600,360,360],gw:[1240,1024,778,480],gh:[500,600,360,360],type:'hero',justify:'',layout:'fullwidth',mh:\"0\"});\n\t\t\t\t\tvar\trevapi199,\n\t\t\t\t\t\ttpj;\n\t\t\t\t\tfunction revinit_revslider1992() {\n\t\t\t\t\tjQuery(function() {\n\t\t\t\t\t\ttpj = jQuery;\n\t\t\t\t\t\trevapi199 = tpj(\"#rev_slider_199_2\");\n\t\t\t\t\t\tif(revapi199==undefined || revapi199.revolution == undefined){\n\t\t\t\t\t\t\trevslider_showDoubleJqueryError(\"rev_slider_199_2\");\n\t\t\t\t\t\t}else{\n\t\t\t\t\t\t\trevapi199.revolution({\n\t\t\t\t\t\t\t\tsliderType:\"hero\",\n\t\t\t\t\t\t\t\tDPR:\"dpr\",\n\t\t\t\t\t\t\t\tsliderLayout:\"fullwidth\",\n\t\t\t\t\t\t\t\tvisibilityLevels:\"1240,1024,778,480\",\n\t\t\t\t\t\t\t\tgridwidth:\"1240,1024,778,480\",\n\t\t\t\t\t\t\t\tgridheight:\"500,600,360,360\",\n\t\t\t\t\t\t\t\tlazyType:\"smart\",\n\t\t\t\t\t\t\t\tperspective:600,\n\t\t\t\t\t\t\t\tperspectiveType:\"local\",\n\t\t\t\t\t\t\t\teditorheight:\"500,600,360,360\",\n\t\t\t\t\t\t\t\tresponsiveLevels:\"1240,1024,778,480\",\n\t\t\t\t\t\t\t\tprogressBar:{disableProgressBar:true},\n\t\t\t\t\t\t\t\tparallax: {\n\t\t\t\t\t\t\t\t\tlevels:[2,3,4,5,6,7,12,16,10,50,47,48,49,50,51,55],\n\t\t\t\t\t\t\t\t\ttype:\"mouse\",\n\t\t\t\t\t\t\t\t\torigo:\"slidercenter\",\n\t\t\t\t\t\t\t\t\tspeed:2000\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\tfallbacks: {\n\t\t\t\t\t\t\t\t\tallowHTML5AutoPlayOnAndroid:true\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t}\n\t\t\t\t\t\t\n\t\t\t\t\t});\n\t\t\t\t\t} \/\/ End of RevInitScript\n\t\t\t\tvar once_revslider1992 = false;\n\t\t\t\tif (document.readyState === \"loading\") {document.addEventListener('readystatechange',function() { if((document.readyState === \"interactive\" || document.readyState === \"complete\") && !once_revslider1992 ) { once_revslider1992 = true; revinit_revslider1992();}});} else {once_revslider1992 = true; revinit_revslider1992();}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n[\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00bb1\/1&#8243;][\/vc_column][\/vc_row][vc_row bg_color=\u00bb#ffffff\u00bb top_padding=\u00bb10&#8243; bottom_padding=\u00bb20&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_row_inner][vc_column_inner css=\u00bb.vc_custom_1621001846585{background-color: #ffffff !important;}\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_section\u00bb bg_color=\u00bb#efefef\u00bb top_padding=\u00bb60&#8243; bottom_padding=\u00bb20&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_row_inner][vc_column_inner offset=\u00bbvc_hidden-sm vc_hidden-xs\u00bb][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row bg_color=\u00bb#efefef\u00bb][vc_column width=\u00bb1\/1&#8243;][vc_row_inner][vc_column_inner offset=\u00bbvc_hidden-lg vc_hidden-md\u00bb][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_section css=\u00bb.vc_custom_1621669472452{margin-top: px !important;padding-top: px !important;}\u00bb][vc_row top_padding=\u00bb70&#8243; bottom_padding=\u00bb70&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_column_text] Impulso de un clima favorable para el emprendimiento. Identificaci\u00f3n de los problemas de acceso al cr\u00e9dito para las actividades empresariales viables. En la medida de lo posible, identificar y fomentar la articulaci\u00f3n de mecanismos facilitadores de nueva financiaci\u00f3n. Facilitar la reorientaci\u00f3n de la actividad a trav\u00e9s de la innovaci\u00f3n. Informar de toda la normativa, proyectos y l\u00edneas p\u00fablicas de apoyo al emprendimiento. [\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column width=\u00bb1\/1&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_row section_arrow=\u00bbfalse\u00bb top_padding=\u00bb70&#8243; bottom_padding=\u00bb60&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row bg_color=\u00bb#ffffff\u00bb top_padding=\u00bb40&#8243; bottom_padding=\u00bb60&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1621669212561{padding-top: px !important;padding-bottom: px !important;padding-left: px !important;}\u00bb el_id=\u00bbmpimp\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; el_id=\u00bbmpimp\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; el_id=\u00bbmpimp\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; el_id=\u00bbmpimp\u00bb][\/vc_column_inner][\/vc_row_inner][vc_empty_space][vc_row_inner][vc_column_inner width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1739807012377{padding-top: px !important;padding-bottom: px !important;padding-left: px !important;}\u00bb el_id=\u00bbmpimp\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_section][vc_row][vc_column width=\u00bb1\/1&#8243;][\/vc_column][\/vc_row][\/vc_section]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_links_to":"","_links_to_target":""},"acf":[],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/pages\/16235"}],"collection":[{"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/comments?post=16235"}],"version-history":[{"count":20,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/pages\/16235\/revisions"}],"predecessor-version":[{"id":223939,"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/pages\/16235\/revisions\/223939"}],"wp:attachment":[{"href":"https:\/\/www.foment.com\/es\/wp-json\/wp\/v2\/media?parent=16235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}